{"id":109176,"date":"2016-03-22T09:49:00","date_gmt":"2016-03-22T08:49:00","guid":{"rendered":"http:\/\/www.albinfo.ch\/fr\/?p=109176"},"modified":"2016-03-22T09:49:23","modified_gmt":"2016-03-22T08:49:23","slug":"bonjour-cest-isa-mustafa-tu-nas-rien-dautre-a-faire-que-de-toccuper-de-mon-frere-fils-de-chien-tu-vas-me-le-payer-cher-cest-avec-ces-mo","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/bonjour-cest-isa-mustafa-tu-nas-rien-dautre-a-faire-que-de-toccuper-de-mon-frere-fils-de-chien-tu-vas-me-le-payer-cher-cest-avec-ces-mo\/","title":{"rendered":"Le Premier ministre insulte le journaliste : \u00ab fils de chien \u00bb"},"content":{"rendered":"<p>Le Premier ministre du Kosovo Isa Mustafa a une nouvelle fois perdu patience, mais cette fois non pas avec ses rivaux politiques, comme cela lui arrive souvent, mais contre un journaliste. Il a menac\u00e9 le journaliste Vehbi Kajtazi de lui \u00ab\u00a0faire payer cher\u00a0\u00bb d\u2019avoir publi\u00e9 un article au titre de \u00ab\u00a0Le fr\u00e8re du Premier ministre Mustafa a demand\u00e9 l\u2019asile en France et en Allemagne\u00a0\u00bb, publi\u00e9 dans Insider.<\/p>\n<p>Isa Mustafa a appel\u00e9 le journaliste Kajtazi sur Viber \u00e0 17\u00a0h\u00a032, en jurant et en le mena\u00e7ant.<\/p>\n<p>Le journaliste a r\u00e9pondu que l\u2019article a \u00e9t\u00e9 publi\u00e9 parce qu\u2019il s\u2019agit du fr\u00e8re du Premier ministre qui part \u00e0 l\u2019\u00e9tranger pour se faire soigner et que cela souligne le mauvais \u00e9tat du secteur de la sant\u00e9.<\/p>\n<p>Le journaliste a communiqu\u00e9 avec Arban Abrashi, le porte-parole du Premier ministre, pour demander des \u00e9claircissements sur cette affaire. Ce dernier lui a exprim\u00e9 ses regrets et a ajout\u00e9 que le Premier ministre n\u2019\u00e9tait pas joignable au t\u00e9l\u00e9phone.<\/p>\n<p>La r\u00e9action de l\u2019Association des journalistes du Kosovo a \u00e9t\u00e9 imm\u00e9diate.<\/p>\n<p>\u00ab\u00a0Le journaliste Kajtazi a annonc\u00e9 d\u00e9tenir des preuves que les appels t\u00e9l\u00e9phoniques mena\u00e7ants sont venus du num\u00e9ro de t\u00e9l\u00e9phone du Premier ministre Isa Mustafa. AGK consid\u00e8re que cette affaire est scandaleuse, surtout lorsque la menace provient d\u2019une autorit\u00e9 sup\u00e9rieure, qui devrait \u00eatre le garant de la libert\u00e9 d\u2019expression et du libre exercice du journalisme\u00a0\u00bb.<\/p>\n<p>L\u2019Association des journalistes du Kosovo exige que le Premier ministre Isa Mustafa fasse des excuses publiques et qu\u2019il clarifie sa position sur l\u2019affaire. Cette situation, selon l\u2019AGK, r\u00e9v\u00e8le les conditions d\u00e9favorables pour le libre exercice du journalisme au Kosovo.<\/p>\n<p>\u00ab\u00a0Les menaces et la violence contre les journalistes ont augment\u00e9 et cela demande une attention particuli\u00e8re de la part des autorit\u00e9s qui prot\u00e8gent les journalistes. Conscient du fait que la libert\u00e9 d\u2019expression et des m\u00e9dias est l\u2019une des valeurs les plus importantes d\u2019une soci\u00e9t\u00e9 d\u00e9mocratique, l\u2019AGK appelle les institutions locales \u00e0 donner la priorit\u00e9 au travail des journalistes et \u00e0 prendre des mesures pour cr\u00e9er un environnement s\u00fbr pour eux\u00a0\u00bb est-il \u00e9crit dans le communiqu\u00e9 de l\u2019AGK.<\/p>\n<p>La r\u00e9action du Premier ministre est survenue apr\u00e8s que les m\u00e9dias ont publi\u00e9 un article qui indiquait que l\u2019ann\u00e9e derni\u00e8re le fr\u00e8re du Premier ministre, Ragip, avait immigr\u00e9 ill\u00e9galement en Allemagne. Le Premier ministre reconna\u00eet les faits, mais il dit que c\u2019\u00e9tait pour des raisons de sant\u00e9, et qu\u2019aujourd\u2019hui son fr\u00e8re se trouve au Kosovo dans un \u00e9tat critique, luttant contre le cancer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab Bonjour, c\u2019est Isa Mustafa. Tu n\u2019as rien d\u2019autre \u00e0 faire que de t\u2019occuper de mon fr\u00e8re ? Fils de chien. Tu vas me le payer cher \u00bb. C\u2019est avec ces mots qu\u2019Isa Mustafa s\u2019est adress\u00e9 au journaliste.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-109176","post","type-post","status-publish","format-standard","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/109176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=109176"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/109176\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=109176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=109176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=109176"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=109176"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=109176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}