{"id":107855,"date":"2016-03-06T09:47:51","date_gmt":"2016-03-06T08:47:51","guid":{"rendered":"http:\/\/www.albinfo.ch\/fr\/?p=107855"},"modified":"2016-03-06T09:49:53","modified_gmt":"2016-03-06T08:49:53","slug":"lintegration-se-fait-principalement-par-lemploi","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/lintegration-se-fait-principalement-par-lemploi\/","title":{"rendered":"&#8220;L&#8217;int\u00e9gration se fait principalement par l&#8217;emploi&#8221;"},"content":{"rendered":"<p><strong>Albinfo.ch :<\/strong> Six candidats de gauche\u00a0 ont \u00e9t\u00e9 \u00e9lus \u00e0 Lausanne. Comment vous \u00e9valuez vos chances en tant que candidat PLR au deuxi\u00e8me tour de ces \u00e9lections, dans la perspective de briguer le dernier si\u00e8ge \u00e0 la municipalit\u00e9 de Lausanne ?<\/p>\n<p><strong>Pierre-Antoine Hildbrand :<\/strong> 40 % au moins de la population lausannoise n&#8217;est pas repr\u00e9sent\u00e9e \u00e0 la Municipalit\u00e9 \u00e0 l&#8217;issue du 1er tour. J&#8217;esp\u00e8re que le 2e tour permettra au Parti lib\u00e9ral-radical (PLR) de compl\u00e9ter la municipalit\u00e9 avec comme priorit\u00e9s l&#8217;emploi et la lutte contre toute hausse des imp\u00f4ts.<\/p>\n<p><strong>Albinfo.ch :<\/strong> Les \u00e9trangers ont la possibilit\u00e9 de voter et \u00e0 se repr\u00e9senter sur le plan communal. Comment se pr\u00e9sente la situation \u00e0 Lausanne, \u00e0 la fois sur le plan de l\u2019utilisation du droit de vote et de la repr\u00e9sentativit\u00e9 ?<\/p>\n<p><strong>P.-A.H<\/strong><br \/>\nR\u00e9sultats globaux<br \/>\nTaux de participation 38.76 %<\/p>\n<p><strong>Suisses<\/strong><br \/>\nNombre d\u2019\u00e9lecteurs suisses 63&#8217;716<br \/>\nCartes de vote re\u00e7ues 38\u2019068<br \/>\nTaux de participation 59.75%<\/p>\n<p><strong>\u00c9trangers<\/strong><br \/>\nNombre d\u2019\u00e9lecteurs \u00e9trangers 21\u2019907<br \/>\nCartes de vote re\u00e7ues 4\u2019283<br \/>\nTaux de participation 19.55%<\/p>\n<p>Comme pr\u00e9sent\u00e9 ci-dessus, le taux de participation des \u00e9trangers est malheureusement faible. C&#8217;est regrettable. Il a toutefois augment\u00e9 de 2% par rapport \u00e0 la derni\u00e8re fois. Nous devons continuer \u00e0 encourager la participation aux \u00e9lections et favoriser une inclusion toujours plus forte dans notre ville.<\/p>\n<p>Le PLR se veut un parti pour tous. Il doit mieux valoriser la r\u00e9ussite et la valeur du travail des \u00e9trangers et des personnes d&#8217;origines \u00e9trang\u00e8res et leur importance consid\u00e9rable pour la prosp\u00e9rit\u00e9.<\/p>\n<p><strong>Albinfo.ch :<\/strong> Quel est votre perspective sur les th\u00e8me de la migration et l\u2019int\u00e9gration des populations migrantes \u00e0 Lausanne et plus g\u00e9n\u00e9ralement en Suisse ?<\/p>\n<p><strong>P.-A.H :<\/strong> Quant l&#8217;\u00e9conomie va, tout est plus simple et l&#8217;ascenseur social fonctionne. L&#8217;int\u00e9gration se fait principalement par l&#8217;emploi. S&#8217;agissant de l&#8217;int\u00e9gration par l&#8217;\u00e9cole, les recherches r\u00e9centes montrent l&#8217;importance de valoriser le multilinguisme et de donner un r\u00f4le positif aux parents.<\/p>\n<p><strong>Albinfo.ch :<\/strong> le PLR compte peu de militants et candidats issus de la migration, en particulier originaire des Balkans. N\u2019y a-t \u2019il pas l\u00e0 un paradoxe sachant qu\u2019il y a une forte fibre entrepreneuriale chez eux?<br \/>\nP.-A.H : A tort ou \u00e0 raison nous tenons un discours d\u00e9mocratique qui vaut pour tous, sans distinction d&#8217;origine. Je pense que de nombreuses personnes originaires des Balkans se reconnaissent dans un programme en faveur de l&#8217;emploi et de la formation. Ils connaissent aussi les cons\u00e9quences dramatiques des discours d&#8217;exclusion et de haine ou les ravages que provoque le fait qu&#8217;une seule id\u00e9ologie soit au pouvoir.<\/p>\n<p>Sur notre liste figurait notamment Egzon Rexhepi, \u00e9tudiant en sciences politiques.<\/p>\n<p>Nous nous r\u00e9jouissons toujours d&#8217;accueillir de nouveaux sympathisants et notre porte est ouverte. Pour l&#8217;anecdote, mon \u00e9pouse, naturalis\u00e9e, est turque avec des origines maternelles de Shkod\u00ebr.<\/p>\n<p><strong>Albinfo.ch :<\/strong> Comment comptez-vous changez cette situation ? Allez-vous \u00eatre davantage proactifs pour aller \u00e0 la rencontre les diff\u00e9rentes populations immigr\u00e9es et mieux comprendre leurs attentes et besoins?<\/p>\n<p><strong>P.-A.H :<\/strong> Je mesure la responsabilit\u00e9 qui est la mienne en portant seul le r\u00f4le de repr\u00e9senter les pr\u00e9occupations \u00e9conomiques lors de ce 2\u00e8me tour. Je souhaite vivement b\u00e2tir une relation sp\u00e9ciale avec tous ceux qui s&#8217;engagent dans leur communaut\u00e9 et qui contribuent par leur travail et leurs r\u00f4le \u00e9conomique au d\u00e9veloppement de la ville.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><strong>Pierre-Antoine Hildbrand<\/strong><br \/>\nMari\u00e9, deux enfants, juriste, secr\u00e9taire g\u00e9n\u00e9ral d\u2019associations professionnelles et de caisses d\u2019allocations familiales, conseiller communal, ancien pr\u00e9sident des Jeunes Radicaux vaudois, officier, pr\u00e9sident de la Soci\u00e9t\u00e9 de d\u00e9veloppement et des int\u00e9r\u00eats d\u2019Ouchy (SDIO), membre du comit\u00e9 de l\u2019Association des Parents d\u2019\u00c9l\u00e8ves (de Lausanne)<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Pierre-Antoine Hildbrand, candidat PLR pour le septi\u00e8me si\u00e8ge au deuxi\u00e8me tour des \u00e9lections de la Municipalit\u00e9 de Lausanne , livre sa lecture de l&#8217;int\u00e9gration  et rel\u00e8ve son int\u00e9r\u00eat \u00e0 nouer des liens sp\u00e9ciaux avec les communaut\u00e9s \u00e9trang\u00e8res<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1164,1163,1186,1411,2014],"tags":[],"vendi":[],"content_country":[],"class_list":["post-107855","post","type-post","status-publish","format-standard","hentry","category-integration-fr","category-fr-e-diaspora","category-couverture-de-terrain","category-newsletter-fr","category-newsletter-media-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/107855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=107855"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/107855\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=107855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=107855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=107855"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=107855"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=107855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}