{"id":107458,"date":"2016-03-01T09:47:29","date_gmt":"2016-03-01T08:47:29","guid":{"rendered":"http:\/\/www.albinfo.ch\/fr\/?p=107458"},"modified":"2016-03-01T09:47:43","modified_gmt":"2016-03-01T08:47:43","slug":"le-film-shok-na-pas-remporte-doscar","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/le-film-shok-na-pas-remporte-doscar\/","title":{"rendered":"Le film \u00ab Shok \u00bb n\u2019a pas remport\u00e9 d\u2019Oscar"},"content":{"rendered":"<p><span style=\"line-height: 1.5;\">La c\u00e9r\u00e9monie des Oscars a eu lieu sur la sc\u00e8ne du \u00ab\u00a0Dolby Theater\u00a0\u00bb \u00e0 Los Angeles et grands espoirs pour le film \u00ab\u00a0Shok\u00a0\u00bb ont pris fin par une douche froide. Le film nomin\u00e9 et consid\u00e9r\u00e9 par beaucoup comme le favori n\u2019a pas \u00e9t\u00e9 prim\u00e9. Mais, comme on le dit dans ces cas l\u00e0, la nomination elle-m\u00eame est un grand succ\u00e8s pour le pays et la petite industrie cin\u00e9matographique du Kosovo.<\/span><\/p>\n<p>Et en effet, dans le cas du Kosovo un tel constat est significatif au vu des circonstances dans lesquelles \u00e9voluent la culture et le cin\u00e9ma au Kosovo. \u00ab\u00a0Shok\u00a0\u00bb a r\u00e9ussi \u00e0 se placer suffisamment haut pour devenir l\u2019un des cinq meilleurs films au monde dans sa cat\u00e9gorie.<\/p>\n<p>Le film \u00ab\u00a0Stuterer\u00a0\u00bb a re\u00e7u l\u2019Oscar dans la cat\u00e9gorie du film de court-m\u00e9trage.<\/p>\n<p>Le moment le plus \u00e9mouvant fut celui du prix du meilleur acteur. L\u2019acteur Leonardo di Caprio a d\u00e9croch\u00e9 le premier Oscar de sa carri\u00e8re pour son r\u00f4le dans \u00ab\u00a0The Revenant\u00a0\u00bb.<\/p>\n<p>Dans la cat\u00e9gorie du meilleur long-m\u00e9trage, c\u2019est le film \u00ab\u00a0Spotlight\u00a0\u00bb qui l\u2019a emport\u00e9.<\/p>\n<p>Alejandro Gonz\u00e1lez I\u00f1\u00e1rritu a re\u00e7u l\u2019Oscar du meilleur r\u00e9alisateur pour le film \u00ab\u00a0The Revenant\u00a0\u00bb.<\/p>\n<p>L\u2019Oscar de la meilleure actrice a \u00e9t\u00e9 attribu\u00e9 \u00e0 Brie Larson, pour son r\u00f4le dans \u00ab\u00a0Room\u00a0\u00bb.<\/p>\n<p>Le meilleur second r\u00f4le f\u00e9minin est revenu \u00e0 Alicia Vikander pour \u00ab\u00a0Danish Girl\u00a0\u00bb et le meilleur second r\u00f4le masculin a \u00e9t\u00e9 remport\u00e9 par Mark Relance pour le film \u00ab\u00a0Bridge of Spies\u00a0\u00bb.<\/p>\n<p>L\u2019Oscar de la meilleure bande originale a \u00e9t\u00e9 attribu\u00e9 au compositeur Ennio Morricone pour le film \u00ab\u00a0The Hateful Eight\u00a0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La c\u00e9r\u00e9monie des Oscars a eu lieu sur la sc\u00e8ne du \u00ab\u00a0Dolby Theater\u00a0\u00bb \u00e0 Los Angeles et grands espoirs pour le film \u00ab\u00a0Shok\u00a0\u00bb ont pris fin par une douche froide. Le film nomin\u00e9 et consid\u00e9r\u00e9 par beaucoup comme le favori n\u2019a pas \u00e9t\u00e9 prim\u00e9. Mais, comme on le dit dans ces cas l\u00e0, la nomination [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159,1168],"tags":[],"vendi":[],"content_country":[],"class_list":["post-107458","post","type-post","status-publish","format-standard","hentry","category-actuel","category-ch-balkans","category-culture"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/107458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=107458"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/107458\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=107458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=107458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=107458"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=107458"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=107458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}