{"id":105167,"date":"2016-02-04T08:47:53","date_gmt":"2016-02-04T07:47:53","guid":{"rendered":"http:\/\/www.albinfo.ch\/fr\/?p=105167"},"modified":"2016-02-04T08:47:53","modified_gmt":"2016-02-04T07:47:53","slug":"en-trois-mois-2-480-nouvelles-entreprises-enregistrees","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/fr\/en-trois-mois-2-480-nouvelles-entreprises-enregistrees\/","title":{"rendered":"En trois mois, 2 480 nouvelles entreprises enregistr\u00e9es"},"content":{"rendered":"<p>Selon l\u2019Agence des statistiques du Kosovo, au cours des trois derniers mois de l\u2019ann\u00e9e 2015, 2\u00a0480 nouvelles entreprises ont \u00e9t\u00e9 enregistr\u00e9es, soit 14\u00a0% de plus que pendant la m\u00eame p\u00e9riode de l\u2019ann\u00e9e pr\u00e9c\u00e9dente.<\/p>\n<p>Durant le dernier trimestre de 2015, le nombre de nouvelles entreprises au Kosovo a augment\u00e9 de fa\u00e7on significative. Selon l\u2019Agence de la statistique du Kosovo (SAK), lors du quatri\u00e8me trimestre de 2015, 2\u00a0480 nouvelles entreprises ont \u00e9t\u00e9 cr\u00e9\u00e9es au total, ce qui repr\u00e9sente une augmentation de 14\u00a0% par rapport \u00e0 la m\u00eame p\u00e9riode de l\u2019ann\u00e9e pr\u00e9c\u00e9dente.<\/p>\n<p>Ces statistiques apparaissent dans le \u00ab\u00a0R\u00e9pertoire des statistiques des entreprises du Kosovo 2015\u00a0\u00bb publi\u00e9 par l\u2019ASK. C\u2019est un rapport sur les nouvelles entreprises recens\u00e9es par l\u2019Agence pour l\u2019enregistrement des entreprises au Kosovo (ARBK).<\/p>\n<p>Selon cette agence, cela repr\u00e9sente aussi une augmentation de 8,6\u00a0% du nombre de nouvelles entreprises par rapport au trimestre pr\u00e9c\u00e9dent de l\u2019ann\u00e9e 2015.<\/p>\n<p>\u00ab\u00a0Les activit\u00e9s \u00e9conomiques pr\u00e9f\u00e9r\u00e9es au cours du trimestre sont les suivantes\u00a0: le commerce avec 746 nouvelles entreprises, 271 nouvelles fabriques, 270 cr\u00e9ations d\u2019entreprises d\u2019agriculture, de sylviculture et de pisciculture, 189 cr\u00e9ations pour le secteur des autres activit\u00e9s de services, 246 pour l\u2019h\u00e9bergement et les services de restauration, 175 pour les activit\u00e9s scientifiques et techniques et 163 nouvelles entreprises dans le secteur de la construction\u00a0\u00bb, est-il \u00e9crit dans le rapport.<\/p>\n<p>Selon les m\u00eames informations, la plupart de ces entreprises ont embauch\u00e9 de 1 \u00e0 4 employ\u00e9s. Cette cat\u00e9gorie repr\u00e9sente environ 2\u00a0393 entreprises, soit 96,5\u00a0% des nouvelles entreprises.<\/p>\n<p>En ce qui concerne la port\u00e9e g\u00e9ographique des nouvelles entreprises, au niveau municipal, comme \u00e0 chaque trimestre Prishtina arrive en t\u00eate avec 593 nouvelles entreprises, suivi des localit\u00e9s suivantes\u00a0: Peja avec 184 nouvelles entreprises, Prizren (177), Ferizaj (160), Gjakova (131), Gjilan (119) et Mitrovica (111). Les autres municipalit\u00e9s ne comptent qu\u2019un plus petit nombre de nouvelles soci\u00e9t\u00e9s enregistr\u00e9es au cours du trimestre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selon l\u2019Agence des statistiques du Kosovo, au cours des trois derniers mois de l\u2019ann\u00e9e 2015, 2\u00a0480 nouvelles entreprises ont \u00e9t\u00e9 enregistr\u00e9es, soit 14\u00a0% de plus que pendant la m\u00eame p\u00e9riode de l\u2019ann\u00e9e pr\u00e9c\u00e9dente. Durant le dernier trimestre de 2015, le nombre de nouvelles entreprises au Kosovo a augment\u00e9 de fa\u00e7on significative. Selon l\u2019Agence de la [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,1159],"tags":[],"vendi":[],"content_country":[],"class_list":["post-105167","post","type-post","status-publish","format-standard","hentry","category-actuel","category-ch-balkans"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/105167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/comments?post=105167"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/posts\/105167\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/media?parent=105167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/categories?post=105167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/tags?post=105167"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/vendi?post=105167"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/fr\/wp-json\/wp\/v2\/content_country?post=105167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}