{"id":1541,"count":9,"description":"","link":"https:\/\/www.albinfo.at\/de\/tag\/shpenzime\/","name":"shpenzime","slug":"shpenzime","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags\/1541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts?tags=1541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}