{"id":99270,"date":"2015-11-27T09:16:17","date_gmt":"2015-11-27T08:16:17","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=99270"},"modified":"2015-11-27T09:16:17","modified_gmt":"2015-11-27T08:16:17","slug":"mustafa-in-deutschland","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/mustafa-in-deutschland\/","title":{"rendered":"Mustafa in Deutschland"},"content":{"rendered":"<p>Der kosovarische Premierminister Isa Mustafa zeigte volles Verst\u00e4ndnis f\u00fcr die Entscheidung der Bundesregierung, Asylantr\u00e4ge von\u00a0kosovarischen Fl\u00fcchtlingen im Schnellverfahren zu bearbeiten und die Asylsuchenden\u00a0schnell zur\u00fcckzuf\u00fchren.<\/p>\n<div>Der bayerische Ministerpr\u00e4sident Horst Seehofer empfing in M\u00fcnchen den kosovarischen Regierungschef Isa Mustafa.<\/div>\n<div><\/div>\n<div>Seehofer sagte, er werde im kommenden Jahr Kosova besuchen. Dieser Besuch wird vor allem im Sinne der wirtschaftlichen Zusammenarbeit sein, \u00a0meldet die Deutsche Presseagentur dpa.<\/div>\n<div><\/div>\n<div>&#8220;Die wirtschaftliche Unterst\u00fctzung ist das, was wir im Moment am dringensten brauchen&#8221;, sagte Prerminister Isa Mustafa.\u00a0 Mustafa zeigte volles Verst\u00e4ndnis f\u00fcr die Entscheidung der Bundesregierung, kosovarische Asylsuchende schnell zur\u00fcckzuf\u00fchren. \u00dcber Asylantr\u00e4ge von kosovarischen Fl\u00fcchtlingen soll\u00a0im Schnellverfahren entschieden werden, meldet <a href=\"http:\/\/albinfo.ch\" target=\"_blank\">albinfo.ch<\/a>.<\/div>\n<div><\/div>\n<div>&#8220;Wir sind der Meinung, dass Kosova ein sicheres Herkunftsland ist. Die R\u00fcckf\u00fchrung ist v\u00f6llig in Ordnung&#8221;, zitiert dpa den kosovarischen Permierminister Isa Mustafa.<\/div>\n<div class=\"yj6qo ajU\">\n<div id=\":1n5\" class=\"ajR\" tabindex=\"0\" data-tooltip=\"Afficher le contenu abr\u00e9g\u00e9\"><img decoding=\"async\" class=\"ajT\" src=\"https:\/\/ssl.gstatic.com\/ui\/v1\/icons\/mail\/images\/cleardot.gif\" alt=\"\" \/><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Kosova ist ein sicheres Land, R\u00fcckf\u00fchrung von Fl\u00fcchtlingen ist in Ordnung&#8221;<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-99270","post","type-post","status-publish","format-standard","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/99270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=99270"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/99270\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=99270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=99270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=99270"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=99270"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=99270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}