{"id":94938,"date":"2015-10-06T20:08:23","date_gmt":"2015-10-06T18:08:23","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=94938"},"modified":"2015-10-09T09:41:24","modified_gmt":"2015-10-09T07:41:24","slug":"250-infermiere-shqiptare-punesohen-ne-gjermani-2","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/250-infermiere-shqiptare-punesohen-ne-gjermani-2\/","title":{"rendered":"250 albanische Krankenpflegerinnen und Krankenpfleger finden Arbeit in Deutschland"},"content":{"rendered":"<p>250 Krankenpflegerinnen und Krankenpfleger aus Albanien werden in deutschen Krankenh\u00e4usern und Kliniken Arbeit finden. Ab dem 5. Oktober 2015 besuchen sie deutsche Sprachkurse, die bis zu einem Jahr dauern werden. Wenn die ausgew\u00e4hlten Bewerber sich\u00a0gen\u00fcgend Sprachkenntnisse, aber auch spezielle Kenntnisse f\u00fcr ihr spezifisches Profil\u00a0angeeignet haben, werden sie nach Deutschland ausreisen &#8211; das Land k\u00e4mpft\u00a0in bestimmten Branchen mit grossem Fachkr\u00e4ftemangel.<\/p>\n<p>Der Generaldirektor der Firma, die diese Fachkr\u00e4fte f\u00fcr die deutschen Kliniken und Krankh\u00e4user\u00a0rekrutiert,\u00a0Dietmar \u00a0Metzger, sagte, auch wenn man sich nun nur f\u00fcr 250 Bewerber entschieden hat, bleibt der Weg Richtung Deutschland offen, solange Deutschland gegen den\u00a0Fachkr\u00e4ftemangel k\u00e4mpft.<\/p>\n<p>&#8220;Wir werden weitere junge Einsteiger und Berufserfahrene rekrutieren, solange das gemeinsame Interesse der beiden L\u00e4nder und deren grosse Nachfrage besteht. Nun haben wir 250 Bewerber rekrutiert, die die Kriterien\u00a0erf\u00fcllen. Dies ist keine geschlossene Liste, denn wir haben vor, in naher Zukunft die Zahl der Rekrutierten zu verdoppeln &#8211; wir wollen sogar bis zu 1000 Krankenpflegerinnen und Krankenpfleger pro Jahr einstellen&#8221;, betonte Metzger, schreibt &#8220;Shekulli&#8221;.<\/p>\n<p>Die deutsche Arbeitsagentur hat eine Liste mit weiteren Berufen ver\u00f6ffentlichen, in denen Fachkr\u00e4ftemangel herrscht. Daher\u00a0will die Organisation von Metzger auch f\u00fcr weitere Berufe Bewerber in Albanien rekrutieren.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aus 1300 Bewerbern hat man 250 ausgew\u00e4hlt, die zun\u00e4chst Kurse in deutscher Sprache besuchen werden, um dann in deutschen Kliniken zu arbeiten.<\/p>\n","protected":false},"author":19,"featured_media":94911,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-94938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/94938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=94938"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/94938\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/94911"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=94938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=94938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=94938"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=94938"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=94938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}