{"id":937227,"date":"2026-07-08T12:45:03","date_gmt":"2026-07-08T10:45:03","guid":{"rendered":"https:\/\/www.albinfo.ch\/1zvicra-shenon-histori-fitin-ndaj-kolumbise-dhe-prek-cerekfinalen-e-boterorit\/"},"modified":"2026-07-08T21:53:52","modified_gmt":"2026-07-08T19:53:52","slug":"1zvicra-shenon-histori-fitin-ndaj-kolumbise-dhe-prek-cerekfinalen-e-boterorit","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/1zvicra-shenon-histori-fitin-ndaj-kolumbise-dhe-prek-cerekfinalen-e-boterorit\/","title":{"rendered":"Die Schweiz schreibt Geschichte, besiegt Kolumbien und erreicht das Viertelfinale der Weltmeisterschaft"},"content":{"rendered":"<p class=\"isSelectedEnd\">Die Schweizer Nationalmannschaft hat sich ein goldenes Ticket f\u00fcr das Viertelfinale der Weltmeisterschaft 2026 gesichert, nachdem sie Kolumbien in einem dramatischen Spiel besiegt hat, das \u00fcber die regul\u00e4ren 90 Minuten hinausging, schreibt albinfo.ch.<\/p>\n<p>Nach einem au\u00dfergew\u00f6hnlichen Kampf in Vancouver, bei dem die regul\u00e4re Spielzeit mit einem torlosen 0:0 endete, zeigten die Schweizer in den entscheidenden Momenten einen starken Charakter und brachen den Widerstand der S\u00fcdamerikaner. Die von Granit Xhaka angef\u00fchrte Mannschaft schrieb vom Elfmeterpunkt aus Geschichte und reihte sich unter die acht besten Teams der Welt ein.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Schweizer Nationalmannschaft hat sich ein goldenes Ticket f\u00fcr das Viertelfinale der Weltmeisterschaft 2026 gesichert, nachdem sie Kolumbien in einem dramatischen Spiel besiegt hat, das \u00fcber die regul\u00e4ren 90 Minuten hinausging, schreibt albinfo.ch. Nach einem au\u00dfergew\u00f6hnlichen Kampf in Vancouver, bei dem die regul\u00e4re Spielzeit mit einem torlosen 0:0 endete, zeigten die Schweizer in den entscheidenden [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":936977,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34992,24631,1139],"tags":[],"vendi":[],"content_country":[29888,31836,31837],"class_list":["post-937227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boterori-2026-de","category-nachrichten-de-2","category-sport","content_country-zvicer","content_country-austria-de","content_country-germany-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/937227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=937227"}],"version-history":[{"count":1,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/937227\/revisions"}],"predecessor-version":[{"id":937228,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/937227\/revisions\/937228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/936977"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=937227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=937227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=937227"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=937227"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=937227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}