{"id":91347,"date":"2015-08-25T09:53:58","date_gmt":"2015-08-25T07:53:58","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=91347"},"modified":"2015-08-25T10:04:19","modified_gmt":"2015-08-25T08:04:19","slug":"bunjaku-uberzeugt-vom-neuen-albumcover-von-eminem","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/bunjaku-uberzeugt-vom-neuen-albumcover-von-eminem\/","title":{"rendered":"Bunjaku \u00fcberzeugt vom neuen Albumcover von Eminem"},"content":{"rendered":"<p>&#8220;&#8230;alle sagen, ich habe erwartet, dass ich gewinne. Ich war davon \u00fcberzeugt, dass ich gewinnen w\u00fcrde&#8221;, sagte Granit Bunjaku, nachdem bekannt wurde, dass sein Design das neue Album von Eminem schm\u00fccken wird.<\/p>\n<p>Ein Mikrofon, das mit Geschossen geladen ist, das von einem Kosovaren entworfen ist, \u00fcberzeugte die Jury und den weltweit bekannten Rapper Eminem. Der Entwurf von Granit Bunjaku, Absolvent der Architektur an der Uni Prishtina, wurde als bestes Design f\u00fcr das Cover vom neuen Album von Eminem gew\u00e4hlt.<\/p>\n<p>Bunjaku sagte, er sei davon \u00fcberzeugt gewesen, dass er gewinnen w\u00fcrde. Er habe die Arbeiten seiner Konkurrenten verfolgt und dann war er sicher, dass sein Entwurf der beste sein wird.<\/p>\n<p>&#8220;Eigentlich haben mit aller gesagt, dass ich den Preis gewinnen w\u00fcrde. Ich war von Anfang an davon \u00fcberzeugt, dass ich gewinnen w\u00fcrde&#8221;, sagte er in einem kurzen Interview mit koha.net. &#8220;Dennoch muss ich sagen, dass ich schon etwas unter Schock stand als die Entscheidung bekannt gegeben wurde&#8221;.<\/p>\n<p>In seinem Entwurf zeigt Bunjaku in den H\u00e4nden von Eminem ein Mikro, das mit Geschossen geladen ist. Auf den ersten Blick sieht es sehr einfach aus, doch vielleicht genau dies hat die Jury von &#8220;Creative Allies&#8221; \u00fcberzeugt.<\/p>\n<p>&#8220;Die Idee hatte ich von den Texten von Eminem, von seinen Worten, die er der Masse richtet&#8221;, so Bunjaku.<\/p>\n<p>Er gibt zu, dass er kein grosser Fan von Eminem ist. &#8220;Ich h\u00f6re ihn, genauso wie ich auch andere K\u00fcnstler h\u00f6re.&#8221;<\/p>\n<p>Eminem selbst hat auf Facebook und auf Twitter die Entscheidung bekannt gegeben. &#8220;Danke an alle, die ihre Vorschl\u00e4ge geschickt haben. Ihr habt f\u00fcr Granit gestimmt und sein Entwurf wurde als bestes gew\u00e4hlt. Gl\u00fcckwunsch mein Freund.&#8221;<\/p>\n<p>Granit geniesst noch diesen Erfolg und sagt, dass er wieder nach solchen M\u00f6glichkeiten schauen wird.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;&#8230;alle sagen, ich habe erwartet, dass ich gewinne. Ich war davon \u00fcberzeugt, dass ich gewinnen w\u00fcrde&#8221;, sagte Granit Bunjaku, nachdem bekannt wurde, dass sein Design das neue Album von Eminem schm\u00fccken wird. Ein Mikrofon, das mit Geschossen geladen ist, das von einem Kosovaren entworfen ist, \u00fcberzeugte die Jury und den weltweit bekannten Rapper Eminem. Der [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1129,1138,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-91347","post","type-post","status-publish","format-standard","hentry","category-ch-balkan","category-kultur","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/91347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=91347"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/91347\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=91347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=91347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=91347"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=91347"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=91347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}