{"id":91275,"date":"2015-08-24T09:50:45","date_gmt":"2015-08-24T07:50:45","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=91275"},"modified":"2015-08-24T09:50:45","modified_gmt":"2015-08-24T07:50:45","slug":"schweizer-unternehmen-fuhrende-investoren-in-kosova","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/schweizer-unternehmen-fuhrende-investoren-in-kosova\/","title":{"rendered":"Schweizer Unternehmen f\u00fchrende Investoren in Kosova"},"content":{"rendered":"<p>Schweizer Unternehmer f\u00fchren die Liste der ausl\u00e4ndischen Investitionen in Kosova mit insgesamt 34.4 Millionen Euro in Jahr 2015 an.<\/p>\n<p>Diese Angaben stammen von der Agentur f\u00fcr Investitionen und Unterst\u00fctzung f\u00fcr Unternehmen in Kosova.<\/p>\n<p>In absoluten Zahlen wurden am meisten Unternehmen mit albanischem Kapital gegr\u00fcndet, meldet Tribuna.<\/p>\n<p>Die Angaben der Agentur f\u00fcr Investitionen und Unterst\u00fctzung der Unternehmen zeigen, dass es in Kosova 42 albanische Unternehmen gibt. Dennoch liegt Albanien auf Platz 6 mit 13.4 Millionen Euro investiertes Kapital in Kosova.<\/p>\n<p>In Kosova operieren 21 Unternehmen, die mit Kapital aus der Schweiz gegr\u00fcndet worden sind. Doch mit insgesamt 34.4 Millionen Euro Investitionen f\u00fchrt die Schweiz die Liste der ausl\u00e4ndischen Investitionen in Kosova. Auf Platz 2 liegt \u00d6sterreich, danach kommen die T\u00fcrkei und Serbien.<\/p>\n<p>Die kosovarische Zentralbank hat in den letzten 2 Jahren einen erheblichen R\u00fcckgang der ausl\u00e4ndischen Investitionen in Kosova verzeichnet. &#8220;Von Januar bis Mai 2015 wurden in Kosova 38 Millionen Euro investiert. In der selben Periode des Vorjahres lagen die ausl\u00e4ndischen Investitionen bei 60 Millionen Euro&#8221;, heisst es in einem Bericht der kosovarischen Zentralbank.<\/p>\n<p>Der Spitzenwert der ausl\u00e4ndischen Investitionen wurde im Jahr 2007 erreicht. In diesem Jahr erreichte der Wert der ausl\u00e4ndischen Investitionen 440 Millionen Euro.<\/p>\n<p>Von 2008 bis 2011 machten die ausl\u00e4ndischen Investitionen durchschnittlich 8.3% des kosovarischen Bruttoinlandsproduktes aus.<\/p>\n<p style=\"margin: 0cm 0cm 7.5pt 0cm;\">\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schweizer Unternehmer f\u00fchren die Liste der ausl\u00e4ndischen Investitionen in Kosova mit insgesamt 34.4 Millionen Euro in Jahr 2015 an. Diese Angaben stammen von der Agentur f\u00fcr Investitionen und Unterst\u00fctzung f\u00fcr Unternehmen in Kosova. In absoluten Zahlen wurden am meisten Unternehmen mit albanischem Kapital gegr\u00fcndet, meldet Tribuna. Die Angaben der Agentur f\u00fcr Investitionen und Unterst\u00fctzung der [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-91275","post","type-post","status-publish","format-standard","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/91275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=91275"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/91275\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=91275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=91275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=91275"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=91275"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=91275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}