{"id":86932,"date":"2015-07-01T08:52:34","date_gmt":"2015-07-01T06:52:34","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=86932"},"modified":"2015-07-01T09:13:39","modified_gmt":"2015-07-01T07:13:39","slug":"griechische-schuldenkrise-ansteckungsrisiko-fur-balkanstaaten","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/griechische-schuldenkrise-ansteckungsrisiko-fur-balkanstaaten\/","title":{"rendered":"Griechische Schuldenkrise &#8211; Ansteckungsrisiko f\u00fcr Balkanstaaten"},"content":{"rendered":"<p>Bankensysteme der Balkanstaaten sind weiterhin ungesch\u00fctzt vor der Gefahr der Ansteckung durch die griechische Schuldenkrise. Griechenland steht mit dem R\u00fccken zur Wand; das Land muss entscheiden, ob es den Euro weiterhin beibehalten oder ob es den gemeinsamen W\u00e4hrungsraum verlassen will.<\/p>\n<p>Die Weltbank schreibt in einem j\u00fcngsten Bericht, dass der wirtschaftliche und finanzielle Druck in Griechenland ein zus\u00e4tzliches Risiko f\u00fcr die Wirtschaft der L\u00e4nder der Region darstellt, auch wenn es diesbez\u00fcglich im Jahr 2010 am schlimmsten war.<\/p>\n<p>Die Bankensysteme in Albanien, Bulgarien, Mazedonien, Rum\u00e4nien und Serbien sind weiterhin einer Ansteckungsgefahr ausgesetzt &#8211; griechische Banken haben viele Ableger in diesen L\u00e4ndern. Daher warnt die Weltbank diese L\u00e4nder vor\u00a0dem Risiko, das aus\u00a0der griechischen Krise f\u00fcr sie ausgeht.<\/p>\n<p>So sind 18% der albanischen Banken mir griechischem Kapital ausgestattet. F\u00fcr das\u00a0albanische Bankensystem stellt die Griechenlandkrise also eine akute Gefahr dar. Zudem kommen 3.7% des albanischen Bruttoinlandproduktes\u00a0in Form von Geldsendungen\u00a0au Griechenland von\u00a0albanischen Migranten.<\/p>\n<p>Dennoch ist das albanische Bankensystem sicher, sagt der albanischen Zentralbankchef Genti Sejko. Die Krise in\u00a0Griechenland ist keine unmittelbare Gefahr f\u00fcr das Bankenstektor in Albanien. Man erwarte allerdings einen R\u00fcckgang der Geldsendungen und des Handelsvolumens mit dem s\u00fcdlichen Nachbarn.<\/p>\n<p>Auch die Albanische Bankenvereinigung versicherte alle albanischen Sparer und Anleger, dass die griechische Schuldenkrise keine Gefahr f\u00fcr ihre Ersparnisse und Anlagen darstellt. Die Banken seien stabil und arbeiten ganz normal weiter, heisst es in einer Medienmitteilung der Vereinigung.<\/p>\n<p>&#8220;Das albanische Bankensystem, einschliesslich Banken mit griechischem Kapital, ist finanziell und operational unabh\u00e4ngig von den Bankensystemen anderer L\u00e4nder.\u00a0 Alle Banken in Albanien arbeiten als unabh\u00e4ngige Einheiten im Rahmen albanischer Gesetze und unterstehen albanischen Regulierungsvorschriften&#8221;, heisst es in der Medienmitteilung. Das albanische Bankensystem hat einen hohen Deckungsgrad mit\u00a0Kapital\u00a0und\u00a0eine\u00a0hohe Liquidit\u00e4t. Die Banken sind also stabil und von den negativen Auswirkungen von der Krise im Nachbarland nicht unmittelbar betroffen.<\/p>\n<p>Auch Kosova ist von der Griechenlandkrise minimal betroffen. Die kosovarische Wirtschaft hat eine sehr lose Bindung zur griechischen Wirtschaft, sagt f\u00fcr das Radio Freies Europa der Mediensprecher der kosovarischen Zentralbank, Besnik Kada. Griechische Direktinvestitionen sowie Geldsendungen von kosovarischen Migration aus Griechenland sind sehr tief. Zudem gibt es auf\u00a0dem kosovarischen Bankensektor keine Bank mit griechischem Kapital.<\/p>\n<p>Heute muss Griechenland 1.7 Milliarden Euro an den IWF zur\u00fcckzahlen. Der griechische Finanzminister hat allerdings schon angek\u00fcndigt, dass das Land diese Frist nicht einhalten und den Kredit nicht zur\u00fcckzahlen kann. Die Gl\u00e4ubiger haben best\u00e4tigt, dass sie die weiteren Hilfsfonds nicht freigeben werden solange sich die Regierung von Tsipras nicht zu den geforderten Reformen\u00a0bekennt.<\/p>\n<p>In den kommenden Tagen entscheidet sich das Schicksal der griechischen Wirtschaft und der Verbleib des Landes in der Eurozone. Am 5. Juli sollen die Griechen in einem Referendum dar\u00fcber entscheiden, ob sie die Reformpl\u00e4ne der Europartner annehmen oder ablehnen.<\/p>\n<p>Laut Experten sind mehrere Szenarien denkbar. So k\u00f6nnen die Verhandlungspartner vielleicht doch noch in der letzten Sekunde einen Kompromiss finden. Danach w\u00e4ren Fonds freigegeben und das Land kann den Kredit an den IWF zur\u00fcckzahlen.<\/p>\n<p>Deweiteren ist denkbar das die Griechen die Reformpl\u00e4ne annehmen. Dann w\u00e4re Tsipras wohl gezwungen, zur\u00fcckzutreten. Er hat sinem\u00a0Volk empfohlen, die Reformpl\u00e4ne der Geldgeber abzulehnen.<\/p>\n<p>Schliesslich k\u00f6nnten die Griechen tats\u00e4chlich die Reformpl\u00e4ne ablehnen. Dies w\u00fcrde eine weitere Isolation Griechenlands bedeuten. Ein Austritt aus dem Euro ist dann kaum noch vermeidbar. Ein Rausswurf aus dem Euro ist allerdings in den Regelwerken der W\u00e4hrungsunion nicht vorgesehen.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bankensysteme der Balkanstaaten sind weiterhin ungesch\u00fctzt vor der Gefahr der Ansteckung durch die griechische Schuldenkrise. Griechenland steht mit dem R\u00fccken zur Wand; das Land muss entscheiden, ob es den Euro weiterhin beibehalten oder ob es den gemeinsamen W\u00e4hrungsraum verlassen will. Die Weltbank schreibt in einem j\u00fcngsten Bericht, dass der wirtschaftliche und finanzielle Druck in Griechenland [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129,1412],"tags":[],"vendi":[],"content_country":[],"class_list":["post-86932","post","type-post","status-publish","format-standard","hentry","category-aktuell","category-ch-balkan","category-newsletter-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/86932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=86932"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/86932\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=86932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=86932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=86932"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=86932"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=86932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}