{"id":82889,"date":"2015-05-17T18:23:55","date_gmt":"2015-05-17T16:23:55","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=82889"},"modified":"2015-05-22T12:17:58","modified_gmt":"2015-05-22T10:17:58","slug":"proteste-masive-nikolla-ik-2","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/proteste-masive-nikolla-ik-2\/","title":{"rendered":"Massenproteste gegen die Regierung in Skopje"},"content":{"rendered":"<div class=\"galery-slider\"><ul class=\"slides\"><li>\n\t\t\t\t\t\t\t<a data-litebox-text=\"Keystone\" data-litebox-group=\"article-gallery\" href=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2015\/05\/246331320.jpg\" class=\"litebox\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2015\/05\/246331320-586x389.jpg\"\/><\/a>\n\t\t\t\t\t\t\t<div class=\"articleIntro articleText\">\n\t\t\t\t\t\t\t\t<p>Keystone<\/p>\n\t\t\t\t\t\t\t<\/div>\n                        <\/li><li>\n\t\t\t\t\t\t\t<a data-litebox-text=\"Keystone\" data-litebox-group=\"article-gallery\" href=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2015\/05\/246361469.jpg\" class=\"litebox\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2015\/05\/246361469-586x389.jpg\"\/><\/a>\n\t\t\t\t\t\t\t<div class=\"articleIntro articleText\">\n\t\t\t\t\t\t\t\t<p>Keystone<\/p>\n\t\t\t\t\t\t\t<\/div>\n                        <\/li><li>\n\t\t\t\t\t\t\t<a data-litebox-text=\"Keystone\" data-litebox-group=\"article-gallery\" href=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2015\/05\/246360809.jpg\" class=\"litebox\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2015\/05\/246360809-586x389.jpg\"\/><\/a>\n\t\t\t\t\t\t\t<div class=\"articleIntro articleText\">\n\t\t\t\t\t\t\t\t<p>Keystone<\/p>\n\t\t\t\t\t\t\t<\/div>\n                        <\/li><li>\n\t\t\t\t\t\t\t<a data-litebox-text=\"Keystone\" data-litebox-group=\"article-gallery\" href=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2015\/05\/246337785.jpg\" class=\"litebox\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.albinfo.at\/wp-content\/uploads\/2015\/05\/246337785-586x389.jpg\"\/><\/a>\n\t\t\t\t\t\t\t<div class=\"articleIntro articleText\">\n\t\t\t\t\t\t\t\t<p>Keystone<\/p>\n\t\t\t\t\t\t\t<\/div>\n                        <\/li><\/ul><div class=\"slidesounter\"><span class=\"slide-current-slide\"><\/span><span class=\"slide-total-slides\"><\/span><\/div><\/div><link href=\"https:\/\/www.albinfo.at\/wp-content\/themes\/albinfo\/assets\/css\/litebox.css\" rel=\"stylesheet\" type=\"text\/css\" media=\"all\" \/><script src=\"https:\/\/www.albinfo.at\/wp-content\/themes\/albinfo\/assets\/js\/images-loaded.min.js\" type=\"text\/javascript\"><\/script><script src=\"https:\/\/www.albinfo.at\/wp-content\/themes\/albinfo\/assets\/js\/litebox.min.js\" type=\"text\/javascript\"><\/script>\n        <script type=\"text\/javascript\">\n            jQuery(window).load(function() {\n              jQuery(\".flexslider7\").flexslider({\n                animation: \"slide\",\n                controlNav: false,\n                animationLoop: false,\n                slideshow: false,\n              });\n            });\n\t\t\tjQuery(\".litebox\").liteBox();\n        <\/script>\n<p>Mehr als 100\u2018000 Menschen haben sich am Sonntag dem Protest der Opposition gegen die Regierung von Premierminister Nikolla Gruevski \u00a0angeschlossen. Es war die gr\u00f6sste Demonstration der Opposition seit Gruesvki (VMRO-DPMNE) 2006 an die Macht kam.<\/p>\n<p>Dem Aufruf zur Demonstration folgten auch Albaner, T\u00fcrken und andere ethnische Gruppen. Auch ausl\u00e4ndische Diplomaten nahmen am Protest teil, wie der Europarlamentarier Richard Hovit, der auch Berichterstatter\u00a0 \u00fcber Mazedonien im Europa-Parlament ist.<\/p>\n<p>Dies ist die erste Demonstration im multiethnischen Mazedonien, wo beide grossen Volksgruppen, Albaner und Mazedonier f\u00fcr eine Sache gemeinsam\u00a0 protestieren. Im Jahr 2001 stand Mazedonien am Rande eines B\u00fcrgerkrieges. Dieser konnte durch den Eingriff der internationalen Gemeinschaft abgewendet werden. Das darauffolgende Abkommen von Ohrid sollte den Albanern als zweitgr\u00f6sste Bev\u00f6lkerungsgruppe in Mazedonien mehr Rechte einr\u00e4umen. Dieses Abkommen wurde aber von der jetzigen Regierung nur sehr schleppend umgesetzt.<\/p>\n<p>Die eindr\u00fccklichste Botschaft sendeten die Studenten: in einer flammenden Rede, die in Mazedonisch und in Albanisch gelesen wurden, forderten die Studenten den R\u00fccktritt der kriminellen Regierung von Gruevski.<\/p>\n<p><strong>Mazedonier und Albaner, gemeinsam gegen Gruevski<\/strong><\/p>\n<p>Der Sprecher der oppositionellen SDMS, Petar Shillegov sagte, das Volk werde vor dem Regierungssitz solange bleiben, bis Gruevski zur\u00fccktritt \u201eDer R\u00fccktritt ist nah und das Volk wird hier bleiben\u201c. Er zeigte sich zufrieden, dass auch Albaner an der Demonstration teilgenommen haben.<\/p>\n<p>Der Chef der SDSM sagte vor der Menschmenge, es sei an der Zeit, dass Gruevski abtritt. \u201eSeine Stunden sind gez\u00e4hlt, er soll das Regierungsgeb\u00e4ude verlassen\u201c. Er warf der Regierung kriminelle Machenschaften, Wahlmanipulationen, Machtmissbrauch und Unterdr\u00fcckung der Menschen vor. \u201eDie Wahrheit \u00fcber Mazedonien wird an die Oberfl\u00e4che kommen. Wir haben entschieden, die Demokratie wieder einzuf\u00fchren. Dieser Monat wird in die neueren Geschichte von Mazedonien eingehen. Wir werden wieder f\u00fcr Rechtsstaatlichkeit sorgen und dies tun wir gemeinsam mit allen Menschen in unserem Land, unabh\u00e4ngig von ihrer ethnischen und religi\u00f6sen Zugeh\u00f6rigkeit\u201c, sagte Zaev.<\/p>\n<p><strong>Gr\u00f6sste Massendemonstration der Opposition<\/strong><\/p>\n<p>Die Demonstrationen flammten auf, nach dem Bekanntwerden des Abh\u00f6rskandals. Der Oppositionschef ver\u00f6ffentlicht seit nun mehr als 2 Monaten regelm\u00e4ssig abgeh\u00f6rte Telefonate, die die kriminellen Machenschaften von Premierminister Gruevski, seiner Minister und seinem Onkel, dem Chef des Geheimdienstes Sasho Mijallkov aufdecken. Die abgeh\u00f6rten Telefonate, die irgendwie zur Opposition gelangt sind, belegen, dass die gesamte Regierungsstruktur einschliesslich den albanischen Ministern in organisierter Kriminalit\u00e4t und in Korruption verwickelt sind. Der gr\u00f6sste Skandal war, dass die Bodyguards von Gruevski zwei junge Menschen umbrachten \u2013 die ver\u00f6ffentlichen abgeh\u00f6rten Telefonate zeigen, dass Gruesvki und seine Leute versucht hatten, diese Morde zu vertuschen.<\/p>\n<p>Die Spitze der kriminellen Handlungen war die Polizeiaktion in einem mehrheitlich von Albanern bewohnten Viertel von Kumanova, eine Stadt im Norden von Mazedonien an der Grenze zu Kosova. In zweit\u00e4tigen kriegerischen Auseinandersetzungen kamen insgesamt 22 Personen ums Leben, davon 8 Polizisten. Mehr als 60 H\u00e4user wurden zerst\u00f6rt.<\/p>\n<p>Laut internationalen Quellen war diese Polizeiaktion ein Szenario, das von Gruevski, von der nun zur\u00fcckgetretenen Innenministerin Jankullovska und vom Geheimdienstchef vorbereitet worden ist. Das geheime Szenario sah vor, dass die UCK-K\u00e4mpfer dorthin gelockt worden waren, damit sie von der Polizei erschossen werden konnten. \u00a0Ziel war es, die Aufmerksamkeit der \u00d6ffentlichkeit von den Skandalen der Regierung abzulenken. Doch die internationalen Vertreter haben dieses Szenario durchschaut. Nach Gespr\u00e4chen mit ausl\u00e4ndische Diplomaten m\u00fcssten Janullovska und Mijallkov zur\u00fccktreten.<\/p>\n<p>Viele internationale und regionale polirische Analysten hoffen, dass dies das Ende des Regimes von Nikolla Gruevski ist. Der Protest war friedlich und verlief ohne Zwischenf\u00e4lle.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Oppositionsf\u00fchrer und Chef der SDSM (sozial-demokratische Liga von Mazedonien), Zoran Zaev sagte vor rund 100\u2018000 Menschen in Skopje, es ist an der Zeit, dass NIkalla Gruevski und seine Leute zur\u00fccktreten.<\/p>\n","protected":false},"author":19,"featured_media":82759,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-82889","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/82889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=82889"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/82889\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/82759"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=82889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=82889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=82889"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=82889"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=82889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}