{"id":828693,"date":"2025-05-10T22:54:36","date_gmt":"2025-05-10T20:54:36","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=828693"},"modified":"2025-05-10T22:54:36","modified_gmt":"2025-05-10T20:54:36","slug":"xhaka-gegen-dortmund-topspiel-in-der-bundesliga","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/xhaka-gegen-dortmund-topspiel-in-der-bundesliga\/","title":{"rendered":"Xhaka gegen Dortmund, Topspiel in der Bundesliga"},"content":{"rendered":"<p data-start=\"0\" data-end=\"171\">Bayer Leverkusen &#8211; Borussia Dortmund steht im Mittelpunkt des 33. Spieltags in der Bundesliga. Die Partie wird am Sonntag ab 15:30 Uhr ausgetragen, berichtet albinfo.ch.<\/p>\n<p data-start=\"173\" data-end=\"371\">Bayern M\u00fcnchen sicherte sich in der vergangenen Runde die deutsche Meisterschaft, nachdem Leverkusen patzte. Mit dem Sieg am letzten Wochenende feierten die Bayern ihre 34. deutsche Meisterschaft.<\/p>\n<p data-start=\"373\" data-end=\"716\">Leverkusen beendet die Saison als Tabellenzweiter. Zwei Spieltage vor Schluss stehen sie bei 68 Punkten. Ab der kommenden Spielzeit wird das Team nicht mehr von Trainer Xabi Alonso betreut: Der 43-J\u00e4hrige k\u00fcndigte am Freitag an, dass er Leverkusen zum Saisonende verlassen wird. Aktuell ist die Werkself seit sieben Ligaspielen ungeschlagen.<\/p>\n<p data-start=\"718\" data-end=\"998\">Dortmund belegt mit 51 Punkten den f\u00fcnften Platz und k\u00e4mpft um einen Champions-League-Rang. Nur die ersten vier Pl\u00e4tze qualifizieren sich f\u00fcr die K\u00f6nigsklasse. Auf Rang vier liegt Freiburg mit einem Punkt Vorsprung auf Dortmund, auf Rang drei Eintracht Frankfurt mit 56 Punkten.<\/p>\n<p data-start=\"1000\" data-end=\"1199\" data-is-last-node=\"\" data-is-only-node=\"\">Bayern M\u00fcnchen empf\u00e4ngt am Samstag ab 18:30 Uhr Borussia M\u00f6nchengladbach und wird voraussichtlich mit den Fans den Titel feiern. Gladbach liegt mit 45 Punkten derzeit auf dem neunten Tabellenplatz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bayer Leverkusen &#8211; Borussia Dortmund steht im Mittelpunkt des 33. Spieltags in der Bundesliga. Die Partie wird am Sonntag ab 15:30 Uhr ausgetragen, berichtet albinfo.ch. Bayern M\u00fcnchen sicherte sich in der vergangenen Runde die deutsche Meisterschaft, nachdem Leverkusen patzte. Mit dem Sieg am letzten Wochenende feierten die Bayern ihre 34. deutsche Meisterschaft. Leverkusen beendet die [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":797749,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4023,24631,1139],"tags":[],"vendi":[],"content_country":[29888,31836,31837],"class_list":["post-828693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futboll-de","category-nachrichten-de-2","category-sport","content_country-zvicer","content_country-austria-de","content_country-germany-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/828693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=828693"}],"version-history":[{"count":1,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/828693\/revisions"}],"predecessor-version":[{"id":828695,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/828693\/revisions\/828695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/797749"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=828693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=828693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=828693"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=828693"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=828693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}