{"id":820368,"date":"2025-04-06T22:29:50","date_gmt":"2025-04-06T20:29:50","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=820368"},"modified":"2025-04-06T22:29:50","modified_gmt":"2025-04-06T20:29:50","slug":"wallis-ist-raclette-weltmeister-weltrekord-mit-fast-5-000-teilnehmern","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/wallis-ist-raclette-weltmeister-weltrekord-mit-fast-5-000-teilnehmern\/","title":{"rendered":"Wallis ist Raclette-Weltmeister: Weltrekord mit fast 5.000 Teilnehmern"},"content":{"rendered":"<p>Die Bewohner des Kantons Wallis haben eindrucksvoll bewiesen, dass sie in Sachen Raclette die Nase vorn haben. Bei einem spektakul\u00e4ren Abendessen in Martigny stellte der Schweizer Kanton einen neuen Weltrekord auf \u2013 mit genau 4.893 G\u00e4sten, die gleichzeitig Raclette genossen.<\/p>\n<p>Die Veranstaltung wurde vom bekannten Raclette-Meister Eddy Baillifard organisiert, der sich nach dem gelungenen Event begeistert zeigte: \u201eDas ist ein ph\u00e4nomenaler Erfolg \u2013 was f\u00fcr eine Begeisterung beim Publikum und den K\u00e4se-Kratzern!\u201c, berichtet <a href=\"http:\/\/albinfo.ch\">albinfo.ch<\/a>.<\/p>\n<p>Die Initiative war eine Antwort auf den Rekord aus dem Vorjahr, der von den Franzosen in Saint-\u00c9tienne aufgestellt wurde \u2013 dort wurde Raclette f\u00fcr etwa 2.200 Personen serviert, sp\u00e4ter dann sogar f\u00fcr rund 2.500. F\u00fcr die Walliser war das untragbar. \u201eWir konnten den Franzosen nicht den Weltrekord f\u00fcr das gr\u00f6\u00dfte Raclette \u00fcberlassen\u201c, sagte Samuel Bonvin, Direktor des Ausstellungszentrums MyExpo, wo das Fest stattfand. \u201eRaclette ist ein kulturelles Erbe des Wallis, und der Raclette-K\u00e4se aus dem Wallis ist einzigartig.\u201c<\/p>\n<p>Beim Event wurde Raclette in traditioneller Form serviert \u2013 nicht in Tischpf\u00e4nnchen, wie in vielen modernen Restaurants, sondern mit halbierten K\u00e4selaiben, die \u00fcber Feuer oder mit speziellen Ger\u00e4ten geschmolzen und dann direkt auf den Teller geschabt wurden. Daher stammt auch der Name \u201eRaclette \u201c, abgeleitet vom franz\u00f6sischen Verb <em>racler<\/em>, was \u201eschaben\u201c bedeutet. Der K\u00e4se wurde \u2013 wie es der Brauch verlangt \u2013 mit Kartoffeln serviert, schreibt 20minuten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Bewohner des Kantons Wallis haben eindrucksvoll bewiesen, dass sie in Sachen Raclette die Nase vorn haben. Bei einem spektakul\u00e4ren Abendessen in Martigny stellte der Schweizer Kanton einen neuen Weltrekord auf \u2013 mit genau 4.893 G\u00e4sten, die gleichzeitig Raclette genossen. Die Veranstaltung wurde vom bekannten Raclette-Meister Eddy Baillifard organisiert, der sich nach dem gelungenen Event [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":686108,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1188,24006,24631,1140],"tags":[],"vendi":[],"content_country":[29888,31836,31837],"class_list":["post-820368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shkurt-ch-de","category-lajme-jeta-ne-zvicer-de","category-nachrichten-de-2","category-leben-in-der-schweiz","content_country-zvicer","content_country-austria-de","content_country-germany-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/820368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=820368"}],"version-history":[{"count":1,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/820368\/revisions"}],"predecessor-version":[{"id":820369,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/820368\/revisions\/820369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/686108"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=820368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=820368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=820368"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=820368"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=820368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}