{"id":80195,"date":"2015-04-16T00:07:25","date_gmt":"2015-04-15T22:07:25","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=80195"},"modified":"2015-04-17T09:33:34","modified_gmt":"2015-04-17T07:33:34","slug":"nje-kryeminister-shqiptar-do-ta-shpetonte-maqedonine-2","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/nje-kryeminister-shqiptar-do-ta-shpetonte-maqedonine-2\/","title":{"rendered":"Ein albanischer Premierminister w\u00fcrde Mazedonien retten"},"content":{"rendered":"<p>Die Bildung einer technischen Regierung mit einem albanischst\u00e4mmigen Premierminister\u00a0 k\u00f6nnte der Ausweg f\u00fcr die tiefe politische Krise in Mazedonien sein, sagt Ex-Regierungschef Lub\u00e7o Georgievski.<\/p>\n<div class=\"gmail_quote\">\n<div>Die technische Regierung w\u00fcrde demokratische Wahlen organisieren und den blockierten EU-Integrationsprozess des Landes wieder in Gang setzen. Um eine schnelle L\u00f6sung f\u00fcr die aktuelle Krise zu erzielen, m\u00fcsse man die Personen amnestieren, die die Abh\u00f6rungen der\u00a0Telefonatedurchgef\u00fchrt haben, die von der Opposition nun seit Wochen ver\u00f6ffentlicht werden,\u00a0, egal ob sie in der Regierung sitzen, oder von der Opposition kommen, meint Gerogiervski.<\/div>\n<div><\/div>\n<div>&#8220;In der letzten Zeit hat man immer mehr davon gesprochen, dass die technische Regierung von einem albanischst\u00e4mmigen Regierungschef geleitet werden soll. Dies ist f\u00fcr mich v\u00f6llig in Ordnung. Ich denke, in den letzten Jahren haben die Albaner 4 &#8211; 5 Intelektuelle hervorgebracht, die diese Aufgabe erfolgreich wahrnehmen k\u00f6nnten&#8221;.<\/div>\n<div><\/div>\n<div>Der politische Analyst Nazmi Maliqi sagt, albanische und mazedonische politische Parteien m\u00fcssen \u00fcber gemeinsame politische (Wahlkampf-) Programme nachdenken. Sie sollen nationalistische Wahlk\u00e4mpfe vermeiden, die bisher nur Hass zwischen den Ethnien gesch\u00fcrt haben.<\/div>\n<div><\/div>\n<div>&#8220;Patriotische nationalistischee Projekte sind das Leitmotiv der Politik in Mazedonien gewesen. Wir haben so viele Wahlk\u00e4mpfe in Mazedonien erlebt, aber bisher noch keine albanisch-mazedonische Wahlkampfkoalition mit einem politischen Projekt\u00a0erlebt, das auch das Regierungsprojekt gewesen w\u00e4re&#8221;, so Maliqi.<\/div>\n<div><\/div>\n<div>Nach dem Bekanntwerden des Abh\u00f6rskandals befindet sich die Regierung in Skopje in einer teifen Krise und das Land ist politisch gel\u00e4hmt. Die Opposition ver\u00f6ffentlich seit Wochen nach und nach abgeh\u00f6rte Telefonate, von denen man erf\u00e4hrt, dass die Regierung von VMRO-DPMNE in Zusammenarbeit mit dem Geheimdienst\u00a0illegal mehr als 20&#8217;000 Menschen abgeh\u00f6rt hat. Zudem ist bekannt geworden, dass die Partei von Regierungschef Nikolla Gruevski mehrfach\u00a0Lokal- und Parlamentswahlen schwer manipuliert sowie das Justizsystem missbraucht hat.<\/div>\n<div><\/div>\n<div>In Mazedonien leben mehr als 30% Albaner. Bisher ist kein Albaner\u00a0an der Spitze\u00a0einer der\u00a0wichtigen staatlichen Institutionen wie die Regierung, das Parlamant, oder das Pr\u00e4sidentenamt ernannt worden.<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ein technische Regierung mit einem albanischen Premierminister k\u00f6nnte eine L\u00f6sung f\u00fcr Mazedonien bieten, so der Ex-Regierungschef Lub\u00e7o Georgievski<\/p>\n","protected":false},"author":19,"featured_media":80074,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-80195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/80195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=80195"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/80195\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/80074"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=80195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=80195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=80195"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=80195"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=80195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}