{"id":70655,"date":"2014-12-28T13:15:23","date_gmt":"2014-12-28T12:15:23","guid":{"rendered":""},"modified":"2014-12-30T11:52:52","modified_gmt":"2014-12-30T09:52:52","slug":"helvetas-projekt-modell-fur-landwirtschaftliche-berufsausbildung-in-kosova","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/helvetas-projekt-modell-fur-landwirtschaftliche-berufsausbildung-in-kosova\/","title":{"rendered":"Helvetas-Projekt: Modell f\u00fcr landwirtschaftliche Berufsausbildung in Kosova"},"content":{"rendered":"<p>Bis vor einigen Jahren war der Anbau von Himbeeren in der Gemeinde Sht\u00ebrpc\u00eb sozusagen unbekannt. Im Rahmen des Projekts APR (Landwirtschaftliche Berufsausbildung) des Hilfswerks Helvetas besuchten dieses Jahr allein in der Gemeinde Sht\u00ebrpc\u00eb 84 haupts\u00e4chlich junge Menschen eine Ausbildung im Himbeeranbau, und innerhalb dieser Ausbildung pflanzten sie auf je f\u00fcnf Aren Himbeeren an. Einige der Projektteilnehmer legten ihre Anbaufl\u00e4chen zwecks einfacherer Bearbeitung zusammen, w\u00e4hrend andere sich (aufgrund der Entfernung zwischen den Grundst\u00fccken) f\u00fcr den Himbeeranbau auf ihrem je eigenen Feld entschieden.<\/p>\n<p>Von sieben Gruppen sind sechs mit insgesamt 64 Personen serbischer Ethnie, w\u00e4hrend eine Gruppe von 20 Personen albanischer Ethnie ist. Alle Teilnehmer profitierten vom Projekt APR, einige wurden auch mit Setzlingen unterst\u00fctzt, w\u00e4hrend die St\u00fctzger\u00fcste und das Bew\u00e4sserungssystem wie auch ein Teil der Setzlinge Investitionen der Gruppenmitglieder selbst sind. Die Beerenbauern gedenken, alle ihre Familienangeh\u00f6rigen in das Gesch\u00e4ft miteinzubeziehen.<\/p>\n<p>Cvetan Stefanovi\u0107 aus dem Dorf Gotovush pflanzte auf einer Fl\u00e4che von f\u00fcnf Aren 650 Himbeerstauden der Sorte Meeker an. Laut ihm l\u00e4sst sich diese Himbeersorte dichter als andere anpflanzen (in einem Abstand von 33 cm). &#8220;Nat\u00fcrlich kann meine Familie nicht von dieser Produktion allein leben, doch wenn ich davon ausgehe, dass, wie die Fachleute sagen, von f\u00fcnf Aren Himbeeren gleich viel Gewinn wie von vier Hektaren Weizen zu machen ist, dann lohnt es sich, mich einzusetzen, und wieso denn nicht gleich meine ganze Familie&#8221;, sagt Stefanovi\u0107.<\/p>\n<p>\u017deljko Nikoli\u0107, Gemeindeverantwortlicher des Projekts APR vor Ort, \u00e4ussert sich zufrieden mit dem Engagement der Helvetas in seiner Gemeinde, insbesondere wegen der Hilfe, die diese schweizerische Organisation der Jugend und den ans\u00e4ssigen Bauern in Sht\u00ebrpc\u00eb bietet, indem sie ihnen eine direkte Besch\u00e4ftigung in verschiedenen Bereichen erm\u00f6glicht. Helvetas unterst\u00fctzt jede Initiative, die die Jungen in dieser Gemeinde zur Arbeitsbeschaffung ergreifen.<\/p>\n<p>Auf Interesse stiess auch die Bienenzucht. Zwei Gruppen von jungen Leuten, die sich f\u00fcr die Bienenzucht interessierten, wurden von entsprechenden Fachleuten ausgebildet, die Gruppe aus V\u00ebrbeshtica von Jovica Slavi\u0107 von Sht\u00ebrpc\u00eb und die Gruppe aus dem Dorf Berevce von \u017divce Sarko\u010devi\u0107. Neunzehn junge Imker erhielten von der Helvetas Ausbildung sowie je ein Bienenvolk und einige Imkereiinstrumente, w\u00e4hrend f\u00fcr die Bienenk\u00f6rbe bzw. \u2013k\u00e4sten die Projektteilnehmer selbst aufkamen.<\/p>\n<p>Auch in der Viehzucht und weiteren Bereichen brachte das Projekt APR der Bev\u00f6lkerung von Sht\u00ebrpc\u00eb etwas. Da gibt es etwa eine Gruppe von jungen Leuten, die gerade dabei sind, eine Ausbildung zur Aufzucht von Schweinen abzuschliessen. Der Gruppe geh\u00f6ren f\u00fcnf Personen an, die sich auch um die Renovation des Stalls k\u00fcmmern, in welchem sie die Tiere unterbringen werden und wo ein kleines Unternehmen f\u00fcr Fleischproduktion und \u2013verarbeitung entstehen wird. Die entsprechende Gruppe wird einen Teil der zur Schweinezucht ben\u00f6tigten Ausr\u00fcstung erhalten, w\u00e4hrend die Gruppe der jungen Personen sich um die Renovation des Geb\u00e4udes und Anschaffung der &nbsp;Tiere k\u00fcmmern wird.<\/p>\n<p>Nikoli\u0107 berichtet ausserdem \u00fcber die Realisierung des Projekts mit den ans\u00e4ssigen Bauernfamilien. Es werden haupts\u00e4chlich Gruppen von Frauen in ausgepr\u00e4gt l\u00e4ndlichen Gebieten unterst\u00fctzt. Frauen der albanischen und der serbischen Gemeinschaft werden theoretische und praktische Ausbildungen angeboten. Insgesamt 230 Teilnehmerinnen (zu 80% Frauen) profitierten von Ausbildungen in Bereichen wie Viehzucht, Imkerei, Bergkr\u00e4uter und Obstbau. Nebst den Ausbildungen unterst\u00fctzte das APR-Projekt die Frauen, indem es sich an den Investitionen f\u00fcr den Kauf von Ausr\u00fcstung zur Verbesserung der Qualit\u00e4t des traditionellen K\u00e4ses beteiligt, oder es unterst\u00fctzt Frauen im Obstbau, beim Bau von Brunnen zur Bew\u00e4sserung ihrer Parzellen, und auch durch Mithilfe bei Investitionen zur Verbesserung der Qualit\u00e4t des Honigs. Die Unterst\u00fctzung durch APR wird den Frauen dieser Gegend helfen, die K\u00e4sequalit\u00e4t zu steigern, Menge und Qualit\u00e4t der Himbeeren zu erh\u00f6hen respektive zu verbessern, und mit Produktion und Verkauf des bekannten Honigs der Gemeinde Sht\u00ebrpc\u00eb ein gutes Einkommen zu erzielen.<\/p>\n<p>\u201eDa wir uns tats\u00e4chlich in einer auch f\u00fcr den Tourismus sehr geeigneten Region befinden, hoffe ich, dass Helvetas-Swiss Intercooperation sich in Zukunft auch in dieser Richtung engagierenn wird, und ich bin sicher, dass dies zu Erfolg f\u00fchrt, wovon auch die einheimische Bev\u00f6lkerung profitieren wird. Wir sind jedenfalls sehr zufrieden mit der Arbeit der Helvetas in unserer Gemeinde\u201c, gibt Nikoli\u0107 seiner Anerkennung f\u00fcr die Arbeit von Helvetas Ausdruck.<\/p>\n<p>Eine erfolgreiche Durchf\u00fchrung des Projekts APR in Sht\u00ebrpc\u00eb wie auch in den anderen drei Regionen von Kosovo (Kamenica, Novob\u00ebrd\u00eb und Dragash) lassen allein schon die g\u00fcnstigen Voraussetzungen erwarten \u2013 nat\u00fcrliche Reicht\u00fcmer, g\u00fcnstiges Klima, junge Arbeitskr\u00e4fte und, selbstverst\u00e4ndlich, die Hilfsbereitschaft der Helvetas.<\/p>\n<p align=\"right\"><strong>Xhevdet Kallaba<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Anbau von Himbeeren der Sorten Meeker und Polka geh\u00f6rt in der Gemeinde Sht\u00ebrpc\u00eb inzwischen zu Hausaufgaben. Dank der Hilfe von HELVETAS pflanzten 84 Projektteilnehmer auf je f\u00fcnf Aren Himbeeren an. Das Interesse f\u00fcr den Himbeeranbau w\u00e4chst zunehmend<\/p>\n","protected":false},"author":40,"featured_media":66794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1131,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-70655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-investitionen","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/70655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=70655"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/70655\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/66794"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=70655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=70655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=70655"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=70655"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=70655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}