{"id":70641,"date":"2014-12-08T22:21:44","date_gmt":"2014-12-08T21:21:44","guid":{"rendered":""},"modified":"2014-12-10T09:22:45","modified_gmt":"2014-12-10T07:22:45","slug":"politische-krise-in-kosova-gelost","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/politische-krise-in-kosova-gelost\/","title":{"rendered":"Politische Krise in Kosova gel\u00f6st"},"content":{"rendered":"<p>Oppositionsf\u00fchrer Isa Mustafa hat das Mandat zur Regierungsbildung erhalten. Der Vize-Chef der PDK, Kadri Veseli, wird neuer Parlamentsvorsitzende. Damit geht die sechs monatige politische Krise in Kosova zu Ende.<\/p>\n<div>Der ehemalige Chef des Geheimdinestes (SHIK) Kadri Veseli wurde zum Vorsitzenden des Parlaments best\u00e4tigt. Die neue Regierung wurde allerdings nicht best\u00e4tigt &#8211; die zehn serbischen Abgeordneten haben gr\u00f6ssere Forderungen an die neue Regierung gestellt.<\/div>\n<div>&nbsp;<\/div>\n<div>Mustafa, der sicher Regierungschef wird, kommt an die Spitze der Regierung nach einer sechs Monate andauernden politischen Krise. Er wird der sechste Regierungschef seit dem Ende des Krieges im Jahr 1999.<\/div>\n<div>&nbsp;<\/div>\n<div>Der ehemalige Finanzminister der Exil-Regierung von Bujar Bukoshi, hat ein Expose seines Regierungsprogramms vorgetragen. Er versprach wirtschaftliche Entwicklung, Kampf gegen die Korruption und gegen das organisierte Verbrechen &#8211; der Rechtsstaat ist die Basis des Regierens, sagte er.<\/div>\n<div>&nbsp;<\/div>\n<div>&#8220;Die neue Regierung wird mit der Zivilgesellschaft und Unternehmern zusammenarbeiten. Wir werden die Korruption und alle Arten von Extremismus bek\u00e4mpfen und die Rechte des Einzelnen respektieren&#8221;, so Mustafa. Auch der Dialog mit Serbien werde weitergef\u00fchrt. Der Prozess der EU-Integrationen soll einen neuen Schub bekommen.<\/div>\n<div>&nbsp;<\/div>\n<div>&#8220;Das Ziel ist, eine neue effektive, kompetente und verantwortungsvolle Regierung zu stellen, die das Vertrauen der B\u00fcrger des Landes und das Vertrauen der internationalen Partner an die Vitalit\u00e4t des neuen unabh\u00e4ngigen Staates st\u00e4rkt&#8221;<\/div>\n<div>&nbsp;<\/div>\n<div>Die neue Opposotion kritisierte den neuen Regierungschef scharf. Er sei ein gescheiterter und die Koalition PDK-LDK seien eine Partnerit\u00e4t des B\u00f6sen.<\/div>\n<div>&nbsp;<\/div>\n<div><strong>Haradinaj: PDK-LDK, Koalition des B\u00f6sen<\/strong><\/div>\n<div>&nbsp;<\/div>\n<div>Der Chef der AAK Ramush Haradinaj sagte, die neue Koalition sei eine Partnerit\u00e4t des B\u00f6sen. Wie k\u00f6nne so eine Regierung \u00fcberhaupt funktionieren? Eines Tages jedoch, wird auch diese Regierung zu Ende gehen.<\/div>\n<div>&nbsp;<\/div>\n<div>&#8220;Jedes Mal, wenn der Wechsel und die Ver\u00e4nderung m\u00f6glich war, haben sich die Schlechten zusammengetan &#8211; der Schlimme und der Schwache&#8221;, sagte Haradinaj.<\/div>\n<div>&nbsp;<\/div>\n<div>&#8220;Im Grunde st\u00f6rt uns diese Koalition nicht. Denn selbt die Vorsitzenden dieser Koalition haben mehr als einmal gesagt, dass eine solche Koalition unnat\u00fcrlich ist. Zwei Parteien bilden&nbsp;eine grosse Koalition, damit das Land eine gute Regierung bekommt. Doch eine gute Regierung kann nicht von Menschen kommen, die zwei Gesichter haben und von Doppelmoral gepr\u00e4gt sind&#8221;, sagte der ehemalige Parlamentsvorsitzende Jakup Krasniqi.<\/div>\n<div>&nbsp;<\/div>\n<div>&#8220;Diese Regierung braucht keine starke Kritik oder Bef\u00fcrworter. Denn diese Regierung hat nicht einmal eine Strasse asphaltiert, keine Schule gebaut, wenn dies nicht in Wahlstimmen \u00fcbersetzt wurde&#8221;, so Glauk Konjufca von Vet\u00ebvendosje!<\/div>\n<div>&nbsp;<\/div>\n<div><strong>Vet\u00ebvendosje: Schwarzer Tag f\u00fcr Kosova&nbsp;<\/strong><\/div>\n<div>&nbsp;<\/div>\n<div>Der nun neue Regierungschef, kam&nbsp;mit dem Menschen zusammen, der das Land so miserabel gef\u00fchrt hat in den letzten Jahren.<\/div>\n<div>&nbsp;<\/div>\n<div>&#8220;Dieser neue Regierungschef kam an die Spitze der LDK, dadurch dass er den Menschen versprach, der kriminellen Regierung der PDK ein Ende zu setzen. Doch dieser Mensch sei in keine Sekunde erhlich gewesen. Wie kann er die Stimmen der B\u00fcrger missbrauchen und jetzt mit Hashim Thaci in einer Regierung sitzen&#8221;, sagte unter anderem Glauk Konjufca.<\/div>\n<div>&nbsp;<\/div>\n<div>Der F\u00fchrer der Begewegung Vet\u00ebvendosje! sagte, die Ver\u00e4nderung in Kosova kann nicht mit einer Regierung kommen, in der auch die PDK sitzt. Wer mit der PDK koaliert, wollen keine Ver\u00e4nderung. Es sei ein schwarzer Tag f\u00fcr Kosova, denn Vorsitzender des Parlaments ist nun ein Mann des Geheimdienstes SHIK und auf der anderen Seite haben sich zwei schrumpfende Parteien zusammengetan, nur um die Macht an sich zu reissen. &#8220;Die Parolle der PDK ist &#8220;Familie&nbsp;ist Eigentum ist&nbsp;Staat&#8221;. LDK kann keine Koalitioni mit PDK f\u00fchren &#8211; LDK muss Teil der PDK-Familie werden&#8221;, so Kurti.<\/div>\n<div>&nbsp;<\/div>\n<div>Der bisherige Regierungschef Hashim Thaci sagte, die anderen Parteien seien unehrlich, wenn sie die neue Koalition kritisieren, die er als &#8216;nat\u00fcrlich&#8217; bezeichnete.<\/div>\n<div>&nbsp;<\/div>\n<div>&#8220;PDK und LDK sind Mitte-Rechts Parteien. Ich m\u00f6chte sagen, dass bevor ich die Koalition mit LDK unterschrieben habe, haben mir alle anderen Parteien angeboten, mit ihnen eine Koalition einzugehen. Ich wollte aber nicht, dass die untransparent verl\u00e4uft. Tags\u00fcber haben sie mit Mustafa verhandelt, nachmittags waren sie in den B\u00fcros der PDK&#8221;, si Thaci.<\/div>\n<div>&nbsp;<\/div>\n<div>PDK und LDK haben einen Vertrag unterschrieben, der Hashim Thaci im Jahr 2016 den Posten des Staatsschefs sicherert, wann das Mandat von Atifete Jahjaga endet.<\/div>\n<div class=\"yj6qo ajU\">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Kadri Veseli ist der neue Parlamentsvorsitzende, der Oppositionsf\u00fchrer Isa Mustafa soll die neue Regierung in Prishtina f\u00fchren. Heute soll die neue Regierung stehen.<\/p>\n","protected":false},"author":24223,"featured_media":66347,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-70641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/70641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/24223"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=70641"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/70641\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/66347"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=70641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=70641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=70641"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=70641"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=70641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}