{"id":64998,"date":"2014-11-14T00:17:11","date_gmt":"2014-11-13T23:17:11","guid":{"rendered":""},"modified":"2014-11-17T09:10:47","modified_gmt":"2014-11-17T07:10:47","slug":"lage-des-privaten-sektors-kritisch","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/lage-des-privaten-sektors-kritisch\/","title":{"rendered":"Lage des privaten Sektors kritisch"},"content":{"rendered":"<p>Hohe Korruption, fehlende institutionelle Unterst\u00fctzung, unlauter Wttbewerb und die sechs monatige politische Krise haben Unternehmen in Kosova grossen Schaden zugef\u00fcgt, hiess es in der von &#8216;Riinvest&#8217; organisierten Kofenrenz &#8220;Business Climate in Kosovo&#8221;. <\/p>\n<div>Ausser der politischen Krise herrscht ein schlechte Wirtschaftsklima nun mehr seit 4 Jahren in Kosova. Die Privatwirtschaft ist in einer schweren Krise, sagte Lumir Abdixhiku, Leiter von Riinvest. Das einzige Ziel des Staates bisher sei es, Steuern und Abgaben&nbsp;einzukassieren. Die institutionelle Unterst\u00fctzung f\u00fcr die Unternehmen bleibe auf der Strecke.<\/div>\n<div>Die politisch Krise, die nun mehr seit 6 Monaten dauert, kann zu einem finanziellen Kollaps des Landes f\u00fchren. Um dies zu verhindern, m\u00fcsse der Haushalt f\u00fcr das Jahr 2015 bis zum 31.12.2014 verabschiedet werden.<\/div>\n<div>&nbsp;<\/div>\n<div>Thomas Gocchi vom EU-B\u00fcro in Prishtina sprach \u00fcber die Sorgen der EU bez\u00fcglich der politischen Krise im Land. Er forderte die Parteien dazu&nbsp;auf, so schnell wir m\u00f6glich eine L\u00f6sung zu finden.<\/div>\n<div>Jan-Peter Olters von der Weltbank sagte, die hohe Arbeitslosigkeit und das Aussenhandelsdefizit sind zwei grosse Nachteile und Schwachpunkte der kosovarischen Wirtschaft. Der Privatsektor definiere den Erfolg der wirtschaftlichen Entwicklung.<\/div>\n<div>Mit diesem negativen Trend der wirtschaftlichen Entwicklung verliere Kosova rund 325 Millionen Dollar im Jahr.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hohe Korruption, unlauter Wettbewerb und die sechs monatige politische Krise haben der Privatwirtschaft grossen Schaden gebracht. Laut &#8216;Riinvest&#8217; ist die Lage des Privatensektors kritisch.<\/p>\n","protected":false},"author":24223,"featured_media":54953,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-64998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/24223"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=64998"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64998\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/54953"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=64998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=64998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=64998"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=64998"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=64998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}