{"id":64987,"date":"2014-10-29T12:46:37","date_gmt":"2014-10-29T11:46:37","guid":{"rendered":""},"modified":"2015-01-28T09:51:10","modified_gmt":"2015-01-28T08:51:10","slug":"politische-krise-in-kosova-verscharft-sich","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/politische-krise-in-kosova-verscharft-sich\/","title":{"rendered":"Politische Krise in Kosova versch\u00e4rft sich"},"content":{"rendered":"<p>Die politische Krise in Kosova versch\u00e4rft sich immer mehr, die beiden politischen Lager (die PDK und das B\u00fcndnis VLAN) haben sich in ihren Haltungen versteift, so dass sie jegliche M\u00f6glichkeit zur \u00dcberwindung der politischen Pattsituation blockieren. Laut politischen Beobachtern sind die Missverst\u00e4ndnisse so weit gediehen, dass es keine L\u00f6sung ohne Vermittlung von internationaler Seite gibt.<\/p>\n<p>Die Krise versch\u00e4rfte sich, nachdem die Pr\u00e4sidentin des Landes, Atifete Jahjaga, den Antrag der Parteien der nach den Wahlen gebildeten Koalition (LDK, AAK, Nisma) und von 17 Abgeordneten der Minderheiten, sie solle vom Verfassungsgericht zus\u00e4tzliche Erkl\u00e4rungen f\u00fcr einen Ausweg aus der Krise verlangen, abgewiesen hatte.<\/p>\n<p>Jahjaga vertritt eine andere Haltung als jene, die das B\u00fcndnis mit seinem Antrag vertritt. Sie verlangt, die L\u00f6sung solle in einem gemeinsamen Treffen aller politischen Leader bestehen.<\/p>\n<p>&#8220;Vermittels Treffen mit den politischen F\u00fchrern des Landes werde ich weiterhin an der Vereinfachung des Prozesses f\u00fcr die Bildung neuer staatlicher Institutionen arbeiten. Und ich bin weiterhin bereit, den Prozess, durch welchen die Leader der parlamentarischen politischen Parteien eine L\u00f6sung f\u00fcr die entstandene Sackgasse finden werden, zu vereinfachen&#8221;, sagte sie.<\/p>\n<p>Jene Abgeordneten, die ihr parlamentarisches Mandat von den drei Oppositionsparteien erhielten, aber auch jene der Minderheiten, verlangten von Jahjaga, sie solle Punkt 127 des vorangegangenen Entscheids des Verfassungsgerichts an das Gericht zur\u00fcckweisen.<\/p>\n<p>Dieser Punkt, der den Mitgliedern der Legislative empfiehlt, selbst eine L\u00f6sung zu finden, ist nicht sehr klar. Deshalb verlangen die erw\u00e4hnten Abgeordneten, Pr\u00e4sidentin Jahjaga m\u00f6ge das Gericht nochmals um Kl\u00e4rung ersuchen, wie dieser Punkt in der Praxis zu verstehen sei. Jahjaga wies diesen Antrag jedoch ab, womit sie die Opposition in eine schwierige Lage brachte.<\/p>\n<p>Albinfo.ch sprach mit einigen politischen Beobachtern in Kosova und Makedonien. Diese sagen, die Krise habe solche Ausmasse angenommen, dass nur noch ausserordentliche Wahlen das Land retten k\u00f6nnten. Die Schuld an der seit f\u00fcnf Monaten andauernden Krise geben sie allen F\u00fchrern der politischen Parteien, darin eingeschlossen auch Staatspr\u00e4sidentin Jahjaga.<\/p>\n<p><strong>Option Wahlen am wenigsten erw\u00fcnscht<\/strong><\/p>\n<p>Adrian \u00c7ollaku ist Chefredaktor der Onlinezeitung Blic. Er sagte, es gebe zwei realistische Optionen zur \u00dcberwindung der politischen Krise: &#8220;Die Neuformation der Koalition V-LAN und ein m\u00f6gliches Abkommen PDK-LDK.&#8221; Letzteres ist laut ihm weniger wahrscheinlich, w\u00e4hrend eine \u00c4nderung des Abkommens der nach den Wahlen gebildeten Koalition realistisch sei.<\/p>\n<p>&#8220;Nach dem Verlust des Postens des Parlamentsvorsitzenden wegen des Gerichtsentscheids muss das B\u00fcndnis das Abkommen neukonfigurieren, indem es LDK-Chef Isa Mustafa umplatziert, sei es auf den Posten des Ministerpr\u00e4sidenten, oder je nachdem wie sie sich untereinander verst\u00e4ndigen, der PDK den Posten des Ministerpr\u00e4sidenten \u00fcberl\u00e4sst. Das bedeutet, der VLAN hat keine Zeit mehr zu verlieren&#8221;, sagt \u00c7ollaku.<\/p>\n<p>Der Gerichtsentscheid sei zu respektieren, deshalb m\u00fcsse das B\u00fcndnis den Kandidaten der PDK zum Parlamentsvorsitzenden w\u00e4hlen und den Weg zur Regierungsbildung \u00f6ffnen.<\/p>\n<p>&#8220;Hashim Tha\u00e7i hat vierzehn Tage Zeit, die Regierung zu bilden. Nach dieser Frist ist Jahjaga gem\u00e4ss Verdikt des Verfassungsgerichts dazu verpflichtet, dem Block zu erlauben, seinen Kandidaten zu w\u00e4hlen, denn andernfalls k\u00f6nnte die Bev\u00f6lkerung auf die Strasse gehen&#8221;, sagt \u00c7ollaku.<\/p>\n<p>Hingegen ist seiner Ansicht nach ein Abkommen zwischen der PDK und dem B\u00fcndnis weniger wahrscheinlich. &#8220;Und wenn diese M\u00f6glichkeiten scheitern, braucht es Wahlen, die dem Augenschein nach auch von internationaler Seite nicht sehr erw\u00fcnscht sind, insbesondere jetzt, wo das Land vor vielen Herausforderungen steht, wie dem Sondergericht, den Gespr\u00e4chen mit Serbien etc.&#8221; meint \u00c7ollaku.<\/p>\n<p>Azem Vllasi als Kenner in politischen Dingen sagt, die einfachste und schnellste L\u00f6sung zur \u00dcberwindung der politischen Pattsituation sei eine Koalition PDK-LDK.<\/p>\n<p>&#8220;Ich denke, dass die LDK f\u00fcr die entstandene Situation verantwortlich ist, denn der Entscheid des Verfassungsgerichts, welcher der PDK das Recht gab, den Posten des Parlamentsvorsitzenden zu w\u00e4hlen, war ihr klar&#8221;, meint Vllasi, dessen Ansicht nach die LDK in Koalition mit der PDK auch den Posten des Ministerpr\u00e4sidenten verlangen kann.<\/p>\n<p><strong>Rashidi: &#8220;Gesamte politische Klasse verantwortlich&#8221;<\/strong><\/p>\n<p>Nazim Rashidi, politischer Beobachter aus Makedonien, sagt, schuld an der jetzigen Lage sei die gesamte politische Klasse in Kosovo. &#8220;Die Verantwortung liegt zweifellos bei der gesamten politischen Klasse. Auffallend ist die fehlende Kompromissbereitschaft und das geht auf Kosten aller&#8221;, erkl\u00e4rte Rashidi.<\/p>\n<p>Seiner Ansicht nach von Bedeutung ist jedoch das korrekte Funktionieren der Institutionen, und dies sei offenbar der Fall. &#8220;Das ist das Verdienst des Verantwortungsbewusstseins in der Verwaltung, von Menschen, die den Staat sch\u00e4tzen, was offensichtlich im Widerspruch zur politischen Klasse steht, die sich einfach nicht aufraffen kann, eine L\u00f6sung zu finden&#8221;, sagte Rashidi.<\/p>\n<p>Als erstes sollten nun laut ihm die politischen Handlungstr\u00e4ger die Verwaltung, die Staatsbeamtinnen dazu ermutigen, weiterhin verantwortlich zu handeln. Jede \u00e4hnliche Lage irgendwo auf dem Balkan k\u00f6nnte laut Rashidi realistischer Weise auch zu einer noch tieferen gesellschaftlichen Krise f\u00fchren.<\/p>\n<p>Auf die Frage, ob die politische L\u00f6sung beim kosovarischen Parlament oder in Treffen mit den politischen F\u00fchrern liege, antwortet Rashidi, dies sei weniger wichtig.<\/p>\n<p>&#8220;Die L\u00f6sung f\u00fcr die politische Pattsituation, ob nun im Parlament oder mit Wahlen, muss so schnell wie m\u00f6glich kommen. Das ist massgebend. Auf die Politik muss Druck ausge\u00fcbt werden, diesen Schwebezustand nicht weiterandauern zu lassen. Eines ist klar, wenn es bis jetzt keinen Kompromiss gibt, soll das Volk noch einmal entscheiden k\u00f6nnen&#8221;, sagte er.<\/p>\n<p>Auf die Frage, wie stark die Krise dem Image Kosovos geschadet habe, entgegnete Rashidi, diese schade allen, der politischen Klasse, dem Staat, am meisten aber den Menschen, obwohl gerade sie sich zur Zeit am verantwortungsvollsten zeigten.<\/p>\n<p>In Kosova hatten am 8.Juni dieses Jahres Wahlen stattgefunden, nachdem das Parlament sich im Mai aufgel\u00f6st hatte. Seither funktioniert Kosova ohne Parlament und mit von Amts wegen eingesetzter Regierung. Infolge der nichtexistierenden demokratischen Organe konnte das Haushaltsbudget f\u00fcr 2015 nicht genehmigt werden, was ein Hindernis darstellt.<\/p>\n<p>Pr\u00e4sidentin Atifete Jahjaga schliesst nicht aus, dass es zu ausserordentlichen Wahlen kommen k\u00f6nnte.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Albinfo.ch sprach mit einigen politischen Beobachtern in Kosovo und Makedonien. Sie sagen, die Krise habe solche Ausmasse angenommen, dass nur noch Wahlen das Land retten k\u00f6nnten.<\/p>\n","protected":false},"author":1,"featured_media":72681,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-64987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=64987"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64987\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/72681"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=64987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=64987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=64987"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=64987"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=64987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}