{"id":64974,"date":"2014-10-16T15:26:03","date_gmt":"2014-10-16T13:26:03","guid":{"rendered":""},"modified":"2014-10-17T09:08:46","modified_gmt":"2014-10-17T07:08:46","slug":"hooligan-randale-demolierte-geschafte-albanischer-eigentumer","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/hooligan-randale-demolierte-geschafte-albanischer-eigentumer\/","title":{"rendered":"Hooligan Randale : Demolierte Gesch\u00e4fte albanischer Eigent\u00fcmer"},"content":{"rendered":"<p>Der gewaltige Spielabbruch im Fu\u00dfballspiel zwischen Serbien und Albanien in Belgrad hatte auch gestern&nbsp; Gewalt zur Folge. &nbsp;&nbsp;Die B\u00e4ckerei \u201cDva brata\u201d&nbsp; des albanischen Besitzer wurde gestern in Sombor von unbekannten T\u00e4tern angebrant .<\/p>\n<p>Laut Angaben von B92 wurde der Brand in der&nbsp; B\u00e4ckerei durch einen Molotowcocktail angestiftet und sie brannte ganz ab.<\/p>\n<p>Es soll dies das zweite Mal der Brandstiftung in dieser B\u00e4ckerei sein. Zum ersten Mal wurde sie bei der Unabh\u00e4ngigkeitserkl\u00e4rung von Kosova angebrannt.<\/p>\n<p>Nicht nur die B\u00e4ckereri in Sombor, sondern auch zwei weitere Gesch\u00e4fte albanischer Eigent\u00fcmer wurden in der letzten Nacht angegriffen. In Novi Sad wurde ein albanisches Eigentum mit Steinen beworfen, w\u00e4hrend dessen wurde in Nova Pazova eine Handgranate in der B\u00e4ckerei eines Albaners geworfen.<\/p>\n<p>Der Besitzer der B\u00e4ckerei \u201cMilenijum as\u201d in Stara Pazova erz\u00e4hlte \u00fcber den Angriff in der letzten Nacht gegen 01.00 Uhr in seine Werkstatt.<\/p>\n<p>\u201cEiner der Angreifer hat mit einer automatischen Schusswaffe ca. 50 mal abgefeuert, dabei hat ein anderer eine Handgranate auf die Werkstatt geworfen und hat sie demoliert \u201d, sagte Asllani und f\u00fcgte hinzu, dass die Polizei vor Ort gewesen sei, berichtet \u201cZ\u00ebri\u201d.<\/p>\n<p>Inzwischen berichten die montenegrinischen Medien \u00fcber einen Angriff auf die albanische Botschaft in Podgorica. Die Zeitung \u201cPobjeda\u201d berichtet, dass drei T\u00e4ter gegen 10:45 Uhr Steine auf die albanische Botschaft geworfen haben. Es wurden nur Sachsch\u00e4den verursacht. Die drei mutma\u00dflichen Angreifer wurden von der Polizei festgenommen, unter ihnen ist ein ehemaliger Polizeibeamter aus Podgorica.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zwei B\u00e4ckereien albanischer Eifent\u00fcmer  wurden von den Hooligans angegriffen. Die eine in Sombor wurde niedergebrannt und die andere in Nova Pazova wurde von einer Bombe getroffen<\/p>\n","protected":false},"author":24223,"featured_media":54418,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-64974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/24223"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=64974"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64974\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/54418"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=64974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=64974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=64974"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=64974"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=64974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}