{"id":64969,"date":"2014-10-14T14:58:05","date_gmt":"2014-10-14T12:58:05","guid":{"rendered":""},"modified":"2014-10-17T09:02:16","modified_gmt":"2014-10-17T07:02:16","slug":"ungefahr-500-jugendliche-aus-kosova-haben-geheiratet-und-einen-antrag-auf--aufenthaltspapiere-gestellt","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/ungefahr-500-jugendliche-aus-kosova-haben-geheiratet-und-einen-antrag-auf--aufenthaltspapiere-gestellt\/","title":{"rendered":"Ungef\u00e4hr  500 Jugendliche aus Kosova haben geheiratet und einen Antrag auf  \u201c Aufenthaltspapiere\u201d  gestellt"},"content":{"rendered":"<p>\u201cIm Jahr 2012 haben 2163 Kosovaren einen Antrag auf Familienzusammenf\u00fchrung gestellt, davon waren 1112 Antr\u00e4ge auf eine Heirat mit einem schweizerischen Staatsb\u00fcrger\u201d hei\u00dft es in der Mitteilung, Zitat von \u201cZ\u00ebri\u201d.<\/p>\n<p>Inzwischen wird von der deutschen Botschaft in Prishtina berichtet, dass keine ausf\u00fchrliche Angaben der Familienzusammenf\u00fchrungsantr\u00e4ge vorhanden sind.<\/p>\n<p>Laut Auskunft der Botschaft werden die Aufenthaltsgenehmigungsantr\u00e4ge nicht nur in der Botschaft verarbeitet, sondern auch von Ausl\u00e4nderbeh\u00f6rden und bei Antr\u00e4ge auf Visum zum Zweck einer Arbeitsaufnahme ist die Bundesagentur f\u00fcr Arbeit zust\u00e4ndig.<\/p>\n<p>Andererseits teilte die Botschaft mit, dass &nbsp;3600 D- Visen oder ein l\u00e4ngerfristiger Aufenthalt&nbsp; nur im Jahr 2013 f\u00fcr Kosovaren ausgestellt wurden. 2400 davon sind Familienzusammenf\u00fchrungen. &nbsp;<\/p>\n<p>Ansonsten sind \u201cBr\u00e4ute mit Aufenthaltspapiere\u201d au\u00dfergew\u00f6hnlich beliebt bei den Jugendlichen in Kosova. Laut einer Umfrage des letzten Jahres sollen mehr als die H\u00e4lfte der Jugendlichen in Kovova die Heimat verlassen und in die EU-Staaten auswandern, wollen. Au\u00dferdem marschierten eine Gruppe von Jugendlichen im Sommer mit dem Slogan \u201cIch will eine Braut mit Aufenthaltspapiere\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"\n<p>Im Laufe des 1.Halbjahres haben 931 Kosovaren bei der schweizerischen Botschaft in Kosova eine Familienzusammenf\u00fchrung beantragt. 486 von ihnen haben Gesuche f\u00fcr Schweizer Aufenthaltspapiere infolge einer Heirat gemacht. Diese Angaben ver\u00f6ffentlchte die schweizerische Botschaft in Prishtina.<\/p>\n","protected":false},"author":24223,"featured_media":54356,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-64969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/24223"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=64969"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64969\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/54356"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=64969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=64969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=64969"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=64969"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=64969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}