{"id":64948,"date":"2014-09-24T16:34:58","date_gmt":"2014-09-24T14:34:58","guid":{"rendered":""},"modified":"2014-09-26T11:36:36","modified_gmt":"2014-09-26T09:36:36","slug":"die-saisonarbeit-weiterhin-ein-traum-fur-kosovaren","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/die-saisonarbeit-weiterhin-ein-traum-fur-kosovaren\/","title":{"rendered":"Die Saisonarbeit, weiterhin ein Traum f\u00fcr Kosovaren"},"content":{"rendered":"<p><span style=\"font-size: small;\">Kosova hat dieses Jahr keine Vereinbarung f\u00fcr Saisonarbeit unterzeichnet. Nur zwei kosovarische Staatsb\u00fcrger haben sich f\u00fcr die Saisonarbeit im Ausland vorbereitet, aber auch die scheiterten.<\/span><\/p>\n<p><span style=\"font-size: small;\">Laut Statistiken sind mehr als 30% der Kosovaren arbeitslos, w\u00e4hrend 70% der Bev\u00f6lkerung im Alter von unter 31 Jahre&nbsp; sind.&nbsp;<\/span><\/p>\n<p><span style=\"font-size: small;\">Die Regierung in Prishtina hat bisher Zusammenarbeit f\u00fcr Saisonarbeit mit Deutschland gegr\u00fcndet, und es besteht auch eine Vereinbarung mit der Schweiz und dem F\u00fcrstentum Lichtenstein.<\/span><\/p>\n<p><span style=\"font-size: small;\">Hafiz Leka vom Ministerium f\u00fcr Arbeit und Sozialf\u00fcrsorge sagt, dass die Studenten, die letztes Jahr an der Saisonarbeit beteiligt waren, es wahrscheinlich auch dieses Jahr sind. Leka sagt, dass dieses Jahr nur zwei Staatsb\u00fcrger sich f\u00fcr die Saisonarbeit vorbereitet haben, die aber ihre Arbeit noch nicht begonnen haben.<\/span><\/p>\n<p><span style=\"font-size: small;\">Leka betont, dass diese Zusammenarbeit mit den Bundesarbeitvermittlungszentren in Deutschland dieses Jahr nicht funktionierte. Grund daf\u00fcr, ist der politische Krampf, der hier im Januar herrschte, so Leka.<\/span><\/p>\n<p><span style=\"font-size: small;\">Einige Jugendliche im Kosovo w\u00fcrden gerne in verschiedenen L\u00e4ndern Europas als Saisonarbeiter arbeiten.<\/span><\/p>\n<p><span style=\"font-size: small;\">\u201cKosova soll eine Vereinbarung f\u00fcr Saisonarbeit haben. Ich w\u00fcrde gerne als Saisonarbeiter arbeiten um meiner Familie und mir zu helfen\u201d, sagt Ardit Leka.<\/span><\/p>\n<p><span style=\"font-size: small;\">Auch Meriton Krasniqi-arbeitslos sagt, dass er, wenn er die M\u00f6lichkeit h\u00e4tte wie in Kosova, aber auch in Ausland gerne arbeiten w\u00fcrde.<\/span><\/p>\n<p><span style=\"font-size: small;\">\u201cUnser Zentrum f\u00fcr Migration und Dienstleistungen steht vielen Studenten zur Verf\u00fcgung, die sich f\u00fcr die Saisonarbeit in den EU-L\u00e4ndern interessieren. Dieses Jahr gab es sehr weniger Projekte. Grund daf\u00fcr, ist m\u00f6glicherweise auch die Fehlfunktion der Institutionen der Republik Kosovo nach den Wahlen vom 8. Juni\u201d, \u00e4u\u00dferte sich Leka.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nur zwei kosovarische Staatsb\u00fcrger haben sich f\u00fcr die Saisonarbeit im Ausland vorbereitet, aber auch die scheiterten<\/p>\n","protected":false},"author":24223,"featured_media":53974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-64948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/24223"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=64948"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64948\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/53974"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=64948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=64948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=64948"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=64948"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=64948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}