{"id":64886,"date":"2014-07-12T17:50:23","date_gmt":"2014-07-12T15:50:23","guid":{"rendered":""},"modified":"2014-07-14T13:15:53","modified_gmt":"2014-07-14T11:15:53","slug":"schwache-ernte-auch-in-diesem-jahr","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/schwache-ernte-auch-in-diesem-jahr\/","title":{"rendered":"Schwache Ernte auch in diesem Jahr"},"content":{"rendered":"<p>Das Landwirtschaftsministerium rechnet damit, dass dieses Jahr Kosova 80% der Nachfragen nach Weizen durch eigene Ertr\u00e4ge decken wird. Allerdings betonen die Landwirtschaftsverb\u00e4nde, dass es nur 30% der Nachfrage gedeckt werden kann.<\/p>\n<div>Laut Angaben der Kommission zur Beobachtung der Ernte 2014 im Rahmen des Landwirtschaftsministerium werden in diesem Jahr 85\u00b4000 Hektar Wiezen angebaut. Damit werde man 80% der inl\u00e4ndischen Nachfrage decken k\u00f6nnen, sagt Jusuf Cikaqi von dieser Kommission.<\/div>\n<div>&nbsp;<\/div>\n<div>In Kosova seien aber maximal 60\u00b4000 Hektar Weizen angebaut. Somit werden die Weizenertr\u00e4ge nur f\u00fcr maximal 30% der Bev\u00f6lkerung reichen. Man m\u00fcsste bis zu 170\u00b4000 Hektar Fl\u00e4chen mit Weizen anbauen, damit man die&nbsp;Bev\u00f6lkerung in Kosova ern\u00e4hren&nbsp;kann, sagt Tahir Tahiri vom Gewerkschaftsbund kosovarische Bauern.<\/div>\n<div>&nbsp;<\/div>\n<div>Die durschnittliche Ernte in diesem Jahr betr\u00e4gt 3&#8217;000 Kilo pro Hektar.<\/div>\n<div>&nbsp;<\/div>\n<div>Somit&nbsp;ist Kosova auch in diesem Jahr von den Weizenimporten aus Serbien abh\u00e4ngig.<\/div>\n<div>&nbsp;<\/div>\n<div>Laut Angaben von internationalen Organisationen liegt die Nachfrage nach Weizen bei 205 Kilo pro Kopf.<\/div>\n<div>&nbsp;<\/div>\n<div>Wegen der schwachen Ernte und der m\u00f6glichen Importschwierigkeiten kann es zu Preisesteigerungen kommen.<\/div>\n<div class=\"yj6qo ajU\">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Weizenetr\u00e4ge reichen auch dieses Jahr nicht, die Nachfrage nach Brot in Kosova zu decken.<\/p>\n","protected":false},"author":19,"featured_media":52781,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-64886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=64886"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64886\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/52781"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=64886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=64886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=64886"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=64886"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=64886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}