{"id":64882,"date":"2014-07-08T09:20:49","date_gmt":"2014-07-08T07:20:49","guid":{"rendered":""},"modified":"2014-07-09T12:01:50","modified_gmt":"2014-07-09T10:01:50","slug":"die-albaner-mussen-auch-verantwortung-ubernehmen","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/die-albaner-mussen-auch-verantwortung-ubernehmen\/","title":{"rendered":"&#8220;Die Albaner m\u00fcssen auch Verantwortung \u00fcbernehmen&#8221;"},"content":{"rendered":"<p>Nach Ansicht von Nazim Rashidi, politischer Beobachter in Makedonien, befindet sich der makedonische Staat auf einem schwierigen Weg zur Schaffung interethnischer Beziehungen. Der albanischen politischen Klasse wirft er vor, sich taub zu stellen.<\/p>\n<p>Im Gespr\u00e4ch mit albinfo.ch sagt Rashidi, die politische Klasse sei durch ihr Schweigen zu den Problemen mitverantwortlich f\u00fcr diesen Zustand. Zum Prozess um den &#8220;Fall Monstra&#8221; meint Rashidi, eine Schuld sei nie bewiesen worden.<\/p>\n<p>Auf die Frage, ob das Abkommen von Ohrid aufs Spiel gesetzt werden sollte, sagte Rashidi, in Makedonien h\u00e4tten seit 2001 noch andere Abkommen abgeschlossen werden k\u00f6nnen, doch das Problem sei deren Umsetzung.<\/p>\n<p><strong>Albinfo.ch:<\/strong> Herr Rashidi, die j\u00fcngsten Proteste zeigten, wie heikel die Lage in Makedonien ist. Wer tr\u00e4gt zur zunehmenden Spannung der Situation dort bei?<\/p>\n<p><strong>Rashidi:<\/strong> Am meisten Sorgen bereitet mir das klar fehlende Vertrauen in die Institutionen, das sich nun zeigt, und dass dagegen nichts unternommen wird. Je tiefgreifender der Vertrauensverlust, desto mehr wird es Reaktionen ausserhalb der Institutionen geben. Erstaunlich ist, und das l\u00e4sst mir keine Ruhe, dass im Grunde genommen niemand die Lehren aus der Vergangenheit gezogen hat. Makedonien ging durch eine schwierige Periode, w\u00e4hrend der es sich bem\u00fchte, Vertrauen in die Institutionen aufzubauen, vor allem bei den Albanern. Das h\u00e4tte Makedonien nach 2001 nur zu gut wissen sollen. Doch es geschieht das Gegenteil.<\/p>\n<p>Und anstatt dass die Beh\u00f6rden und Institutionen selbst oder auch die albanischen Politiker mehr zur Kl\u00e4rung beitragen w\u00fcrden, tragen sie mit un\u00fcberlegten Aussagen, andere mit Schweigen, noch mehr zur Vertiefung des Misstrauens gegen\u00fcber dem Staat bei.<\/p>\n<p><strong>Albinfo.ch:<\/strong> Beweisen diese Proteste, dass die Albaner in Makedonien von den Inhabern der Regierungsmacht diskriminiert werden?<\/p>\n<p><strong>Rashidi:<\/strong> Meiner Meinung nach befindet sich Makedonien in einer Phase, in der vieles in der Hand der Albaner liegt. Das Problem liegt bei der Unf\u00e4higkeit einer ganzen politischen Klasse, die sich im institutionellen Terrain nicht zurechtfindet. Erkl\u00e4rungen wie &#8220;denn die Albaner werden st\u00e4ndig diskriminiert&#8221; stellen eine Amnestie f\u00fcr die albanischen Akteure dar. Jene sind jedoch Teil der Institutionen, das erkl\u00e4ren sie uns st\u00e4ndig, jetzt m\u00fcssen sie auch Verantwortung \u00fcbernehmen.<\/p>\n<p>Die Frage der gleichen Rechte ist noch nicht so weit gediehen, dass sie ein f\u00fcr alle Mal abgeschlossen werden k\u00f6nnte, vielmehr braucht es dazu st\u00e4ndige Aufmerksamkeit, wof\u00fcr eine institutionelle Kultur geschaffen werden muss. Doch mit unf\u00e4higen F\u00fchrungskr\u00e4ften, mit einer Auswahl von Personen, die dank kleinlichem politischen Kalk\u00fcl und nicht auf Grund von Verdiensten auf ihre Posten kommen, ist dies nicht m\u00f6glich, und wir werden Zeugen eines zunehmenden Abbaus sein.<\/p>\n<p>Es findet eine Abwertung der demokratischen Prozesse statt, Gewalt und Angst herrschen. Doch wenn die Politiker vor Herausforderungen stehen, insbesondere institutionellen, (sicherlich mit Ausnahmen), dann schweigen sie bestenfalls, w\u00e4hrend wir alle die Opfer ihrer Ignoranz sind.<\/p>\n<p><strong>Albinfo.ch:<\/strong> Ist der &#8220;Fall Monstra&#8221; politisch montiert und weshalb sprechen die albanischen Richter und Juristen nicht \u00fcber diesen Fall?<\/p>\n<p><strong>Rashidi:<\/strong> Fest steht, dass wir es mit einem unrechten Verfahren zu tun haben. Niemand glaubt dem Entscheid und niemand ist aufgrund der geschilderten Tatsachen davon \u00fcberzeugt, dass es sich um die wirklichen Schuldigen des T\u00f6tungsdeliktes handelt. Betont werden muss, dass es keinen Albaner gab, der nach dem Vorfall diesen nicht verurteilte. Keiner will die Schuldigen verteidigen, doch andererseits will keiner in einem Staat leben, wo Menschen ohne Beweis schuldig gesprochen werden.<\/p>\n<p>Die Leute stehen unter dem Eindruck, dass Schwache und Ungesch\u00fctzte mit allem rechnen m\u00fcssen (und es gibt andere F\u00e4lle, wo Verurteilungen, die Makedonier betrafen, jedoch solche mit anderer politischer Herkunft als jener der herrschenden Regierung, ebenfalls zu Reaktionen f\u00fchrten). F\u00fcgen wir diesem Gef\u00fchl noch das ethnische Element hinzu, haben wir die Reaktionen, wie wir sie nun sehen.<\/p>\n<p>Auf der andern Seite verst\u00e4rkt das Schweigen der Verantwortlichen in den Institutionen das Gef\u00fchl der Unsicherheit noch mehr, anstatt dass letztere etwas zur Beruhigung unternehmen w\u00fcrden. Wir haben hier nicht einen politischen Prozess, sondern vielmehr einen Prozess, bei welchem die Menschen immer mehr die Unf\u00e4higkeit der politischen Klasse erkennen.<\/p>\n<p><strong>Albinfo.ch:<\/strong> Weshalb schweigt die politische Klasse? Wie kommentieren Sie die albanischen politischen Parteien in Makedonien?<\/p>\n<p><strong>Rashidi:<\/strong> Die politischen Prozesse in Makedonien gehen von einem Terrain rein ethnischer Konfrontationen in ein zunehmend institutionelles Terrain \u00fcber, wo L\u00f6sungen, die durch Abkommen offeriert werden, in Entscheiden und beh\u00f6rdlichen Schritten umgesetzt werden m\u00fcssten. Doch in dieser zweiten Phase findet sich die politische Klasse nicht zurecht, da sie Politik mehr als L\u00f6sung f\u00fcr den sozialen Status der Politiker ansieht, deren Interesse den Gewinnen, die dank der Macht m\u00f6glich sind, und nicht den Prozessen, die Verantwortungsbewusstsein erfordern, gilt.<\/p>\n<p>In der Folge wird das politische Handeln sowohl durch die Inhaber der Regierungsgewalt wie durch die Opposition abgewertet, mit unf\u00e4higen, unqualifizierten politischen Exponenten und hohen Beamten, die davon ausgehen, dass zur F\u00fchrung von Institutionen ein mehr schlecht als recht erlangtes Diplom gen\u00fcge, ohne sich bewusst zu sein, dass sie das Leben von Menschen in H\u00e4nden halten.<\/p>\n<p>Mit erschreckender Sorglosigkeit nimmt diese Klasse von Politikern ihre Aufgaben wahr, und bleibt so stecken zwischen jenem deklarativen Politisieren, in welchem die nationalistische Rhetorik vorherrscht, und dem politischen Handeln in Institutionen, wo das Gesetz herrschen sollte und wo sie sich nicht zurechtfinden. Dieser Mangel an Verantwortungsbewusstsein schafft Unzufriedenheit, und diese zeigt sich nun. Die Ver\u00e4rgerung w\u00e4chst noch mehr, wenn Erkl\u00e4rungen f\u00fcr eine st\u00e4rkere Vertretung der Albaner in den potentiell einflussreichen Positionen zu h\u00f6ren sind, wo doch deren Einfluss, unf\u00e4hig wie sie sind, gerade so ist als w\u00e4ren sie gar nicht da.<\/p>\n<p><strong>Albinfo.ch:<\/strong> Soll das Abkommen von Ohrid aufs Spiel gesetzt werden?<\/p>\n<p><strong>Rashidi:<\/strong> Abkommen in politischen Prozessen entstehen als Folge einer Krise und mit dem Ziel, jene zu \u00fcberwinden. So wie die Dinge heute stehen, k\u00f6nnten wir ein Abkommen oder auch mehrere haben, doch solange sie nicht umgesetzt werden, solange sie nicht wirken k\u00f6nnen, h\u00e4tten sie nicht den geringsten Wert. Makedonien steht vor der Herausforderung, einen Staat aufzubauen, wo Recht und Gleichstellung f\u00fcr alle gelten, auf der Basis von welchem Abkommen auch immer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Laut dem politischen Beobachter Nazim Rashidi befindet sich Makedonien auf einem schwierigen Weg des Aufbaus interethnischer Beziehungen. Seiner Ansicht nach tr\u00e4gt die politische Klasse zu dieser Situation bei.<\/p>\n","protected":false},"author":19,"featured_media":52606,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-64882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=64882"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64882\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/52606"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=64882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=64882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=64882"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=64882"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=64882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}