{"id":64838,"date":"2014-05-10T12:26:45","date_gmt":"2014-05-10T10:26:45","guid":{"rendered":""},"modified":"2014-05-14T09:03:56","modified_gmt":"2014-05-14T07:03:56","slug":"abkommen-zwischen-wirtschaftsverbanden","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/abkommen-zwischen-wirtschaftsverbanden\/","title":{"rendered":"Abkommen zwischen Wirtschaftsverb\u00e4nden"},"content":{"rendered":"<p>Am vergangen Freitag wurde in der kosovarischen Botschaft in Bern ein Abkommen zur Zusammenarbeit zwischen der Wirtschaftskammer Schweiz-Kosova und der Verbandes der albanischer Unternehmen in der Schweiz unterschrieben. Beide Verb\u00e4nde haben als Ziel, die Zusammenarbeit albanischer und Schweizer Unternehmen zu st\u00e4rken, und in Kosova sowie im restlichen albanisch-sprachigen Raum zusammen zu investieren.<\/p>\n<p>Das Abkommen wurde vom Vorsitzenden der Wirtschaftskammer Schweiz-Kosova, Stefan Sarkani und dem Vorsitzenden des Verbandes albanischer Unternehmen in der Schweiz, Fehmi Fetahu unterzeichnet. Der kosovarische Botschafter Naim Malaj hat die Unterzeichnung dieses Abkommens unterst\u00fctzt.<\/p>\n<p>Beide Wirtschaftsverb\u00e4nde wollen nun ihre Zusammenarbeit und ihre Rolle in der Erf\u00fcllung der gemeinsamen Ziele st\u00e4rken<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Abkommen wurde von Vorsitzenden der Wirtschaftskammer Schweiz-Kosova, Stefan Sarkani und dem Vorsitzenden des Verbandes albanischer Unternehmen in der Schweiz, Fehmi Fetahu unterzeichnet.<\/p>\n","protected":false},"author":40,"featured_media":51498,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1131,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-64838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-investitionen","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=64838"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64838\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/51498"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=64838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=64838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=64838"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=64838"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=64838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}