{"id":64798,"date":"2014-03-29T14:49:48","date_gmt":"2014-03-29T13:49:48","guid":{"rendered":""},"modified":"2014-03-31T09:22:56","modified_gmt":"2014-03-31T07:22:56","slug":"tradition-des-tabakanbaus-soll-in-gjilan-wiederbelebt-werden","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/tradition-des-tabakanbaus-soll-in-gjilan-wiederbelebt-werden\/","title":{"rendered":"Tradition des Tabakanbaus soll in Gjilan wiederbelebt werden"},"content":{"rendered":"<p>Entsprechende Gespr\u00e4che f\u00fchrte Teflotabaco mit den Beh\u00f6rden der Stadt Gjilan. Die Region von Gjilan schaut auf eine sehr lange Tradition des Tabakanbaus zur\u00fcck. Die Tabakbauern haben den Renditen sehr gut leben k\u00f6nnen. Nun will die Stadt diese Kultur wiederbeleben.<\/p>\n<div>Ramiz Ramadani von der Direktion f\u00fcr Landwirtschaft versprach seinem italienischen Gast Antonelo Celestini die uneingeschr\u00e4nkte Unterst\u00fctzung der Stadt Gjilan. So sollen auch neue Arbeitspl\u00e4tze geschaffen werden.<\/div>\n<div>&nbsp;<\/div>\n<div>&#8220;Wir w\u00fcnschen uns, dass jede Fl\u00e4che in Gjilan angebaut wird, auch mit Tabak. In unserer Region kultivieren wir Tabak seit 1949. Wir wollen diese Tradition wiederbeleben&#8221;, zitiert <a href=\"http:\/\/koha.net\" target=\"_blank\">koha.net<\/a> Ramiz Ramadani.<\/div>\n<div>&nbsp;<\/div>\n<div>Der Vertreter von Teflatabaco, Antonela Celestini, sagte, sein Unternehmen sei am Anbau der Tabaksorte Virginia interessiert. Teflatabaco werde den Tabakbauern alle n\u00f6tigen technischen Mitteln zur Verf\u00fcgung stellen. Und der Ankauf werde sicher sein. Man k\u00f6nne in Gjilan problemlos die Sorte Virginia anbauen, denn dies habe man auch fr\u00fcher gemacht, so Ramadani.<\/div>\n<div>&nbsp;<\/div>\n<div>Die Direktion f\u00fcr Landwirtschaft und die Vertreter von Teflatabaco und Global Pellet sind \u00fcbereingekommen, dass man dieses Jahr einige dutzende Hektar Land mit Tabak anbaut. In den kommenden Jahren sollen die angebauten Fl\u00e4chen ausgeweitet werden.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die italienische Firma Teflatabaco will in Zusammenarbeit mit der Firma Global Pellet die Tradition des Anbaus von Tabak in Gjilan wiederbeleben.<\/p>\n","protected":false},"author":40,"featured_media":50685,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1131,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-64798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-investitionen","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=64798"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64798\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/50685"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=64798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=64798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=64798"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=64798"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=64798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}