{"id":64686,"date":"2014-01-13T09:09:49","date_gmt":"2014-01-13T08:09:49","guid":{"rendered":""},"modified":"2014-03-27T12:34:13","modified_gmt":"2014-03-27T10:34:13","slug":"syrien-indoktrination-von-albanern","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/syrien-indoktrination-von-albanern\/","title":{"rendered":"Syrien: Indoktrination von Albanern"},"content":{"rendered":"<p>Eine in albanischer Sprache verfasste Botschaft \u00fcber einen Videolink, in welcher er zum Kampf gegen das Regime von Bashar al Asad aufruft, machte Lavdim S. aus Ka\u00e7anik ber\u00fchmt. Er ist einer von Dutzenden oder Hunderten Albanern, die auf der Seite der Aufst\u00e4ndischen im syrischen B\u00fcrgerkrieg k\u00e4mpfen. <\/p>\n<p>Er ruft in Allahs Namen dazu auf, auf Damaskus&#8217; Boden f\u00fcr &#8220;die Verteidigung der muslimischen Br\u00fcder und Schwestern zu k\u00e4mpfen&#8221;. Nebst Lavdim gibt es noch ein paar andere Albaner, die ebenso Videobotschaften lancierten, in welchen sie zum ideologischen Glaubenskampf (Djihad)in Syrien aufrufen.<\/p>\n<p>Die j\u00fcngste Nachricht kam vor drei Tagen aus der Gegend um Aleppo, wo ein Albaner aus Albanien erz\u00e4hlt, dass er und die muslimischen Freunde &#8220;gesund und wohlauf&#8221; seien.<br \/>Eine weitere Nachricht jedoch kam aus dem Quartier Taslixhe in Prishtina, wo F.S. (42-j\u00e4hrig) seiner Frau schreibt, dass er die letzten Minuten seines Lebens durchlebe.<br \/>Schau den Kindern gut!<\/p>\n<p>&#8220;Schau den Kindern gut, so lange war es mir beschieden zu leben, jetzt trete ich vor Gott&#8221;, schreibt der Zweiundvierzigj\u00e4hrige seiner Frau, die nun Witwe geworden ist, mit einer 9-j\u00e4hrigen Tochter und einem 7-j\u00e4hrigen Sohn, die in der kosovarischen Hauptstadt zur Schule gehen.<\/p>\n<p>In sein Haus kommen nun die Trauernden, ihr Beileid auszudr\u00fccken, nachder express gekommenen Trauernachricht, dass der Sohn als Shehid &#8211; als M\u00e4rtyrer &#8211; auf Damaskus Erde gefallen sei.<br \/>Der Jahresanfang von 2014 ist f\u00fcr die albanischen Freiwilligen, die in Syrien k\u00e4mpfen, schlimm. Innerhalb einer Woche wurde der Tod von drei Albanern best\u00e4tigt, Hetem Dema und Kijani Mujaku von Ka\u00e7anik und F.S. aus Prishtina. M\u00f6glicherweise wurden noch einige weitere albanische Freiwillige in der Gegend von Idlib und Aleppo get\u00f6tet.<br \/>Die albanischen Freiwilligen verloren ihr Leben bei Zusammenst\u00f6ssen mit einheimischen Rebellen und nicht mit Truppen des Pr\u00e4sidenten Bashar Al-Assad.<br \/>Laut Medien in Kosova sind jedoch m\u00f6glicherweise noch einige weitere Albaner umgebracht worden, im Nordwesten Syriens, da der Konflikt sich in der Gegend ereignete, wo die Albaner konzentriert waren.<br \/>&nbsp;<br \/><strong>Wie viele albanische Freiwillige k\u00e4mpfen in Syrien?<\/strong><\/p>\n<p>Die kosovarischen Beh\u00f6rden haben keine Statistik, wie viele Kosovaren sich am B\u00fcrgerkrieg in Syrien beteiligen. Die Angaben variieren von 20 bis zu 800 Albanern. Die Angeh\u00f6rigen des Prishtinasers, der gestern get\u00f6tet wurde, sagen, dass ihr Sohn gesagt habe, es bef\u00e4nden sich ungef\u00e4hr 150 Albaner in Aleppo, wo auch die letzte Offensive stattgefunden hatte. Aussenminister Enver Hoxhaj dementiert jedoch diese Zahl und sagt, dass sich in Syrien nicht mehr als 30 kosovarische Freiwillige aufhielten.<\/p>\n<p>&#8220;Das Ph\u00e4nomen der Teilnahme von B\u00fcrgern Kosovas ist isoliert, klein, und so wie in allen anderen Staaten der EU, so besteht es auch in einigen Staaten des Balkans, leider auch in Kosovo. Die in diesen Tagen in den Medien zirkulierende Zahl von angeblich 150 Personen ist nicht korrekt. Es m\u00f6gen 20 bis 30 Personen sein&#8221;, sagte Hoxhaj.<\/p>\n<p>Vor einigen Monaten meldete die Agentur FarsNews, dass sich 800 albanische Freiwillige (aus Albanien, Makedonien und Kosova)der Freien Syrischen Armee angeschlossen h\u00e4tten. Im direkten Kampfgeschehen wurden mehr als 10 Albaner get\u00f6tet. An die Orte des Kampfeinsatzes geschickt werden die Freiwilligen internationalen Medien zufolge nach milit\u00e4rische Training in der T\u00fcrkei.<\/p>\n<p>Die Beh\u00f6rden in Kosovo sind besorgt dar\u00fcber, dass M\u00e4nner aus Kosovo nach Syrien gehen und dort im Namen des Djihad k\u00e4mpfen. Prishtina muss sich \u00fcberlegen, wie es gegen diese Leute vorgehen soll, vor allem nach deren R\u00fcckkehr in die Heimat, da sie eine dauernde Bedrohung f\u00fcr die B\u00fcrger Kosovos sein k\u00f6nnen.<\/p>\n<p>Der stellvertretende Regierungschef und Justizminister Hajredin Ku\u00e7i erkl\u00e4rte, dass die Angelegenheit nun in der Regierung behandelt werde, auch wenn es keinen konkreten Beschluss gebe, zitiert Z\u00ebri.<\/p>\n<p><strong>Die Freiwilligen sollen strafrechtlich verfolgt werden!<\/strong><\/p>\n<p>Der kosovarische Aussenminister Enver Hoxhaj sagte, es m\u00fcssten Gesetzes\u00e4nderungen erfolgen, um eine solche Teilnahme zu verhindern. Er sagte, in einigen L\u00e4ndern w\u00fcrden solchen Personen die Staatsb\u00fcrgerschaft genommen oder sie w\u00fcrden strafrechtlich verfolgt.<\/p>\n<p>Auch die kosovarische Polizei verf\u00fcgt \u00fcber keine Informationen dar\u00fcber, wie viele Kosovaren an den K\u00e4mpfen in Syrien teilnehmen.<\/p>\n<p>Der offizielle Polizeisprecher, Brahim Sadriu, sagte jedoch, dass die Polizei gest\u00fctzt auf ihren gesetzlichen Auftrag Informationen \u00fcber Entwicklungen, die eine Bedrohung der Sicherheit in der Republik Kosovo sein k\u00f6nnten, sammelt und analysiert.<\/p>\n<p>&#8220;Aufgrund verschiedener Informationen rechnen wir nicht mit einer grossen Zahl kosovarischer B\u00fcrger im Krieg in Syrien. Wir haben auch Informationen \u00fcber einige Zur\u00fcckgekehrte&#8221;, sagte Sadriu.<\/p>\n<p>Albinfo.ch fragte Politologen, aber auch Gottesm\u00e4nner nach ihrer Meinung zu den Syrieng\u00e4ngern. Sie betrachten die Teilnahme von Freiwilligen im syrischen B\u00fcrgerkrieg als Fehler. Gem\u00e4ss den Glaubensvertretern hat dieser Krieg nichts mit dem heiligen Glaubenskrieg zu tun.<br \/>&nbsp;<br \/><strong>Der Krieg in Syrien hat nichts mit dem Djihad zu tun&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &nbsp;<br \/>&nbsp;<br \/>Xhabir Hamiti war Pr\u00e4sident des Rats der Islamischen Gemeinschaft Kosovas, und ist bekannt als Theologe, der den traditionellen liberalen Islam unterst\u00fctzt. Er sagt, die gesamte kosovarische politische F\u00fchrungsklasse, aber auch die Glaubensf\u00fchrer, m\u00fcssten einstimmig dagegen eintreten, dass Leute aus Kosova in den, wie er ihn nennt, monstr\u00f6sen Konflikt in Syrien gehen.<\/p>\n<p>&#8220;Es gibt keinerlei islamische Grundlage, dorthin zu gehen, denn es ist ein Konflikt zwischen vielen Fraktionen und Fronten des gleichen Volkes &#8230; Diejenigen, die diesen Krieg einen heiligen Krieg nennen, wissen es entweder aufgrund ihrer Ignoranz und blinden Indoktrinierung nicht besser, oder sie wissen es, aber verwenden absichtlich diesen Ausdruck&#8221;, erkl\u00e4rte Hamiti.<\/p>\n<p>Der heilige Krieg hat, wie er sagte, Regeln und Prinzipien, die in diesem Krieg, wie er sagte, v\u00f6llig fehlen. Er fordert die Imame in Kosovo auf, w\u00e4hrend der Predigten in den Moscheen die Leute dazu aufzurufen, nicht Teil eines Konflikts von Fraktionen und Fronten zu werden.<br \/>&nbsp;<br \/>Auch die Islamische Gemeinschaft von Kosova reagierte erneut im Zusammenhang mit den Kosovaren in Syrien, vor allem nach dem Tod von einigen der Ihren.<br \/>&nbsp;<br \/>Oberimam Sabri Bajgora rief alle kosovarischen K\u00e4mpfer dazu auf, die Front zu verlassen und nach Kosova zur\u00fcckzukehren. &#8220;Dieser Krieg hat seinen Kompass verloren. Anf\u00e4nglich war er ein reiner Befreiungskrieg und freiheitsliebend. Aber das gilt nicht mehr. Ich rufe alle unsere S\u00f6hne dort auf, nach Kosova zur\u00fcckzukehren&#8221;, appellierte Bajgora.<\/p>\n<p>Fadil Lepaja, Direktor des Zentrums f\u00fcr balkanische Studien in Prishtina, sagt, dass der Gang von Freiwilligen nach Syrien&nbsp; nach deren R\u00fcckkehr in die Heimat nachtr\u00e4gliche Folgen haben werde. Laut ihm schaffen diese Freiwilligen internationale Verbindungen mit muslimischen Br\u00fcdern, die sp\u00e4ter ihre Verbindungen auch in den Balkan und anderswo ausbreiten werden.<\/p>\n<p><strong>Kosova an der Kreuzung der Zivilisationen<\/strong><br \/>&nbsp;<br \/>Der Kampf gegen solche internationalen Engagements&nbsp; wird in den K\u00f6pfen der Menschen gef\u00fchrt und gewonnen, und diesbez\u00fcglich befinden wir uns als Gesellschaft an der Kreuzung der Zivilisationen&#8221;, sagt Lepaja zu albinfo.ch unter anderem.<br \/>Es sei Zeit, dass&nbsp; die kosovarischen Intellektuellen ein albanisches Modell des modernen Islam schaffen sollten, welches mit Demokratie und b\u00fcrgerlichen Freiheiten vereinbar sei, und nicht ineffiziente Modelle beg\u00fcnstigen, die auch unter uns immer mehr den religi\u00f6sen Extremismus st\u00e4rken.&#8221;<\/p>\n<p>&#8220;Hier spielt auch der Staat eine Rolle, sei es mit moralischer und materieller Unterst\u00fctzung, und nur in letzter Konsequenz mit notwendiger gesellschaftlicher Repression, um das demokratische System zu verteidigen&#8221;, meint Lepaja.<\/p>\n<p>Im \u00dcbrigen berichten die Medien, dass in Syrien einige Gruppen von Aufst\u00e4ndischen wirkten, die auf den Sturz von Bashar Al Asad hinarbeiteten. Nebst der Freien Syrischen Armee gibt es drei weitere Kampfgruppen: die revolution\u00e4re Opposition, die von Anfang an den Sturz von Asad wollte; Al Nusra, eine der terroristischen Al Kaida nahestehende Organisation; und &#8220;Der Islamische Staat des Irak und der Levante&#8221;, eine von Al Nusra abgespaltete Gruppe. Die j\u00fcngsten F\u00e4lle von mehreren get\u00f6teten Albanern sollen sich mutmasslich bei Zusammenst\u00f6ssen von Gruppen untereinander ereignet haben. Die albanischen Freiwilligen sollen, gem\u00e4ss Berichten, in zwei Gruppen geteilt sein, in Aleppo und Idliba.<br \/>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Innert einer Woche kamen drei kosovarische Freiwillige im B\u00fcrgerkrieg in Syrien ums Leben. Die Teilnahme von Freiwilligen bereitet den Beh\u00f6rden in Prishtina Sorgen; sie fordern ein Verbot solcher Teilnahme<\/p>\n","protected":false},"author":19,"featured_media":49238,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-64686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=64686"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64686\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/49238"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=64686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=64686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=64686"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=64686"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=64686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}