{"id":64666,"date":"2013-12-25T20:11:11","date_gmt":"2013-12-25T19:11:11","guid":{"rendered":""},"modified":"2014-01-20T12:12:10","modified_gmt":"2014-01-20T10:12:10","slug":"das-jahr-der-wirtschaftlichen-stagnation","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/das-jahr-der-wirtschaftlichen-stagnation\/","title":{"rendered":"Das Jahr der wirtschaftlichen Stagnation"},"content":{"rendered":"<p>Auch das Jahr 2013 ist ein Jahr der schlechten sozialen und wirtschaftlichen Lage in Kosova gewesen &#8211; die extreme Armut mit 10% und die Arbeitslosigkeit mit 30% weiterhin auf sehr hohem Niveau bleiben. Auch die Wirtschafts insgesamt &nbsp;verzeichnet unzureichende Wachstumsraten.<\/p>\n<div>&nbsp;<\/div>\n<div>Wirtschaftsexperten sagen, dass die niedrigen Auslandsinvestitionen, die B\u00fcrokratie sowie die hohe Korruption auch in diesem Jahr die Hauptprobleme sind, mit denen Kosova zu k\u00e4mpfen hat. Das stockenden Reformtempo und die hohen Kreditzinsen haben die Entwicklung der Wirtschaft gehindert.<\/div>\n<div>&nbsp;<\/div>\n<div>Allein die Fertigstellung der Autobahn Prishtina-Morina k\u00f6nnte man als wirtschaftlichen Erfolg des Jahres 2013 verbuchen. Auch das Energieabkommen zwischen Albanien und Kosova hat eine beachtliche Bedeutung.<\/div>\n<div>&nbsp;<\/div>\n<div>Das fehlen einer wirtschaftlichen Strategie und der Mangel an wirtschaftspolitischen Instrumenten, die organisierte Kriminalit\u00e4t sind weitere Schwachpunkte der kosovarischen Wirtschaft, sagt Wirtschaftsprofessor Musa Limani.<\/div>\n<div>&nbsp;<\/div>\n<div>Auch in diesem Jahr zeichnet sich unsere Wirtschaft durch einen sehr hohen Zahlungsbilanzdefizit aus. Zudem haben wir mit hoher Kriminalit\u00e4t und Schmuggel zu k\u00e4mpfen, sowie hohe Arbeitslosigkeit und Armut und einen R\u00fcckgang des Lebensstandards.<\/div>\n<div>&nbsp;<\/div>\n<div>&#8220;Das hohe Handelsbilanzdefizit und die Tatsache, dass wir 60% unser Steuereinnahmen an den Grenzen generieren, zeigen, dass wir ein sehr niedriges Niveau der Entwicklung unseres produzierenden Gewerbes haben. Die wirtschaftliche Theorie und Praxis sagen aber, dass das produzierende Gewerbe die Hauptquelle der Entwicklung und des Wachstums ist. Und nicht der Handel &#8211; der Handel ist eine Dienstleistung, sagt Limani.<\/div>\n<div>&nbsp;<\/div>\n<div>Das Wirtschaftswachstum von 3% ist f\u00fcr L\u00e4nder wie Kosova unzureichend, sagt Agron Demi vom Institut GAP.<\/div>\n<div>&nbsp;<\/div>\n<div>&#8220;Im Jahr 2011 nahm sich Regierung vor, ein j\u00e4hrliches Wirtschaftswachstum von 7% bis 8%, damit sich dies im Endeffekt sich positiv auf den Arbeitsmarkt wirkt. Dies ist aber kl\u00e4glich gescheitert&#8221;, so Demi.<\/div>\n<div>&nbsp;<\/div>\n<div>Der Verkauf von \u00f6ffentlichen Unternehmen ist wohl der einzige Plan der Regierung gewesen, um Wachstum zu generieren. Einige Verkaufsvorhaben sind aber gescheitert &#8211; darum konnte man nicht das n\u00f6tige Wachstum generieren.<\/div>\n<div>&nbsp;<\/div>\n<div>Die jungen Menschen bleiben weiterhin sehr entt\u00e4uscht von diesem negativen Trend. Mehrere Umfragen zeigen, ein Grossteil der jungen Leute will das Land verlassen.<\/div>\n<div class=\"yj6qo ajU\">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Niedrige Auslandsinvestitionen, B\u00fcrokratie und Korruption sind die Hauptprobleme, an denen die kosovarische Wirtschaft leidet. Die Arbeitslosigkeit verharrt weiterhin auf sehr hohe 30%.<\/p>\n","protected":false},"author":40,"featured_media":48938,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-64666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=64666"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64666\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/48938"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=64666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=64666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=64666"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=64666"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=64666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}