{"id":64642,"date":"2013-11-28T13:32:54","date_gmt":"2013-11-28T12:32:54","guid":{"rendered":""},"modified":"2014-01-21T12:13:15","modified_gmt":"2014-01-21T10:13:15","slug":"verifikationsmission-in-kosova","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/verifikationsmission-in-kosova\/","title":{"rendered":"Verifikationsmission in Kosova"},"content":{"rendered":"<p><span style=\"color: #000000;\">Eine Verifikationsmission der EU-Kommission kommt Anfang Dezember nach Kosova, um die Fortschritte des Landes im Prozess der Visaliberalisierung zu pr\u00fcfen.<\/span><\/p>\n<p><span style=\"color: #000000;\">Die Regierung betont, dass sie die Hausaufgaben bereits erledigt hat und dass sie eine positives Ergebnis erwartet. Premierminister Thaci sagt, die Mission sei wichtig und rief die entsprechende Regierungskommission auf, die letzten Vorbereitungen f\u00fcr die Verifikationsmission zu treffen.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201eEs ist wichtig, dass wir ein gutes, positives Ergebnis haben, das auf die Fakten beruht. Wir sind uns alle \u00fcber die Wichtigkeit dieses Prozesses f\u00fcr unser Land bewusst\u201c, so Thaci. Die Mission werde die Themengebiete, wie die R\u00fcckf\u00fchrung, Reintegration, Sicherheit der Reisedokumente, Migration und Asyl pr\u00fcfen.<\/span><\/p>\n<p><span style=\"color: #000000;\">Die EU und Kosova seien sehr sp\u00e4t dran, was den Prozess der Liberalisierung angeht, sagt Shenoll Muharremi, Experte f\u00fcr EU-Fragen. Beide Seiten m\u00fcssen weitere Anstrengungen unternehmen, damit dieser Prozess besser vorankommt. Die Verifikationsmission der EU werde in einigen Bereichen schon positive Entwicklungen sehen. Allerdings gibt es praktisch keine Verbesserung im Bereich der Rechtsstaatlichkeit.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u201eDie EU muss eine verst\u00e4rkt proaktives Handeln zutage legen. Durch verschiedene Missionen und Fortschrittsberichte kann die EU einen gewissen Druck auf die Institutionen des Landes aus\u00fcben, damit sie Reformen rasch umsetzen\u201c, sagt Muharremi.<\/span><\/p>\n<p><span style=\"color: #000000;\">Tats\u00e4chlich hat Kosova eine gute Entwicklung in einigen Bereich hingelegt. Doch die hohe Korruption, mangelnde Rechtsstaatlichkeit und die Asylsuche bleiben weiterhin schwache der kosovarischen Gesellschaft.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine Verifikationsmission kommt Anfang Dezember nach Kosova, um den Fortschritt des Landes im Prozess der Visaliberalisierung zu pr\u00fcfen<\/p>\n","protected":false},"author":40,"featured_media":48390,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-64642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=64642"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64642\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/48390"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=64642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=64642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=64642"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=64642"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=64642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}