{"id":64610,"date":"2013-10-24T17:03:02","date_gmt":"2013-10-24T15:03:02","guid":{"rendered":""},"modified":"2014-01-21T13:29:48","modified_gmt":"2014-01-21T11:29:48","slug":"kreditfinanzierung-nur-gegen-hohe-kreditzinsen","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/kreditfinanzierung-nur-gegen-hohe-kreditzinsen\/","title":{"rendered":"Kreditfinanzierung nur gegen Hohe Kreditzinsen"},"content":{"rendered":"<p><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\">Die Regierung hat keine Antwort auf die Frage, warum Unternehmen einen eher schwierigen Zugang zu Geldern haben; Unternehmensverb\u00e4nde und Wirtschaftsexperten bem\u00e4ngeln den fehlenden wirtschaftlichen Sachverstand der Regierung.<\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\">Der erschwerte Zugang zum Kapital wurde im Fortschrittsbericht der EU Kommission f\u00fcr Kosovo als einer der Gr\u00fcnde f\u00fcr die mangelnde Entwicklung der Unternehmen im Land erw\u00e4hnt.<\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\">Es fehle an seri\u00f6sen Projekten, konkreten Anstrengungen und \u00fcberhaupt an einer Strategie in dieser Richtung, sagen Wirtschaftsexperten. Auf der anderen Seite will das Finanzministerium keine Stellung beziehen, warum man es bisher nicht geschafft hat, entsprechende Institutionen und Mechanismen, die Unternehmen in dieser Hinsicht helfen w\u00fcrden, auf die Beine zu stellen, schreibt Kosova sot.<\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\">Da eine Entwicklungsbank oder ein \u00e4hnlicher Kreditgeber fehlt, sind Unternehmen gezwungen, Kredite zu sehr hohen Zinsen aufzunehmen, wenn sie ihr Gesch\u00e4ft finanzieren und weiter wachsen wollen. Vielfach verschulden sie sich hoch und m\u00fcssen Insolvenz anmelden.<\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"font-family: Calibri;\">Wie kosovarische Zentralbank meldet, sind Kreditzinsen in Kosovo im Jahr 2012 zur\u00fcckgegangen, w\u00e4hrend Einlagezinsen einen kleinen Anstieg verzeichnet haben. Allerdings sind Kreditzinsen im j\u00fcngsten Balkanstaat die h\u00f6chsten in der Region.<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um ihre Gesch\u00e4fte auszuweiten oder ihr Wachstum zu finanzieren, m\u00fcssen Unternehmen Kredite zu sehr hohen Zinsen aufnehmen<\/p>\n","protected":false},"author":40,"featured_media":47696,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-64610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=64610"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64610\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/47696"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=64610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=64610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=64610"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=64610"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=64610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}