{"id":64607,"date":"2013-10-21T15:33:21","date_gmt":"2013-10-21T13:33:21","guid":{"rendered":""},"modified":"2014-01-23T20:22:10","modified_gmt":"2014-01-23T18:22:10","slug":"deutsche-filme-in-9-stadten-in-mazedonien","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/deutsche-filme-in-9-stadten-in-mazedonien\/","title":{"rendered":"Deutsche Filme in 9 St\u00e4dten in Mazedonien"},"content":{"rendered":"<p>In neuen mazedonischen St\u00e4dten wurden deutsche Filme unter dem Motto \u201eIch liebe Film\u201c aufgef\u00fchrt: Skopje, Shtip, Tetova, Prilep, Veles, Manastir, Strumic\u00eb, Kavadar und zum ersten Mal in diesem Jahr auch in Kumanovo.<\/p>\n<p>Neue deutsche Filme thematisieren das Reale, aber auch das M\u00f6gliche und Erw\u00fcnschte. Deutsche Filme gehen in die Tiefe, bieten kompromisslose Konfrontationen auf viele Ebenen, die zum Kernthema f\u00fchren, schreibt DW. Solche Filme machen einem klar, dass nicht alles weiss ist, und dass man sich mit der Realit\u00e4t konfrontiert und sich den Problemen des&nbsp; Lebens sollte.<\/p>\n<p>Die Auswahl der Filme f\u00fcr die 9. Ausgabe wurde sehr sorgf\u00e4ltig gemacht, sodass man Filme aus mehreren Genres&nbsp; gezeigt werden k\u00f6nnen, sagt Helga Teipel, Kultur-Attach\u00e9 in der deutschen Botschaft in Skopje.<\/p>\n<p>\u201eAlle gezeigten Filme wurden von deutschen Regisseuren gedreht, vielen davon sind junge Filmschaffende. Wir sprechen nicht \u00fcber Serien amerikanischer Art \u2013 es geht um Filme, die in deutschen Kinos gezeigt worden sind. Im Programm standen Kom\u00f6dien, Dramen, Kinder- und Dokumentarfilme\u201c, so Helga Teipel.<\/p>\n<p>Die deutsche Botschafterin Gudrun Steinacher betont, dass das Ziel des Festivals ist es, die Kinokultur in Mazedonien und die deutsch-mazedonische Freundschaft zu f\u00f6rdern. Die hohen Zuschauerzahlen zeigen, dass die Kinokultur eine doch beachtliche Resonanz hat.<\/p>\n<p>F\u00fcr die n\u00e4chste Ausgabe und das 10. Jubil\u00e4um k\u00fcndigte die Botschaft, im Programm mehr St\u00e4dte aufzunehmen, wo die Filme gezeigt worden. Zudem plant man mehrere Workshops; auch sollen deutsche Filmschaffende nach Mazedonien reisen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der deutsche Filmfestival in Mazedonien ist nunmehr zu einem traditionellen Festival geworden<\/p>\n","protected":false},"author":19,"featured_media":47640,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-64607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=64607"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64607\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/47640"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=64607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=64607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=64607"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=64607"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=64607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}