{"id":64584,"date":"2013-09-15T13:10:20","date_gmt":"2013-09-15T11:10:20","guid":{"rendered":""},"modified":"2014-01-23T20:45:33","modified_gmt":"2014-01-23T18:45:33","slug":"menschenrechtsverletzungen-in-kosova","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/menschenrechtsverletzungen-in-kosova\/","title":{"rendered":"Menschenrechtsverletzungen in Kosova"},"content":{"rendered":"<p>Samir Kurteshi erachtet als objektiv die Einsch\u00e4tzungen internationaler Organisationen, wonach in Kosova in vielen F\u00e4lle die Menschenrechte verletzt werden. Roma, Egypter und Ashkali werden am meisten benachteiligt. Die Regierung in Prishtina gehe nicht auf die Empfehlungen des Ombudsmanns ein, sagt er f\u00fcr Radio Freies Europa. Der Ombudsmann werde einfach ignoriert.<\/p>\n<div>&nbsp;<\/div>\n<div>&#8220;Die Regierung verh\u00e4lt sich weitgehend ignorierend gegen\u00fcber unseren Vorschl\u00e4gen. Das Parlament macht da eine Ausnahme, da es eine heterogene Zusammensetzung hat. Und so bleibt die Lage der Menschenrechte in Kosovo dennoch sehr schwer&#8221;, sagt Kurteshi.<\/div>\n<div>&nbsp;<\/div>\n<div>Die Einsch\u00e4tzungen von Freedom House, Human Rights Watch bez\u00fcglich der schlechten Lage der Menschenrechte in Kosova betrachtet Kurteshi als objektiv. &#8220;Sicherlich kann es einige Unterschiede in einigen Details geben, doch ich w\u00fcrde die Einsch\u00e4tzung dieser internationalen Organisationen jederzeit bejahen&#8221;, so Kurteshi, ehemaliger politischer Gefangener in Ex-Jugoslavien.<\/div>\n<div>&nbsp;<\/div>\n<div>Am meisten Menschenrechtsverletzungen sind bei der Staatsanwaltschaft zu beobachten, wegen Fahrl\u00e4ssigkeit, Korruption und Faktenmanipulation. In Kosova herrsche keine stabilisierte Gerechtigkeit, weder gesellschaftliche noch institutionelle.<\/div>\n<div>&nbsp;<\/div>\n<div>Schon seit Jahren prangert der Ombudsmann die Missst\u00e4nde an, vor allem in der Justiz, aber auch bei verschiedenen Regierungsstellen.<\/div>\n<div>&nbsp;<\/div>\n<div>&#8220;Die Roma, Ashkalinj und Egypter geh\u00f6ren zu den Minderheiten in Kosova, die am meisten benachteiligt sind, wenn man die allgemeine wirtschaftliche und politische Lage analysiert.&#8221; Es gebe zwar keine offene Diskriminierung, doch die allgemeine Lage dr\u00e4nge sie an den Rand der Gesellschaft.<\/div>\n<div>&nbsp;<\/div>\n<div>Auch die LGBT-Community sei in der letzten Zeit Ziele vieler Angriffe von Extremisten. &nbsp;&#8220;Die Rentner sind in einer sehr schwierigen Lage und geh\u00f6ren zu den diskriminierten. Am schlechtesten stehen aber die Arbeitslosen und die Armen da&#8221;, so Kurteshi.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sami Kurteshi, Ombudsmann in Kosova sagte, Roma, Egypter und Ashkali sind Minderheiten, die am meisten benachteiligt werden.<\/p>\n","protected":false},"author":19,"featured_media":46889,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-64584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=64584"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/64584\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/46889"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=64584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=64584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=64584"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=64584"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=64584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}