{"id":572128,"date":"2022-07-01T18:15:10","date_gmt":"2022-07-01T16:15:10","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=572128"},"modified":"2022-07-01T18:07:07","modified_gmt":"2022-07-01T16:07:07","slug":"der-chef-der-armee-auf-truppenbesuch-im-kosovo","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/der-chef-der-armee-auf-truppenbesuch-im-kosovo\/","title":{"rendered":"Der Chef der Armee auf Truppenbesuch im Kosovo"},"content":{"rendered":"<div class=\"contentHead\"><\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p>Am 30. Juni und 1. Juli 2022 besucht der Chef der Armee, Korpskommandant Thomas S\u00fcssli, wie in jedem Jahr die SWISSCOY im Kosovo.<\/p>\n<p>Mit seinem Truppenbesuch will sich der Chef der Armee einen Einblick in die aktuell zwar ruhige, aber nach wie vor instabile Sicherheitslage im Kosovo verschaffen und gleichzeitig einen Eindruck von den vielf\u00e4ltigen Leistungen gewinnen, die die Schweizer Angeh\u00f6rigen des 46. SWISSCOY-Kontingents erbringen.<\/p>\n<p>Vorgesehen ist zudem ein bilaterales Gespr\u00e4ch mit dem Kommandanten der KFOR, dem ungarischen Generalmajor Ferenc Kaj\u00e1ri.<\/p>\n<p>Korpskommandant Thomas S\u00fcssli wird auf seinem Besuch von der Nidwaldner Regierungsr\u00e4tin Karin Kayser-Frutschi und vom Waadtl\u00e4nder Nationalrat Fran\u00e7ois Pointet begleitet.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Korpskommandant Thomas S\u00fcssli wird auf seinem Besuch von der Nidwaldner Regierungsr\u00e4tin Karin Kayser-Frutschi und vom Waadtl\u00e4nder Nationalrat Fran\u00e7ois Pointet begleitet<\/p>\n","protected":false},"author":4,"featured_media":416116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1188,3952,1129,1140],"tags":[],"vendi":[],"content_country":[29888,31836,31837],"class_list":["post-572128","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-shkurt-ch-de","category-kosova-de","category-ch-balkan","category-leben-in-der-schweiz","content_country-zvicer","content_country-austria-de","content_country-germany-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/572128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=572128"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/572128\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/416116"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=572128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=572128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=572128"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=572128"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=572128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}