{"id":389565,"date":"2020-06-26T12:48:18","date_gmt":"2020-06-26T10:48:18","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=389565"},"modified":"2020-06-26T12:48:18","modified_gmt":"2020-06-26T10:48:18","slug":"coronavirus-arbeitskraefte-aus-drittstaaten-koennen-wieder-zugelassen-werden","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/coronavirus-arbeitskraefte-aus-drittstaaten-koennen-wieder-zugelassen-werden\/","title":{"rendered":"Coronavirus: Arbeitskr\u00e4fte aus Drittstaaten k\u00f6nnen wieder zugelassen werden"},"content":{"rendered":"<div class=\"contentHead\"><\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p>Die Einreisebeschr\u00e4nkungen an den Grenzen zu allen Schengen-Staaten sind am 15. Juni 2020 aufgehoben worden. Seither sind die Binnengrenzen zwischen den Schengen-Staaten und der Schweiz wieder ohne Kontrollen ge\u00f6ffnet. Weiter gilt seit dem 15. Juni 2020 mit allen EU\/EFTA-Staaten sowie dem Vereinigten K\u00f6nigreich ebenfalls wieder die volle Personenfreiz\u00fcgigkeit.<\/p>\n<h3>Zulassungen f\u00fcr Tourismus- oder Kulturbranche wieder m\u00f6glich<\/h3>\n<p>Unter Ber\u00fccksichtigung der j\u00fcngsten pandemischen Entwicklung hebt der Bundesrat in einem n\u00e4chsten Schritt ab dem 6. Juli die Einschr\u00e4nkungen bei der Zulassung von Arbeitskr\u00e4ften aus Drittstaaten auf: Bewilligungen werden im Rahmen des Kontingentsystems wie vor der Corona-Krise erteilt. Damit sollen unter anderem Zulassungen zur Erwerbst\u00e4tigkeit im Tourismus- oder Kulturbereich sowie f\u00fcr Weiterbildungen mit Erwerbst\u00e4tigkeit \u2013 beispielsweise Au-pairs, landwirtschaftliche Praktikanten oder Jugendaustausch \u2013 wieder erm\u00f6glicht werden.<\/p>\n<p>Ebenfalls per 6. Juli 2020 werden die Beschr\u00e4nkungen f\u00fcr Aufenthalte \u00fcber 90 Tage f\u00fcr die nichterwerbst\u00e4tigen Drittstaatsangeh\u00f6rigen \u2013 zum Beispiel Rentner \u2013 aufgehoben. Ab 6. Juli bearbeiten die Kantone solche Gesuche wieder im Rahmen der ordentlichen ausl\u00e4nderrechtlichen Bestimmungen.<\/p>\n<p>Gest\u00fctzt auf das Epidemiengesetz und je nach pandemischer Entwicklung in einzelnen Drittstaaten bleiben grenzsanitarische Massnahmen nach wie vor m\u00f6glich f\u00fcr alle Personen, die aus diesen Staaten in die Schweiz einreisen.<\/p>\n<h3>Vollst\u00e4ndige Lockerung in Abstimmung mit den anderen Schengen-Staaten<\/h3>\n<p>Von den Lockerungen ausgenommen bleibt weiterhin die Einreise von Drittstaats-angeh\u00f6rigen f\u00fcr Kurzaufenthalte von weniger als 90 Tagen \u2013 beispielsweise f\u00fcr Ferienaufenthalte, kurzfristige Ausbildungen, medizinische Behandlungen oder nicht dringende gesch\u00e4ftliche Besprechungen. Wie bis anhin sind derzeit solche Reisen nur in F\u00e4llen \u00e4usserster Notwendigkeit zul\u00e4ssig. Die Aufhebung dieser letzten Einreisebeschr\u00e4nkungen will die Schweiz nach M\u00f6glichkeit in Abstimmung mit den anderen Schengen-Staaten vollziehen. Je nach Entwicklung der epidemiologischen Situation in diesen Drittstaaten soll der Einreisestopp sukzessive und m\u00f6glichst koordiniert aufgehoben werden \u2013 unter Umst\u00e4nden gegen\u00fcber gewissen Staaten auch bereits vor dem 6. Juli. F\u00fcr die Koordination wird die EU-Kommission eine Liste mit Drittstaaten regelm\u00e4ssig aktualisieren. Das EJPD wird die Einreisevorschriften nach R\u00fccksprache mit dem EDI und dem EDA entsprechend auch f\u00fcr die Schweiz schrittweise anpassen.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr die Einreise in die Schweiz gab es seit dem 11. Mai verschiedene Lockerungsschritte. In einem weiteren Schritt hebt der Bundesrat nun per 6. Juli 2020 die corona-bedingten Beschr\u00e4nkungen bei der Zulassung von Arbeitskr\u00e4ften aus Drittstaaten \u2013 also Staaten ausserhalb der EU und der EFTA \u2013 vollst\u00e4ndig auf. Auch die Gesuche nicht erwerbst\u00e4tiger Drittstaatsangeh\u00f6riger \u2013 zum Beispiel Rentner \u2013 sollen ab diesem Datum wieder gem\u00e4ss den \u00fcblichen Kriterien von den Kantonen bearbeitet werden. Allerdings wird es Drittstaatsangeh\u00f6rigen noch nicht m\u00f6glich sein, f\u00fcr Ferien in die Schweiz zu reisen: Einreisen f\u00fcr bewilligungsfreie Aufenthalte von weniger als 90 Tagen werden weiterhin nur in F\u00e4llen \u00e4usserster Notwendigkeit bewilligt<\/p>\n","protected":false},"author":4,"featured_media":265791,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22520,24006,1140],"tags":[],"vendi":[],"content_country":[31836,31837],"class_list":["post-389565","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coronavirus-minute-fuer-minute","category-lajme-jeta-ne-zvicer-de","category-leben-in-der-schweiz","content_country-austria-de","content_country-germany-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/389565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=389565"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/389565\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/265791"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=389565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=389565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=389565"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=389565"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=389565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}