{"id":322233,"date":"2019-10-25T20:40:11","date_gmt":"2019-10-25T18:40:11","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=322233"},"modified":"2019-10-27T21:49:34","modified_gmt":"2019-10-27T20:49:34","slug":"senkung-von-arzneimittelpreisen-fuehrt-2019-zu-einsparungen-von-100-millionen-franken","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/senkung-von-arzneimittelpreisen-fuehrt-2019-zu-einsparungen-von-100-millionen-franken\/","title":{"rendered":"Senkung von Arzneimittelpreisen f\u00fchrt 2019 zu Einsparungen von 100 Millionen Franken"},"content":{"rendered":"<p>Das BAG pr\u00fcft seit 2017 j\u00e4hrlich bei einem Drittel der Arzneimittel der Spezialit\u00e4tenliste, ob sie wirksam, zweckm\u00e4ssig und wirtschaftlich sind. Im Jahr 2019 hat das BAG das letzte Drittel \u00fcberpr\u00fcft; dabei handelt es sich unter anderem um Arzneimittel aus den Bereichen Herz und Kreislauf, Infektiologie und Ophthalmologie. Bisher hat das BAG bei 257 der 478 \u00fcberpr\u00fcften Originalpr\u00e4parate Preissenkungen verf\u00fcgt (54 Prozent). Bei den restlichen Pr\u00e4paraten war keine Preissenkung notwendig; diese sind im Vergleich zu den Referenzl\u00e4ndern und im Vergleich zu anderen Arzneimitteln weiterhin wirtschaftlich. Bei 10 Originalpr\u00e4paraten ist noch offen, ob die Preissenkungen umgesetzt werden k\u00f6nnen, da Beschwerden angek\u00fcndigt sind.<\/p>\n<p>Gleichzeitig mit den Originalpr\u00e4paraten wurden Generika und Co-Marketing-Arzneimittel \u00fcberpr\u00fcft. F\u00fcr 178 (57%) von 313 dieser Arzneimittel f\u00fchrt die \u00dcberpr\u00fcfung ebenfalls zu einer Preissenkung. Dieses Jahr wurden keine Biosimilars \u00fcberpr\u00fcft.<\/p>\n<p>Die diesj\u00e4hrige \u00dcberpr\u00fcfung ist bei rund 90 Prozent der Arzneimittel abgeschlossen und die Preissenkungen werden wie angek\u00fcndigt per 1. Dezember 2019 umgesetzt. Die \u00dcberpr\u00fcfung der restlichen Arzneimittel kann mehrheitlich auf den 1. Februar 2020 abgeschlossen werden.<\/p>\n<p>N\u00e4chstes Jahr beginnt die dreij\u00e4hrliche \u00dcberpr\u00fcfungsrunde von neuem. \u00dcberpr\u00fcft werden wie bereits f\u00fcr das Jahr 2017 die Preise von Arzneimitteln unter anderem aus den Bereichen Gastroenterologie und Onkologie.<\/p>\n<p>Aufteilung in therapeutische Gruppen<br \/>\nDas BAG \u00fcberpr\u00fcft alle drei Jahre die Aufnahmebedingungen und insbesondere die Preise der Arzneimittel der Spezialit\u00e4tenliste. Auf dieser sind all jene Arzneimittel aufgef\u00fchrt, die von der obligatorischen Krankenpflegeversicherung (OKP) verg\u00fctet werden. F\u00fcr die dreij\u00e4hrliche \u00dcberpr\u00fcfung wurden die Arzneimittel vom BAG in drei gleich grosse Einheiten aufgeteilt. Eine Einheit enth\u00e4lt mehrere, unterschiedliche therapeutische Gruppen und umfasst insgesamt knapp 1000 Arzneimittel. Aus Gr\u00fcnden der Gleichbehandlung werden stets alle Arzneimittel einer therapeutischen Gruppe gleichzeitig \u00fcberpr\u00fcft.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Bundesamt f\u00fcr Gesundheit (BAG) hat im Rahmen der dreij\u00e4hrlichen \u00dcberpr\u00fcfung f\u00fcr das Jahr 2019 die Preise von 257 Originalpr\u00e4paraten um durchschnittlich 16.3% gesenkt. Es werden aufgrund dieser \u00dcberpr\u00fcfung Einsparungen von 100 Millionen Franken erwartet. Dank der \u00dcberpr\u00fcfungsperiode 2017 bis 2019 ergeben sich somit Einsparungen von rund 450 Millionen Franken<\/p>\n","protected":false},"author":4,"featured_media":293241,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1141,1140,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-322233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-themen","category-leben-in-der-schweiz","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/322233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=322233"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/322233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/293241"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=322233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=322233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=322233"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=322233"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=322233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}