{"id":303562,"date":"2019-08-22T09:06:28","date_gmt":"2019-08-22T07:06:28","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=303562"},"modified":"2019-08-22T11:08:53","modified_gmt":"2019-08-22T09:08:53","slug":"arbeit-und-gesundheitstress-und-psychosoziale-risiken-am-arbeitsplatz-haben-2017-zugenommen","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/arbeit-und-gesundheitstress-und-psychosoziale-risiken-am-arbeitsplatz-haben-2017-zugenommen\/","title":{"rendered":"Arbeit und GesundheitStress und psychosoziale Risiken am Arbeitsplatz haben 2017 zugenommen"},"content":{"rendered":"<p>2017 waren 50% der Erwerbst\u00e4tigen an ihrem Arbeitsplatz von mindestens drei der insgesamt neun Typen psychosozialer Risiken betroffen. Dies entspricht einer Zunahme von vier Prozentpunkten im Vergleich zu 2012. Psychosoziale Belastungen sind arbeitsorganisatorisch bedingt und entstehen unter anderem durch hohen Zeitdruck, geringen Gestaltungsspielraum, fehlende Unterst\u00fctzung durch Vorgesetzte oder Mitarbeitende, Diskriminierung oder Gewalt sowie Angst um den Arbeitsplatz und Stress.<\/p>\n<p><strong>Stress ist mit weiteren psychosozialen Risiken verbunden &#8230;<\/strong><\/p>\n<p>Der Anteil Personen, die bei der Arbeit meistens oder immer unter Stress stehen, ist sowohl bei den Frauen als auch bei den M\u00e4nnern von 18% im Jahr 2012 auf 21% im Jahr 2017 gestiegen. Damit geh\u00f6rt Stress zu den psychosozialen Risiken, die am st\u00e4rksten zugenommen haben. Besonders deutlich war der Anstieg bei den Erwerbst\u00e4tigen unter 30 Jahren (von 19% auf 25%) sowie im Gesundheits- und Sozialwesen (von 18% auf 23%). Besonders h\u00e4ufig stehen Personen unter Stress, wenn sie mindestens drei weiteren Typen psychosozialer Risiken ausgesetzt sind (2017: 37%). Ihr Anteil hat sich seit 2012 um 4 Prozentpunkte erh\u00f6ht.<\/p>\n<p><strong>&#8230; und steigert das Burn-out-Risiko<\/strong><\/p>\n<p>Knapp die H\u00e4lfte (49%) der sehr oft gestressten Personen f\u00fchlen sich bei der Arbeit emotional ersch\u00f6pft. Bei den Erwerbst\u00e4tigen, die weniger h\u00e4ufig oder nie unter Stress stehen, betr\u00e4gt dieser Anteil 13%. Die emotionale Ersch\u00f6pfung gilt als Zeichen f\u00fcr ein hohes Burn-out-Risiko und steht in Verbindung mit einem weniger guten Gesundheitszustand. Emotional verbrauchte Personen weisen sechsmal h\u00e4ufiger Anzeichen einer mittelschweren bis schweren Depression auf als solche, die sich emotional nicht verbraucht f\u00fchlen (24% gegen\u00fcber 4%). Allgemein erh\u00f6hen alle psychosozialen Risiken die Wahrscheinlichkeit, sich bei der Arbeit emotional verbraucht zu f\u00fchlen.<\/p>\n<p><strong>Stabile Situation bei den physischen Risiken<\/strong><\/p>\n<p>Der Anteil der Personen, die bei der Arbeit mindestens drei von insgesamt neun physischen Risiken ausgesetzt sind, ist hingegen zwischen 2012 und 2017 stabil geblieben (45%). Bei den Frauen haben einige Risiken dennoch zugenommen: Sie m\u00fcssen h\u00e4ufiger stets die gleichen Arm- oder Handbewegungen ausf\u00fchren (Anstieg von 57% auf 61%) oder bei extremen Temperaturen arbeiten. M\u00e4nner sind wiederum \u00f6fter einer H\u00e4ufung physischer Risiken ausgesetzt als Frauen (48% gegen\u00fcber 42%), wobei sich der Unterschied tendenziell verringert.<\/p>\n<p><strong>Einfluss der Arbeitsbedingungen auf den Gesundheitszustand<\/strong><\/p>\n<p>2017 beurteilten 12% der Personen, die mindestens drei physischen Risiken ausgesetzt sind, und 11% der Personen, die unter mindestens drei Typen psychosozialer Risiken leiden, ihren Gesundheitszustand als mittelm\u00e4ssig oder (sehr) schlecht. Bei Personen, die weniger h\u00e4ufig mit diesen Risiken konfrontiert sind, betr\u00e4gt dieser Anteil lediglich 6%. Werden alle Arbeitsbedingungen und soziodemografischen Merkmale ber\u00fccksichtigt, wirken sich neben Stress drei weitere Umst\u00e4nde negativ auf die Gesundheit aus: schmerzhafte oder erm\u00fcdende K\u00f6rperhaltungen, Angst um den Arbeitsplatz sowie emotionale Beanspruchungen wie beispielsweise die Unterdr\u00fcckung von Gef\u00fchlen.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stress wird in der Arbeitswelt immer mehr zur Belastung. 2017 litten 21% der Erwerbst\u00e4tigen an ihrem Arbeitsplatz sehr oft unter Stress, gegen\u00fcber 18% im Jahr 2012. Auch die psychosozialen Risiken nehmen generell zu. Die H\u00e4ufigkeit der physischen Risiken hat sich hingegen kaum ver\u00e4ndert. Knapp die H\u00e4lfte (49%) der gestressten Personen f\u00fchlen sich bei der Arbeit emotional ersch\u00f6pft und weisen folglich ein h\u00f6heres Burn-out-Risiko auf. Dies sind einige Ergebnisse aus der j\u00fcngsten Publikation des Bundesamtes f\u00fcr Statistik (BFS)<\/p>\n","protected":false},"author":4,"featured_media":221046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1141,1140,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-303562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-themen","category-leben-in-der-schweiz","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/303562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=303562"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/303562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/221046"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=303562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=303562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=303562"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=303562"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=303562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}