{"id":258676,"date":"2019-03-20T13:26:55","date_gmt":"2019-03-20T12:26:55","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=258676"},"modified":"2019-03-26T23:22:07","modified_gmt":"2019-03-26T22:22:07","slug":"das-eda-unterstuetzt-aktiv-den-dialog-zwischen-wissenschaft-und-diplomatie","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/das-eda-unterstuetzt-aktiv-den-dialog-zwischen-wissenschaft-und-diplomatie\/","title":{"rendered":"Das EDA unterst\u00fctzt aktiv den Dialog zwischen Wissenschaft und Diplomatie"},"content":{"rendered":"<p style=\"background: white; margin: 0cm 0cm 16.3pt 0cm;\"><span style=\"font-size: 11.5pt; font-family: 'Helvetica',sans-serif; color: #454545;\">Die Ergebnisse einer Studie, die 2017 von Forschenden der Eidgen\u00f6ssischen Technischen Hochschule Lausanne (EPFL) ver\u00f6ffentlicht wurde, zeigen, dass die Korallenriffe im Golf von Akaba und im Roten Meer in einzigartiger Weise widerstandsf\u00e4hig gegen\u00fcber steigenden Wassertemperaturen sind. Dieses Wissen k\u00f6nnte dazu dienen, st\u00e4rker von den Auswirkungen der Klimaerw\u00e4rmung betroffene Riffe an anderen Orten der Welt wieder neu zu besiedeln. \u00a0<\/span><\/p>\n<p style=\"background: white; margin: 0cm 0cm 16.3pt 0cm;\"><span style=\"font-size: 11.5pt; font-family: 'Helvetica',sans-serif; color: #454545;\">In diesem Zusammenhang hat die EPFL beschlossen, ein regionales Forschungszentrum \u2013 das \u00abTransnational Red Sea Center\u00bb \u2013 zu schaffen, das die Zusammenarbeit der wissenschaftlichen Gemeinschaft der Region erm\u00f6glichen soll.<\/span><\/p>\n<p style=\"background: white; margin: 0cm 0cm 16.3pt 0cm;\"><span style=\"font-size: 11.5pt; font-family: 'Helvetica',sans-serif; color: #454545;\">Bundesrat Ignazio Cassis erl\u00e4uterte in seiner Rede, weshalb das EDA Projekte zur F\u00f6rderung des Dialogs zwischen Wissenschaft und Politik unterst\u00fctzt. Als innovatives Land mit einer grossen Wissenschaftsgemeinschaft verf\u00fcgt die Schweiz \u00fcber die Mittel und die Glaubw\u00fcrdigkeit, um in einer Weltregion, die durch einen politisch und kulturell fragilen Kontext gekennzeichnet ist, als Fazilitatorin aufzutreten und einen solchen Dialog zu f\u00f6rdern.<\/span><\/p>\n<p style=\"background: white; margin: 0cm 0cm 16.3pt 0cm;\"><span style=\"font-size: 11.5pt; font-family: 'Helvetica',sans-serif; color: #454545;\">Der Schweizer Aussenminister betonte, dass das Projekt ganz auf der Linie des Beschlusses des Bundesrats liegt, gemeinsam mit dem Kanton und der Stadt Genf die Stiftung \u00abGeneva Science and Diplomacy Anticipator\u00bb zu errichten. Ziel dieser Stiftung ist es, der internationalen Gemeinschaft ein innovatives und flexibles Instrument zur Verf\u00fcgung zu stellen, das es den internationalen Organisationen erleichtert, die Themen der multilateralen Diplomatie des 21. Jahrhunderts anzugehen. Es braucht innovative, grenz\u00fcbergreifende Kooperationen zwischen verschiedenen Akteuren, um die durch diese Entwicklungen verursachten Herausforderungen zu l\u00f6sen, die Gouvernanzbed\u00fcrfnisse zu ermitteln und entsprechende Vorschl\u00e4ge zu unterbreiten.<\/span><\/p>\n<p style=\"background: white; margin: 0cm 0cm 16.3pt 0cm;\"><span style=\"font-size: 11.5pt; font-family: 'Helvetica',sans-serif; color: #454545;\">Der ebenfalls in Bern anwesende Pr\u00e4sident der ETH Lausanne, Martin Vetterli, erl\u00e4uterte die Bedeutung des Projekts f\u00fcr die Region des Roten Meeres. \u00abNichts k\u00f6nnte mich mehr inspirieren als die Arbeit f\u00fcr unsere Hochschule, die sich im Jahr ihres 50-j\u00e4hrigen Bestehens klar dazu bekennt, f\u00fcr die Zukunft unseres Planeten einzustehen\u00bb, betonte er.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Korallen im Golf von Akaba standen im Zentrum einer internationalen Konferenz zum Thema \u00abDialog zwischen Wissenschaft und Diplomatie\u00bb, die am Dienstag, 19. M\u00e4rz 2019, in Bern stattfand. Bundesrat Ignazio Cassis, Vorsteher des EDA, gab bei dieser Gelegenheit bekannt, dass die Schweiz das Projekt der ETH Lausanne zur Errichtung eines \u00abTransnationalen Forschungszentrums f\u00fcr das Rote Meer\u00bb unterst\u00fctzt.<\/p>\n","protected":false},"author":4,"featured_media":258677,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1140,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-258676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-leben-in-der-schweiz","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/258676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=258676"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/258676\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/258677"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=258676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=258676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=258676"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=258676"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=258676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}