{"id":242408,"date":"2019-01-13T14:31:09","date_gmt":"2019-01-13T13:31:09","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=218000"},"modified":"2019-11-04T22:43:20","modified_gmt":"2019-11-04T21:43:20","slug":"das-kino-lumbardhi-soll-auch-in-zukunft-der-bevoelkerung-gehoeren","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/das-kino-lumbardhi-soll-auch-in-zukunft-der-bevoelkerung-gehoeren\/","title":{"rendered":"Das Kino \u201eLumbardhi\u201c soll auch in Zukunft der Bev\u00f6lkerung geh\u00f6ren"},"content":{"rendered":"<p>Erbaut in den 50-er Jahren, brachte das Kino Lumbardhi, einst auch unter dem Namen Bistrica bekannt, die Filmkunst nach Prizren, und bietet heute der Bev\u00f6lkerung die verschiedensten kulturellen Aktivit\u00e4ten sowie \u00f6ffentlichen Raum zur t\u00e4glichen Nutzung.<\/p>\n<p>Doch war es dem Lumbardhi nicht immer beschieden gewesen, ein solcher Raum zu bleiben, ja, es sollte sogar einem Parkplatz weichen. 2007 verhinderte die Bev\u00f6lkerung Prizrens mit Petitionen die Privatisierung des Kinos, und nach sieben Jahren schlossen sich achtundf\u00fcnfzig Nichtregierungsorganisationen zusammen und gr\u00fcndeten die Stiftung Lumbardhi f\u00fcr die Wiederer\u00f6ffnung und den Schutz des Kinos.<\/p>\n<p>Ares Shporta, der Gesch\u00e4ftsleiter der Stiftung Lumbardhi, sagt, Bev\u00f6lkerung und zivilgesellschaftliche Organisationen h\u00e4tten unter dem Motto \u201eDas Lumbardhi soll wieder ein \u00f6ffentlicher Raum sein\u201c die Privatisierung des Geb\u00e4udes bek\u00e4mpft und das Kino der Stadt zur\u00fcckgegeben.<\/p>\n<p>\u201eDank dem Willen der Bev\u00f6lkerung konnte der Prozess gestoppt werden, und das Anliegen bekam grosse Unterst\u00fctzung von vielen Organisationen, Einzelpersonen, Akteuren. Ich denke, dass unsere Standfestigkeit und unser guter Wille die Institutionen zum R\u00fcckzug gezwungen haben und durch das Anliegen der Bev\u00f6lkerung, dass das Lumbardhi als Monument des kulturellen Erbes anerkannt und wieder zum \u00f6ffentlichen Raum werde, gerechtfertigt waren\u201c, sagt er.<\/p>\n<p><strong><a href=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/12\/37100785_984807708367089_3419292815182528512_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-215619\" src=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/12\/37100785_984807708367089_3419292815182528512_n.jpg\" alt=\"\" width=\"600\" height=\"400\" \/><\/a><\/strong><\/p>\n<p><strong>Nach der Rettung vor der Privatisierung warten neue Herausforderungen auf das Lumbardhi<\/strong><\/p>\n<p>Doch nach der gewonnen Schlacht gegen die Privatisierung erwartete die B\u00fcrgerinnen und B\u00fcrger eine neue Herausforderung: Um den Raum wieder zu nutzen, brauchte es auch finanzielle Unterst\u00fctzung. Und eine wichtige Rolle bei der neuen Nutzung des Raumes kam einer Kampagne auf der Plattform KosovoIdeas zu. Innert f\u00fcnfundvierzig Tagen wurden \u00fcber diese Plattform zwanzigtausend Euro gesammelt, was am 3. April 2017zur Wiederer\u00f6ffnung des Lumbardhi f\u00fchrte.<\/p>\n<p>\u00ab\u00a0Dank KosovoIdeas wurde sichtbar, wie gross unsere Unterst\u00fctzung in der Bev\u00f6lkerung wirklich ist. So starteten wir 2017 die Kampagne \u201eLumbardhi public again\u201c und baten um Unterst\u00fctzung, um das Lumbardhi wieder t\u00e4glich nutzen zu k\u00f6nnen. Ungef\u00e4hr neunundachtzig Organisationen und Einzelpersonen haben uns in einer f\u00fcnfundvierzigt\u00e4gigen Kampagne mit einer Summe von rund zwanzigtausend Euro unterst\u00fctzt. In der Folge er\u00f6ffneten wir das Lumbardhi im April 2018 f\u00fcr die t\u00e4gliche Nutzung\u201c, sagt Shporta.<\/p>\n<p>Seither dient das Lumbardhi f\u00fcr vielerlei Aktivit\u00e4ten. Vortr\u00e4ge, Werkst\u00e4tten, Konzerte, Filmvorf\u00fchrungen und viele andere Ideen werden in diesem Kino umgesetzt. Zudem dient das Lumbardhi vielen auch als Arbeitsraum. Zu seinem Charme tr\u00e4gt auch die kleine Bibliothek bei, die beim Eintreten sofort zu sehen ist. Diese Bibliothek wurde auf Initiative und Wunsch der Jugend im Rahmen des Projekts \u201eWiederkehr der Stadt\u201c der NGO \u201eEC ma ndryshe\u201c vergr\u00f6ssert.<\/p>\n<p><strong><a href=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/12\/41688233_1041384482709411_7954004734673682432_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-215631\" src=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/12\/41688233_1041384482709411_7954004734673682432_n.jpg\" alt=\"\" width=\"600\" height=\"400\" \/><\/a><\/strong><\/p>\n<p><strong>Im Dienst der Kultur aller Bev\u00f6lkerungsgruppen<\/strong><\/p>\n<p>Shporta f\u00fchrte aus, das Ziel sei gewesen, wieder einen Raum zu schaffen, der die Bed\u00fcrfnisse der Bev\u00f6lkerung erf\u00fcllt.<\/p>\n<p>\u00ab\u00a0Ziel war, das Lumbardhi wieder zu einer kulturellen Institution zu machen, die den heutigen Bed\u00fcrfnissen der Stadt entspricht, die Inhalt bringt, den Menschen wieder Raum schafft, eine gewisse Best\u00e4ndigkeit hat und vollst\u00e4ndig funktioniert\u201c, sagt er.<\/p>\n<p>Und dass das Lumbardhi immer mehr zum Zentrum kultureller Aktivit\u00e4ten im Dienst aller B\u00fcrgerinnen und B\u00fcrger wird, sagt auch Edi Galushi von der Organisation \u201eRoma Veritas Kosova\u201c. Dank dieses Raumes hat Edi schon mehrere Ideen zur F\u00f6rderung von Kunst und Kultur der Bev\u00f6lkerungsgruppe der Roma umgesetzt.<\/p>\n<p>\u00ab\u00a0Dieser \u00f6ffentliche Raum war n\u00f6tig f\u00fcr Prizren, er hat eindeutig dazu beigetragen, dass auch wir kulturelle Aktivit\u00e4ten organisieren, dass wir noch einen zus\u00e4tzlichen Ort haben, der unseren Anliegen entspricht. Und in den meisten F\u00e4llen entspricht das Lumbardhi den Bed\u00fcrfnissen und Bedingungen f\u00fcr gute kulturelle Aktivit\u00e4ten\u201c, sagt Galushi.<\/p>\n<p><a href=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/12\/31969872_938747372973123_4443697924651614208_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-215634\" src=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/12\/31969872_938747372973123_4443697924651614208_n.jpg\" alt=\"\" width=\"600\" height=\"400\" \/><\/a><\/p>\n<p>Das Album des S\u00e4ngers Driton Berisha mit klassischen Rocksongs, gesungen in Romanes, wurde erstmals im Lumbardhi vorgestellt, und in diesem Geb\u00e4ude fand auch die Gedenkveranstaltung f\u00fcr den verstorbenen Dichter der Roma, Kujtim Pa\u00e7aku, statt. Diese und andere Aktivit\u00e4ten konnten dank der Unterst\u00fctzung durch das Kino stattfinden, wie Edi Galushi sagt.<\/p>\n<p>\u00ab\u00a0Wir sind eindeutig daran interessiert, das Lumbardhi maximal zu nutzen. Doch vielleicht k\u00f6nnte es noch etwas umgebaut und ein wenig multifunktionaler werden, so dass es nicht nur ein Kino bleibt, sondern der Saal ab und zu auch f\u00fcr eine Theaterauff\u00fchrung umimprovisiert werden k\u00f6nnte, also dass es etwas mehr f\u00fcr verschiedene kulturelle Aktivit\u00e4ten ausger\u00fcstet w\u00e4re. Wir m\u00f6chten das Lumbardhi f\u00fcr verschiedene kulturelle Aktivit\u00e4ten nutzen und w\u00fcrden uns freuen, wenn es bald ein multifunktionaler Saal oder Ort w\u00fcrde\u201c, sagte Galushi.<\/p>\n<p><strong><a href=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/12\/44037141_1057194507795075_8438786858833412096_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-215622\" src=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/12\/44037141_1057194507795075_8438786858833412096_n.jpg\" alt=\"\" width=\"600\" height=\"400\" \/><\/a><\/strong><\/p>\n<p><strong>Das Kino Lumbardhi als touristische Attraktion<\/strong><\/p>\n<p>Auch Ares Shporta spricht von der Idee einer Erweiterung des Lumbardhi, und es erwartet ihn nun, wie er sagt, eine neue Herausforderung: die Bestimmung des institutionellen Schicksals des Kinos Lumbardhi und die Erstellung eines Finanz- und Nachhaltigkeitsplanes.<\/p>\n<p>\u00ab\u00a0Unterdessen sind wir daran, ein Ideenprojekt zu entwickeln, um den Raum komplett wiederzubeleben und ihn in einen Ort, der zw\u00f6lf Monate im Jahr genutzt werden kann, umzuwandeln. F\u00fcr diesen Prozess brauchen wir nat\u00fcrlich eine gr\u00f6ssere Finanzierung und wir sind auf gutem Weg, die n\u00f6tige Unterst\u00fctzung zu sichern\u201c, sagte er zu albinfo.ch.<\/p>\n<p>Mittlerweile entwickelt sich das Kino Lumbardhi, das sich im Herzen der Stadt neben dem Fluss gleichen Namens befindet, zu einem attraktiven Touristenmagnet auch f\u00fcr Reisende, die wegen der Geschichte dieses Kinos kommen. Mit seinen zwei S\u00e4len ist das Lumbardhi sogar Gastgeber f\u00fcr einen Teil der Aktivit\u00e4ten des Internationalen Filmfestivals DokuFest.<\/p>\n<p>Aktuell befindet sich das Lumbardhi auf der Liste des einstweilig gesch\u00fctzten Kulturerbes, w\u00e4hrend der Direktor der Stiftung Lumbardhi gegen\u00fcber albinfo.ch \u00e4usserte, geplant sei, sich nach der Realisierung des Ideenprojekts f\u00fcr die Liste des st\u00e4ndig gesch\u00fctzten Kulturerbes zu bewerben, denn schlussendlich sei das Ziel, dass das Lumbardhi f\u00fcr immer der Stadt und der Bev\u00f6lkerung geh\u00f6ren solle.<\/p>\n<blockquote><p><strong><a href=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/12\/44285653_1059429957571530_6530837226308239360_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-215625\" src=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/12\/44285653_1059429957571530_6530837226308239360_n.jpg\" alt=\"\" width=\"534\" height=\"400\" \/><\/a><\/strong><\/p>\n<p><strong>Die Kampagne, die das Lumbardhi rettete<\/strong><\/p>\n<p>\u201eDank KosovoIdeas wurde sichtbar, wie gross unsere Unterst\u00fctzung in der Bev\u00f6lkerung wirklich ist. So starteten wir 2017 die Kampagne \u201eLumbardhi public again\u201c und baten um Unterst\u00fctzung, um das Lumbardhi wieder t\u00e4glich nutzen zu k\u00f6nnen. Ungef\u00e4hr neunundachtzig Organisationen und Einzelpersonen haben uns in einer f\u00fcnfundvierzigt\u00e4gigen Kampagne mit einer Summe von rund zwanzigtausend Euro unterst\u00fctzt. In der Folge er\u00f6ffneten wir das Lumbardhi im April 2018 f\u00fcr die t\u00e4gliche Nutzung.\u201c<\/p>\n<p><strong><em>Foto:\u00a0 Elmedina Arapi<\/em><\/strong><\/p>\n<p><a href=\"https:\/\/kosovaideas.com\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-215628\" src=\"https:\/\/www.albinfo.ch\/wp-content\/uploads\/2018\/12\/kosovaideas_primary_logo_horizontal-1024x174.png\" alt=\"\" width=\"640\" height=\"109\" \/><\/a><\/p>\n<p>&nbsp;<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Das historische Kino \u201eLumbardhi\u201c in Prizren h\u00e4tte gem\u00e4ss Pl\u00e4nen zu einem Parkplatz werden sollen. 2007 verhinderten die B\u00fcrgerinnen und B\u00fcrger von Prizren mit Petitionen eine Privatisierung. Lesen Sie im Folgenden, was die Stiftung \u201eLumbardhi\u201c seither f\u00fcr die R\u00fcckkehr und den Schutz des Kinos getan hat.<\/p>\n","protected":false},"author":6,"featured_media":240026,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1138,1156,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-242408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kultur","category-fotolajmi-de","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/242408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=242408"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/242408\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/240026"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=242408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=242408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=242408"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=242408"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=242408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}