{"id":226010,"date":"2018-10-31T23:31:18","date_gmt":"2018-10-31T22:31:18","guid":{"rendered":"https:\/\/www.albinfo.ch\/?p=226010"},"modified":"2018-11-10T14:47:38","modified_gmt":"2018-11-10T13:47:38","slug":"raucherzahlen-seit-10-jahren-gleichbleibend-veraendertes-konsumverhalten-beim-alkohol","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/raucherzahlen-seit-10-jahren-gleichbleibend-veraendertes-konsumverhalten-beim-alkohol\/","title":{"rendered":"Raucherzahlen seit 10 Jahren gleichbleibend, ver\u00e4ndertes Konsumverhalten beim Alkohol"},"content":{"rendered":"<p>Die Schweizer Bev\u00f6lkerung ist nach eigener Einsch\u00e4tzung bei \u00fcberwiegend guter Gesundheit. 85% bezeichneten 2017 ihren Gesundheitszustand als sehr gut oder gut. Dabei besteht ein klarer Alterstrend: \u00dcber 93% der j\u00fcngeren Menschen im Alter von 15 bis 44 Jahren f\u00fchlen sich gesund, bei den Personen ab 75 Jahren sind es noch 67%. Jeder Vierte war in seinen Alltagsaktivit\u00e4ten durch ein gesundheitliches Problem w\u00e4hrend mindestens sechs Monaten leicht oder stark eingeschr\u00e4nkt. In der \u00e4lteren Bev\u00f6lkerung ab 65 Jahren sind Bluthochdruck (47%), erh\u00f6hter Cholesterinspiegel (32%) sowie Diabetes (11%) verbreitete gesundheitliche Beschwerden.<\/p>\n<p><strong>Raucheranteil bleibt gleich hoch<\/strong><\/p>\n<p>Nachdem der Anteil der Raucherinnen und Raucher von 1997 bis 2007 zur\u00fcckgegangen ist, blieb er in den letzten 10 Jahren bei rund 27%. Der Anteil der Rauchenden ist bei den 15- bis 44-j\u00e4hrigen M\u00e4nnern mit 35% am h\u00f6chsten. Stark reduziert hat sich jedoch die Menge des konsumierten Tabaks. So hat sich im Zeitraum von 1992 bis 2017 der Anteil der Rauchenden, die 20 oder mehr Zigaretten pro Tag rauchen, halbiert (1992: 41%; 2017: 21%).<\/p>\n<p><strong>Weniger t\u00e4glicher Alkoholkonsum&#8230;<\/strong><\/p>\n<p>2017 tranken 82% der Bev\u00f6lkerung Alkohol. Der Anteil der Abstinentinnen und Abstinenten ist etwa gleich geblieben wie 1992, jener der t\u00e4glich Konsumierenden hat sich in den letzten 25 Jahren von 20% auf 11% halbiert. Dies ist jedoch nicht in allen Altersgruppen der Fall. Bei den Personen ab 65 Jahren ist der Anteil der t\u00e4glichen Konsumenten am h\u00f6chsten und bleibt seit 1992 auf diesem Niveau (1992: 29%; 2017: 26%).<\/p>\n<p><strong>&#8230; daf\u00fcr mehr Alkohol bei einzelnen Gelegenheiten<\/strong><\/p>\n<p>Das Konsumverhalten beim Alkohol hat sich \u00fcber die Zeit hinweg ver\u00e4ndert: Die Bev\u00f6lkerung trinkt tendenziell weniger h\u00e4ufig Alkohol, daf\u00fcr bei den sich bietenden Gelegenheiten insgesamt mehr. Insbesondere bei den Jugendlichen und Erwachsenen bis 34 Jahren ist der punktuell risikoreiche Konsum, das sogenannte Rauschtrinken, weit verbreitet: Der Anteil der Personen, die zumindest einmal im Monat innerhalb von wenigen Stunden 5 (M\u00e4nner) resp. 4 (Frauen) Gl\u00e4ser Alkoholisches trinken, stieg von 19% im Jahr 2007 auf 24% im Jahr 2017. Insbesondere bei den jungen Frauen von 15 bis 24 Jahren hat sich die Rate in diesem Zeitraum verdoppelt (von 12% in 2007 auf 24% in 2017).<\/p>\n<p><strong>Lifestyle Gesundheit: K\u00f6rperliche Aktivit\u00e4ten<\/strong><\/p>\n<p>Gesundes Verhalten als Lebensstil ist in Mode. Bei den M\u00e4nnern stieg der Anteil der Personen, die noch nie in ihrem Leben geraucht haben, zwischen 1997 und 2017 von 38% auf 45%. Ebenso nimmt seit 2002 der Anteil der Personen zu, die k\u00f6rperlich aktiv sind (von 62% auf 76%), und der Anteil der Inaktiven nimmt ab (von 18% auf 8%). Insbesondere Frauen sind vermehrt k\u00f6rperlich aktiv, so dass die Geschlechterdifferenzen hinsichtlich Bewegung zunehmend verschwinden. Allerdings manifestieren sich auch soziale Unterschiede: Personen mit Terti\u00e4rabschluss zeigen h\u00e4ufiger ein gesundes Verhalten als Personen ohne nachobligatorische Schulbildung.<\/p>\n<p><strong>Ausgewogene Ern\u00e4hrung<\/strong><\/p>\n<p>Zwei Drittel der Bev\u00f6lkerung achten auf ihre Ern\u00e4hrung und 21% erf\u00fcllen die Ern\u00e4hrungsempfehlungen beim Fr\u00fcchte- und Gem\u00fcsekonsum &#8211; Frauen mehr als M\u00e4nner (28% gegen\u00fcber 15%). Rund zwei Drittel der Bev\u00f6lkerung konsumiert maximal vier Tage die Woche Fleisch. Dieser Anteil hat gegen\u00fcber 1992 um 8 Prozentpunkte zugenommen. Vor allem bei den Frauen zwischen 25 und 64 Jahren geht die H\u00e4ufigkeit des Fleischkonsums zur\u00fcck. In den letzten 25 Jahren hat sich bei den Frauen in dieser Altersgruppe der Anteil der t\u00e4glich Fleischessenden von 20% auf 10% halbiert. Gleichzeitig hat sich der Anteil derjenigen, die kein Fleisch essen, verdreifacht (von 2% auf 6%).<\/p>\n<p><strong>Stabilisierung beim \u00dcbergewicht<\/strong><\/p>\n<p>Nach Wachstumsphasen bleibt 2017 der Anteil der Personen mit \u00dcbergewicht (BMI 25 bis &lt;30) oder Adipositas (BMI ab 30) mit 42% auf dem gleichen Niveau wie 2012. Der Anteil der Personen mit Adipositas hat sich gegen\u00fcber 1992 von 5% auf 11% verdoppelt. M\u00e4nner und Frauen sind zu beinahe gleichen Teilen adip\u00f6s (12% resp. 10%); M\u00e4nner sind hingegen h\u00e4ufiger \u00fcbergewichtig als Frauen (39% gegen\u00fcber 23%). Bei der Adipositas bestehen deutliche soziale Unterschiede: Personen, die nur die obligatorische Schule abgeschlossen haben, weisen h\u00e4ufiger Adipositas auf als Personen mit einer h\u00f6heren Ausbildung (21% gegen\u00fcber 8%).<\/p>\n<p><strong>Sechste Durchf\u00fchrung der Befragung<\/strong><\/p>\n<p>2017 wurden in der Schweiz 22 134 Personen zu ihrem Gesundheitszustand und Gesundheitsverhalten befragt. Die Schweizerische Gesundheitsbefragung findet seit 1992 alle f\u00fcnf Jahre statt. Die kontinuierliche Durchf\u00fchrung erlaubt es, dass Verhaltensmuster \u00fcber 25 Jahre hinweg beobachtet werden k\u00f6nnen. Die Gesundheit der Bev\u00f6lkerung \u00e4ndert sich kontinuierlich im Austausch mit dem gesellschaftlichen Wandel. Dabei interessiert besonders, bei welchen Bev\u00f6lkerungsgruppen \u00c4nderungen festzustellen sind und bei welchen nicht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2017 f\u00fchlten sich 85% der Schweizer Bev\u00f6lkerung ab 15 Jahren gesund. 27% sind Raucherinnen oder Raucher. Dies sind zwar weniger als 1992, aber gleich viel wie 2007. Vier von f\u00fcnf Personen trinken Alkohol, jede Zehnte t\u00e4glich. Die Zahlen der \u00dcbergewichtigen und Adip\u00f6sen haben sich bei 42% stabilisiert. Dies sind die wichtigsten Ergebnisse der sechsten \u00abSchweizerischen Gesundheitsbefragung\u00bb des Bundesamts f\u00fcr Statistik (BFS) aus dem Jahr 2017. Sie zeigt auf, wie sich das Gesundheitsverhalten und der Gesundheitszustand der Bev\u00f6lkerung in den letzten 25 Jahren ver\u00e4ndert haben<\/p>\n","protected":false},"author":14,"featured_media":223463,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1140,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-226010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-leben-in-der-schweiz","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/226010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=226010"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/226010\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/223463"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=226010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=226010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=226010"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=226010"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=226010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}