{"id":205764,"date":"2018-07-09T16:04:04","date_gmt":"2018-07-09T14:04:04","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=205764"},"modified":"2018-07-09T16:04:04","modified_gmt":"2018-07-09T14:04:04","slug":"hochzeitsfeste-als-ausdruck-des-albanischen-kulturerbes","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/hochzeitsfeste-als-ausdruck-des-albanischen-kulturerbes\/","title":{"rendered":"Hochzeitsfeste als Ausdruck des albanischen Kulturerbes"},"content":{"rendered":"<p>Wer ein Liebhaber der albanischen Folklore ist, kennt sicherlich die vielen besungenen Hochzeitsbr\u00e4uche, durch welche die Tradition der Hochzeitszeremonie wiedergegeben werden.<\/p>\n<p>Doch Sitten sind nicht unver\u00e4nderlich. So ist die Tradition der arrangierten Ehen mit dem Wandel der Zeit den Idealen der freien Wahl mehrheitlich gewichen. Auch hat sich die Form der Hochzeitszeremonien ver\u00e4ndert. Es werden immer mehr westliche Riten \u00fcbernommen, wobei einige traditionelle Br\u00e4uche in den Hintergrund geraten oder gar ganz verschwinden.<\/p>\n<p>Allerdings werden Ideale aus Europa und den USA nicht einfach nur reproduziert, sondern mit traditionellen Werten vermischt, was eine v\u00f6llig neue kulturelle Identit\u00e4t schafft. Eine Mischung aus Moderne und Tradition zeichnet die heutigen albanischen Hochzeiten aus.<\/p>\n<p>In dieser Ausgabe des Albinfo.ch-Magazins widmen wir uns dem Thema Hochzeit aus verschiedenen Blickwinkeln. Aus soziologischer und ethnologischer Sicht durchleuchten wir die Bedeutung einer Heirat, stellen Ihnen die sch\u00f6nsten Hochzeitslocations vor und zeigen das Resultat eines Kostenvergleichs zwischen einer albanischen und einer schweizerischen Hochzeitsfeier auf. Ebenfalls lesenswert ist die Analyse \u00fcber den Wandel der Hochzeitsbr\u00e4uche und Riten von der Zeit des <em>Kanuns des Lek\u00eb Dukagjini <\/em>bis heute.<\/p>\n<p>Wir w\u00fcnschen Ihnen eine spannende Lekt\u00fcre rund um das Thema der Saison.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wer ein Liebhaber der albanischen Folklore ist, kennt sicherlich die vielen besungenen Hochzeitsbr\u00e4uche, durch welche die Tradition der Hochzeitszeremonie wiedergegeben werden. Doch Sitten sind nicht unver\u00e4nderlich. So ist die Tradition der arrangierten Ehen mit dem Wandel der Zeit den Idealen der freien Wahl mehrheitlich gewichen. Auch hat sich die Form der Hochzeitszeremonien ver\u00e4ndert. Es werden [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":205526,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1129,1133,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-205764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ch-balkan","category-e-diaspora-de","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/205764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=205764"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/205764\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/205526"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=205764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=205764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=205764"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=205764"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=205764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}