{"id":202233,"date":"2018-06-18T09:00:43","date_gmt":"2018-06-18T07:00:43","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=202233"},"modified":"2021-06-14T15:52:32","modified_gmt":"2021-06-14T13:52:32","slug":"fuer-ine-rechtliche-anerkennung-der-muslimischen-gemeinschaften-in-der-schweiz","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/fuer-ine-rechtliche-anerkennung-der-muslimischen-gemeinschaften-in-der-schweiz\/","title":{"rendered":"F\u00fcr ine rechtliche Anerkennung der muslimischen Gemeinschaften in der Schweiz"},"content":{"rendered":"<p><span data-doc-id=\"4397000231178938\">Wir begr\u00fcssen diese Tagung und alle die, welche zur Verwirklichung dieser Tagung beigetragen haben. Und zugleich w\u00fcnschen wir der gesamten SP Schweiz und ihren F\u00fchrungskr\u00e4ften Fortschritt<\/span> und Erfolg\u00a0in der Erreichung der\u00a0Ziele\u00a0im Wohle\u00a0des\u00a0Landes und dessen\u00a0Bev\u00f6lkerung. Wir sind \u00fcberzeugt, dass die heutige Zeit nicht vergleichbar ist mit der Fr\u00fcheren. Auch in der Schweiz haben sich die Ums\u00e4nde stark ver\u00e4ndert.<\/p>\n<p>Heute haben wir eine Schweiz mit vielen Nationalit\u00e4ten, Religionen und Kulturen, was die SP Schweiz\u00a0dazu\u00a0gef\u00fchrt hat,\u00a0neue Ideen zu entwickeln, welche das Ziel haben, in unserer vielf\u00e4ltigen Geselschaft Gleichheit zu schaffen. Und dazu geh\u00f6rt\u00a0auch\u00a0die heutige SP-Initiative, eine grosse oder kleine\u00a0\u00f6ffentlich-rechtliche Anerkennung der muslimischen Gemeinschaften in der Schweiz zu erreichen.<\/p>\n<p>Gem\u00e4ss meiner Abw\u00e4gung und Bewertung ist eine solche Initiative eine fortschrittliche Idee und diese stellt zugleich eine Notwendigkeit f\u00fcr die Bew\u00e4ltigung\u00a0der Herausforderungen in\u00a0der heutigen geselschaftlichen Realit\u00e4t dar. Denn immerhin stellen die Muslime\u00a0heute einen Bev\u00f6lkerungsanteil von 5%\u00a0in der Schweiz dar. Die Vision der SP Schweiz ist\u00a0aus einem progressiven Standpunkt deshalb so bedeutend,\u00a0weil sie bezweckt, dass sie nicht nur einen Standard der Gleichheit schafft, sondern auch Harmonie und Zusammenhalt inerhalb der gesamten Gesellschaft bezweckt. Aber was wichtig und prim\u00e4r ist, ist die Frage, wie diese Idee in der tats\u00e4chlichen Praxis und den heutigen\u00a0Gegebenheiten gelebt wird. Dieser\u00a0Punkt kann unter Umst\u00e4nden\u00a0zu\u00a0Kontroversen f\u00fchren.<\/p>\n<p>Speziell die Anforderungen an die muslimischen Gemeinschaften k\u00f6nnten als\u00a0nicht erf\u00fcllbar bezeichnen werden. Wir sind jedoch der Meinung, dass\u00a0wenn\u00a0die muslimischen Gemeinschaften konstruktive Beitr\u00e4ge leisten,\u00a0die Forderungen der SP Schweiz\u00a0durchaus zu erf\u00fcllen sind und auch erf\u00fcllt werden m\u00fcssen, denn demokratische Strukturen, gleichberechtigung von Mann und Frau, Unabh\u00e4ngigkeit vom Ausland und Transparenz\u00a0im Finanziellen sind\u00a0eine Voraussetzung f\u00fcr eine Anerkennung\u00a0inerhalb der Schweizer Bev\u00f6klerung.<\/p>\n<p>Ausserdem herrscht innerhalb der muslimischen Gemeinschaften\u00a0eine religi\u00f6se und kulturelle Diversit\u00e4t,\u00a0weshalb sich\u00a0die Umsetzung der\u00a0inklusiven\u00a0L\u00f6sungsvorschl\u00e4ge\u00a0als\u00a0schwierig\u00a0erweisen k\u00f6nnte. Doch wenn die progressiven Kr\u00e4fte in den muslimischen Gemeinschaften sich zusammenschliessen und die Initiative \u00fcbernehmen, k\u00f6nnen auch diese Herausforderungen, da bin ich vollkommen \u00fcberzeugt, bew\u00e4ltigt werden.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute haben wir eine Schweiz mit vielen Nationalit\u00e4ten, Religionen und Kulturen, was die SP Schweiz dazu gef\u00fchrt hat, neue Ideen zu entwickeln, welche das Ziel haben, in unserer vielf\u00e4ltigen Geselschaft Gleichheit zu schaffen. Und dazu geh\u00f6rt auch die heutige SP-Initiative, eine grosse oder kleine \u00f6ffentlich-rechtliche Anerkennung der muslimischen Gemeinschaften in der Schweiz zu erreichen<\/p>\n","protected":false},"author":4,"featured_media":111011,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1141,3908,1140,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-202233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-themen","category-meinungen","category-leben-in-der-schweiz","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/202233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=202233"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/202233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/111011"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=202233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=202233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=202233"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=202233"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=202233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}