{"id":193971,"date":"2018-04-25T11:06:28","date_gmt":"2018-04-25T09:06:28","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=193971"},"modified":"2018-04-27T10:54:30","modified_gmt":"2018-04-27T08:54:30","slug":"bericht-zur-migrationsaussenpolitik-2017","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/bericht-zur-migrationsaussenpolitik-2017\/","title":{"rendered":"Bericht zur Migrationsaussenpolitik 2017"},"content":{"rendered":"<div class=\"contentHead\">\n<p><strong style=\"font-size: 16px;\">Die migrationspolitischen Anforderungen sind in den letzten Jahren gestiegen. Um Herausforderungen wie den Migrationsbewegungen \u00fcber das Mittelmeer oder den Auswirkungen des Syrien-Konflikts zu begegnen, engagiert sich die Schweiz stark auf bilateraler, regionaler und multilateraler Ebene. Die interdepartementale Koordination wurde 2017 neu strukturiert, was auch die Verkn\u00fcpfung zwischen der Migrationspolitik und der internationalen Zusammenarbeit verst\u00e4rkt. Dies h\u00e4lt der Bundesrat in seinem Jahresbericht zur Migrationsaussenpolitik fest, den er in seiner Sitzung vom 25. April 2018 verabschiedet hat.<\/strong><\/p>\n<\/div>\n<div class=\"mod mod-nsbnewsdetails\">\n<p>Im Berichtsjahr wurde die interdepartementale Struktur zur internationalen Migrationszusammenarbeit (IMZ) angepasst. Dies tr\u00e4gt auch zur effizienteren Umsetzung des Auftrags des Parlaments bei, die Migrationspolitik und die internationale Zusammenarbeit st\u00e4rker zu verkn\u00fcpfen. Internationale Zusammenarbeit, politische Prozesse und Instrumente wie die Migrationspartnerschaften sollen vermehrt genutzt werden, um die Herausforderungen und Chancen der Migration mit einem koh\u00e4renten und langfristigen Ansatz zu bearbeiten. Konkret sollen Programme in den Herkunftsregionen zum Schutz von Fl\u00fcchtlingen, zur Bearbeitung der Ursachen erzwungener Migration, sowie zur F\u00f6rderung der Integration vor Ort durch St\u00e4rkung der wirtschaftlichen und sozialen Eigenst\u00e4ndigkeit, beispielsweise durch den Zugang zu Bildung f\u00fcr Kinder und Minderj\u00e4hrige, beitragen.<\/p>\n<h3>Bilaterale Zusammenarbeit<\/h3>\n<p>Im Bereich der bilateralen Zusammenarbeit stehen die Aktivit\u00e4ten in wichtigen Herkunfts-, Transit und Ziell\u00e4ndern von Migrantinnen und Migranten im Vordergrund. Die bilaterale Zusammenarbeit wurde mit verschiedenen Drittstaaten wie Algerien, Marokko und Tunesien gest\u00e4rkt. Mit Sri Lanka zielen die Gespr\u00e4che auf den Abschluss einer Migrationspartnerschaft ab. In Konfliktregionen wie Syrien geht es haupts\u00e4chlich um ein bedarfsgerechtes Engagement f\u00fcr Fl\u00fcchtlinge und Schutzbed\u00fcrftige.<\/p>\n<h3>Multilaterale Zusammenarbeit<\/h3>\n<p>Die Schweiz hat sich 2017 in der Kontaktgruppe Zentrales Mittelmeer engagiert und das dritte Treffen der Gruppe in Bern organisiert. Im Zentrum der Gespr\u00e4che stand die Frage, wie der Schutz der Fl\u00fcchtlinge sowie der Migrantinnen und Migranten entlang der Migrationsroute \u00fcber das zentrale Mittelmeer verbessert werden kann. Die Schweiz unterst\u00fctzt im Rahmen der bilateralen und regionalen Zusammenarbeit mit den Herkunfts- und Transitl\u00e4ndern eine Reihe von Projekten in der Region durch multilaterale Partner wie der Internationalen Organisation f\u00fcr Migration (IOM), das UNO-Hochkommissariat f\u00fcr Fl\u00fcchtlinge (UNHCR) oder der Internationalen Arbeitsorganisation (ILO). Zudem hat die Schweiz auch im vergangenen Jahr \u00fcber das Resettlement-Programm besonders verletzliche Fl\u00fcchtlinge, Opfer des Syrienkonflikts, aufgenommen.<\/p>\n<p>Die mit der Migration verbundenen Herausforderungen und Chancen k\u00f6nnen nur durch internationale Zusammenarbeit angegangen, bzw. genutzt werden. Deshalb setzt sich die Schweiz seit Jahren f\u00fcr eine globale Migrationsgouvernanz ein, welche notwendig ist, damit Migration ein Nutzen f\u00fcr alle ist und Ausbeutung, Zwangsvertreibung, Menschenrechtsverletzungen und irregul\u00e4re Migration verhindert werden k\u00f6nnen. Am UNO-Gipfel f\u00fcr Fl\u00fcchtlinge und Migranten im September 2016 wurden die Grundsteine f\u00fcr zwei globale Rahmenwerke (Global Compacts) erarbeitet und verabschiedet. Die Verhandlungen des Global Compact on Migration (GCM) werden vom Schweizer Botschafter J\u00fcrg Lauber in Ko-Leitung gef\u00fchrt. Die Schweiz tr\u00e4gt damit in zentraler Funktion zur Erarbeitung eines bedeutenden UNO-Prozesses bei, welcher international anerkannte Prinzipien und Standards f\u00fcr den Umgang mit Migrationsbewegungen und Zwangsvertreibung festlegen soll.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Internationale Zusammenarbeit, politische Prozesse und Instrumente wie die Migrationspartnerschaften sollen vermehrt genutzt werden, um die Herausforderungen und Chancen der Migration mit einem koh\u00e4renten und langfristigen Ansatz zu bearbeiten<\/p>\n","protected":false},"author":4,"featured_media":144652,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1141,1140,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-193971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-themen","category-leben-in-der-schweiz","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/193971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=193971"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/193971\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/144652"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=193971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=193971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=193971"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=193971"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=193971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}