{"id":180622,"date":"2018-01-23T18:51:18","date_gmt":"2018-01-23T17:51:18","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=180622\/"},"modified":"2018-01-26T01:25:22","modified_gmt":"2018-01-26T00:25:22","slug":"schweizer-ihra-vorsitz-wissen-ueber-den-holocaust-ist-grundlage-um-bewusstsein-fuer-folgen-von-rassismus-zu-schaffen","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/schweizer-ihra-vorsitz-wissen-ueber-den-holocaust-ist-grundlage-um-bewusstsein-fuer-folgen-von-rassismus-zu-schaffen\/","title":{"rendered":"Schweizer IHRA-Vorsitz: Wissen \u00fcber den Holocaust ist Grundlage, um Bewusstsein f\u00fcr Folgen von Rassismus zu schaffen"},"content":{"rendered":"<p><strong>Aufkl\u00e4rung und Unterricht \u00fcber die Schoah in der Schule standen im Zentrum der Internationalen Studientage \u00fcber Bildung an der P\u00e4dagogischen Hochschule des Kantons Waadt in Lausanne. An der zweit\u00e4gigen Konferenz, welche die Schweiz im Rahmen ihres Vorsitzes der International Holocaust Remembrance Alliance (IHRA) mit der Hochschule organisiert hat, standen Praxisbeispiele und Erfahrungsberichte aus dem Schulbetrieb im Zentrum. Die IHRA hat zum Ziel, die Forschung und Bildung in Bezug auf den Holocaust zu f\u00f6rdern sowie die Erinnerung an die Opfer durch Gedenkfeiern und -st\u00e4tten wachzuhalten. <\/strong><\/p>\n<p>Welche Erfahrungen mit dem Thema Holocaust haben Lehrerinnen und Lehrer im Unterricht gemacht? Welche Anregungen k\u00f6nnen sie geben, wie dieses schwierige Thema angemessen vermittelt werden kann? Die Antworten k\u00f6nnen je nach dem nationalen Kontext, aufgrund der eigenen Geschichte und der Beziehung jedes einzelnen Landes zur Vergangenheit, unterschiedlich ausfallen. Ein Ziel der Internationalen Studientage \u00fcber Bildung an der P\u00e4dagogischen Hochschule in Lausanne war deshalb, Handlungsm\u00f6glichkeiten f\u00fcr Lehrerinnen und Lehrer aufzuzeigen, die m\u00f6glichst wirkungsvoll an die Geschichte des Holocausts erinnern.<\/p>\n<p>Organisiert hatte die Studientage die P\u00e4dagogische Hochschule in Lausanne im Rahmen des Schweizer IHRA-Vorsitzes. Die Konferenz reiht sich in die Themenbereiche Erziehung und Bildung, Jugend sowie Social Media ein, welche die Schweiz als die Priorit\u00e4ten ihres Vorsitzes der IHRA definiert hat. \u201eDie n\u00e4chste Generation \u00fcber den Holocaust zu unterrichten, ist ein Weg, die Erinnerung an den Holocaust wach zu halten\u201c, sagte der amtierende Vorsitzende der IHRA, Benno B\u00e4ttig, bei der Er\u00f6ffnung der Studientage. Er \u00e4usserte die Hoffnung, \u201edass wir durch die Weitergabe von Wissen \u00fcber den Holocaust dazu beitragen k\u00f6nnen, dass jungen Menschen das Bewusstsein daf\u00fcr entwickeln, zu was Rassismus und Diskriminierung f\u00fchren k\u00f6nnen.\u201c Die Weitergabe von Wissen und der Erinnerung an den Holocaust ist in heutiger Zeit umso wichtiger, als immer weniger Menschen noch leben, die den Holocaust als Zeitzeugen erlebt haben und \u00fcber die Gr\u00e4uel erz\u00e4hlen k\u00f6nnen. Benno B\u00e4ttig unterstrich zudem die Notwendigkeit, \u201cjungen Generationen auch die F\u00e4higkeit zum Mitgef\u00fchl mit dem Leiden anderer Menschen zu vermitteln &#8211; und dass sie f\u00fcr sie eintreten, wenn die Zeiten dies erfordern.\u201d<\/p>\n<p>Um diese L\u00fccke zu f\u00fcllen, welche das Verschwinden von Erz\u00e4hlungen durch Holocaust-\u00dcberlebende hinterl\u00e4sst, m\u00fcssen neue Methoden erarbeitet werden. Einer dieser neuen Ans\u00e4tze, der mit neuen Medien arbeitet, ist die Lern-App \u201eFliehen vor dem Holocaust\u201c, die nach ihrer Pr\u00e4sentation an den IHRA-Plenarsitzungen in Bern nun auch in Lausanne einem breiteren Publikum vorgestellt wird. Die Entwicklung der App, die ab Fr\u00fchsommer 2018 von Jugendlichen direkt oder im Unterricht genutzt werden kann, wurde vom Schweizer IHRA-Vorsitz unterst\u00fctzt.<\/p>\n<p>Die IHRA umfasst derzeit 31 Mitgliedstaaten. Unter Schweizer Vorsitz haben zudem Bulgarien und Australien einen wichtigen Schritt zur baldigen Vollmitgliedschaft gemacht. Zu den institutionellen Partnern der IHRA geh\u00f6ren unter anderem die UNO, der Europarat, das B\u00fcro f\u00fcr demokratische Institutionen und Menschenrechte der OSZE und die UNESCO. Die Schweiz ist seit 2004 Mitglied der IHRA. Den Vorsitz der IHRA hat die Schweiz im M\u00e4rz 2017 von Rum\u00e4nien \u00fcbernommen und wird ihn am 6. M\u00e4rz 2018 an Italien weiterreichen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ie Konferenz reiht sich in die Themenbereiche Erziehung und Bildung, Jugend sowie Social Media ein, welche die Schweiz als die Priorit\u00e4ten ihres Vorsitzes der IHRA definiert hat<\/p>\n","protected":false},"author":4,"featured_media":49466,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1141,1140,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-180622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-themen","category-leben-in-der-schweiz","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/180622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=180622"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/180622\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/49466"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=180622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=180622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=180622"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=180622"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=180622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}