{"id":179979,"date":"2018-01-19T13:30:59","date_gmt":"2018-01-19T12:30:59","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=179979\/"},"modified":"2018-01-21T22:49:42","modified_gmt":"2018-01-21T21:49:42","slug":"nobillag-eine-initiative-die-positive-ueberraschungen-bringen-koennte","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/nobillag-eine-initiative-die-positive-ueberraschungen-bringen-koennte\/","title":{"rendered":"NoBillag &#8211; Eine Initiative, die positive \u00dcberraschungen bringen k\u00f6nnte"},"content":{"rendered":"<p style=\"font-weight: 400;\">Aktuell\u00a0wird in den Schweizer Medien \u00fcber eine popul\u00e4re nationale Initiative gesprochen, die selten solche Gef\u00fchle in Bezug auf Geld mit sich bringt. Es geht dabei um\u00a0die Initiative mit dem Namen &#8220;No Billag&#8221;, die darauf abzielt, die Kosten des staatlichen SRG-Fernsehens, die bisher durch die Firma &#8220;Billag AG&#8221;\u00a0eingetrieben wurden, zu streichen.<\/p>\n<p style=\"font-weight: 400;\">Jede Einwohnerin und jeder Einwohner in der Schweiz\u00a0ist mindestens einmal im Jahr mit der Zahlung bei dieser Firma konfrontiert, f\u00fcr die eine gro\u00dfe Mehrheit kein Verst\u00e4ndnis\u00a0f\u00fcr die\u00a0zu zahlende Summe hat (f\u00fcr den privaten Gebrauch zu Hause jetzt bei 451 Franken pro Jahr), aber auch aus dem Grund, weshalb Fernsehen in Industriel\u00e4ndern auch 2017 noch von Steuerzahlern finanziert werden sollten.<\/p>\n<p style=\"font-weight: 400;\">Die Idee des staatlichen Fernsehens hatte zweifelsohne eine politische und finanzielle Legitimit\u00e4t, im Falle der Schweiz im Jahr 1931. Zu der Zeit, als das Fernsehen erfunden wurde, war die Art der Kommunikation und dem Bezug von Information der B\u00fcrger begrenzt. Der Staat hat zu Recht beschlossen, die neue Technologie zu nutzen, um den \u00f6ffentlichen Dienst zu erweitern, d.h. die B\u00fcrger durch Fernsehnachrichten und andere Programme zu informieren.<\/p>\n<p style=\"font-weight: 400;\">Heute, etwa 90 Jahre sp\u00e4ter, ist die technologische Situation v\u00f6llig neu. Menschen kommunizieren und absorbieren Informationen haupts\u00e4chlich \u00fcber das Internet. Die Vielfalt der freien Marktangebote, die wir in der Schweiz genie\u00dfen, gibt uns viele qualitative M\u00f6glichkeiten, guten und genauen Service zu erhalten. Dies gilt nicht f\u00fcr unvoreingenommene Medien, da das staatliche Fernsehen selbst nicht neutral ist. Diese Tatsache wird in vielen F\u00e4llen best\u00e4tigt, wie z.B. positive\u00a0Betonungen in SRF Nachrichten\u00a0beim Gedenken an die Geburt des\u00a0kriminellen und ber\u00fcchtigten Politikers Che Guevara. Andere Beispiele sind zahllos. Also hat jedes Medium genau wie jedes Individuum eine politische Voreingenommenheit. Es ist wichtig, Vielfalt zu haben.<\/p>\n<p style=\"font-weight: 400;\">Die Politik eines demokratischen Staates funktioniert auch gleich. F\u00fcr jedes politische Konzept gibt es politische Parteien, und sie konkurrieren um die B\u00fcrger f\u00fcr ihre Ideen. Die gr\u00f6\u00dfte Errungenschaft moderner und demokratischer Staaten ist die individuelle Freiheit. Dasselbe wird jetzt von dieser Initiative,\u00a0welche von Jugendforen verschiedener Parteien initiiert und von verschiedenen Gruppen, Parteien und Einzelpersonen unterst\u00fctzt wird, verfolgt.<\/p>\n<p style=\"font-weight: 400;\">Der Medienmarkt sollte liberalisiert werden, daher sollte der Staat die historische Rolle des &#8220;Mediendieners&#8221; f\u00fcr seine B\u00fcrger nicht \u00fcbernehmen. Jugendliche unter 30 Jahren zum Beispiel konsumieren heute nicht mehr klassische Medien wie Fernsehen. Sie werden \u00fcber das Internet, soziale Medien und verschiedene Zeitungen informiert,\u00a0welche ihre Dienste im Internet pr\u00e4sentieren.<\/p>\n<p style=\"font-weight: 400;\">Die Freiheit sieht vor, dass jeder von uns selbst entscheidet, welches Medium er konsumieren will und welches nicht und\u00a0wof\u00fcr\u00a0man bezahlen werde und wof\u00fcr nicht. Die aktuelle Situation zwingt jeden Haushalt\u00a0in der Schweiz, die j\u00e4hrlichen Kosten zu bezahlen &#8211; ob\u00a0man\u00a0sich nun das Programm der\u00a0SRG angesehen\/angeh\u00f6rt hat oder nicht. Diese Ungerechtigkeit k\u00f6nnte am 4. M\u00e4rz dieses Jahres enden. Die &#8220;JA&#8221; -Stimme\u00a0erh\u00f6ht nicht nur das Budget zu Hause, sondern schafft auch Raum f\u00fcr noch bessere Marktalternativen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die aktuelle Situation zwingt jeden Haushalt\u00a0in der Schweiz, die j\u00e4hrlichen Kosten zu bezahlen &#8211; ob\u00a0man\u00a0sich nun das Programm der\u00a0SRG angesehen\/angeh\u00f6rt hat oder nicht. Diese Ungerechtigkeit k\u00f6nnte am 4. M\u00e4rz dieses Jahres enden. Die &#8220;JA&#8221; -Stimme\u00a0erh\u00f6ht nicht nur das Budget zu Hause, sondern schafft auch Raum f\u00fcr noch bessere Marktalternativen<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3908,1140,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-179979","post","type-post","status-publish","format-standard","hentry","category-meinungen","category-leben-in-der-schweiz","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/179979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=179979"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/179979\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=179979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=179979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=179979"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=179979"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=179979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}