{"id":173371,"date":"2017-12-01T13:17:47","date_gmt":"2017-12-01T12:17:47","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=173371\/"},"modified":"2017-12-05T00:06:12","modified_gmt":"2017-12-04T23:06:12","slug":"auslaender-und-integrationsgesetz-integration-durch-anreize-verstaerken","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/auslaender-und-integrationsgesetz-integration-durch-anreize-verstaerken\/","title":{"rendered":"Ausl\u00e4nder- und Integrationsgesetz: Integration durch Anreize verst\u00e4rken"},"content":{"rendered":"<p>Das Parlament hat am 16.\u00a0Dezember 2016 die \u00c4nderung des Ausl\u00e4ndergesetzes (AuG) zur Verbesserung der Integration gutgeheissen. Die Umsetzung der Gesetzes\u00e4nderung ist in zwei Pakete aufgeteilt: Das erste Paket tritt Anfang 2018 in Kraft und beinhaltet im Wesentlichen die Abschaffung der Sonderabgabe auf Erwerbseinkommen f\u00fcr Personen aus dem Asylbereich sowie eine technische Anpassung der Finanzierungsbestimmung zur Integrationspauschale.<\/p>\n<p>Heute hat der Bundesrat die Vernehmlassung zum zweiten Paket er\u00f6ffnet, diese l\u00e4uft bis zum 19. M\u00e4rz 2018. Das zweite Paket beinhaltet Anpassungen der Verordnung \u00fcber Zulassung, Aufenthalt und Erwerbst\u00e4tigkeit (VZAE) sowie die Totalrevision der Verordnung \u00fcber die Integration von Ausl\u00e4nderinnen und Ausl\u00e4ndern (VIntA). Diese \u00c4nderungen werden im Sommer 2018 in Kraft treten. Zudem wird das AuG dann in &#8220;Bundesgesetz \u00fcber die Ausl\u00e4nderinnen und Ausl\u00e4nder und \u00fcber die Integration&#8221; (Ausl\u00e4nder- und Integrationsgesetz; AIG) umbenannt.<\/p>\n<h3><strong>Zugang zur Erwerbst\u00e4tigkeit f\u00f6rdern<\/strong><\/h3>\n<p>Das heutige Bewilligungsverfahren f\u00fcr die Aus\u00fcbung einer Erwerbst\u00e4tigkeit von anerkannten Fl\u00fcchtlingen und vorl\u00e4ufig Aufgenommenen wird durch eine einfache Meldung ersetzt. Diese Meldung kann von Dritten vorgenommen werden, die im Auftrag der Integrationsf\u00f6rderung in den Kantonen Praktika- und Arbeitspl\u00e4tze suchen. Das schafft einen leichteren Zugang zu einer Erwerbst\u00e4tigkeit und entlastet die Arbeitgeber. Damit wird das inl\u00e4ndische Arbeitskr\u00e4ftepotenzial gef\u00f6rdert und so die Ausgaben f\u00fcr die Sozialhilfe reduziert. Die Einhaltung der Arbeitsbedingungen wird von bestehenden Kontrollorganen gepr\u00fcft.<\/p>\n<p>Weiter werden die Integrationskriterien auf Verordnungsebene konkretisiert, welche die Migrationsbeh\u00f6rden bei ausl\u00e4nderrechtlichen Entscheiden zu ber\u00fccksichtigen haben. So werden etwa Sprachkompetenzen festgelegt, die f\u00fcr eine Erteilung und Verl\u00e4ngerung einer Bewilligung gefordert sind. Dabei steigen die Anforderungen, je mehr Rechte mit einem ausl\u00e4nderrechtlichen Status verbunden sind.<\/p>\n<p>Ausserdem werden die vom Parlament beschlossenen Massnahmen f\u00fcr Ausl\u00e4nderinnen und Ausl\u00e4nder, die keinen Willen zeigen zu ihrer Integration beizutragen, konkretisiert. So k\u00f6nnen die zust\u00e4ndigen Migrationsbeh\u00f6rden eine Aufenthaltsbewilligung mit einer Integrationsvereinbarung verbinden und damit den betroffenen Personen aufzeigen, was von ihnen erwartet wird. Diese Integrationsvereinbarung wird verbindlich und kann sanktioniert werden. Werden die Integrationskriterien nicht erf\u00fcllt, kann eine R\u00fcckstufung von einer Niederlassungs- (Ausweis C) auf eine Aufenthaltsbewilligung (Ausweis B) erfolgen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Bundesrat hat in seiner Sitzung vom 1. Dezember 2017 die Vernehmlassung zum zweiten Paket der Anpassungen der Verordnungen zum neuen Ausl\u00e4ndergesetz (AuG) er\u00f6ffnet. Die Integration von Ausl\u00e4nderinnen und Ausl\u00e4nder ist eine gemeinsame Aufgabe von Bund und Kantone und soll durch positive Anreize und mit geeigneten Massnahmen verst\u00e4rkt werden. So soll unter anderem der Spracherwerb gef\u00f6rdert und der Zugang zum Arbeitsmarkt f\u00fcr Fl\u00fcchtlinge und vorl\u00e4ufig Aufgenommene erleichtert werden. <\/p>\n","protected":false},"author":4,"featured_media":126482,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1141,1140,1412,2015],"tags":[],"vendi":[],"content_country":[],"class_list":["post-173371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-themen","category-leben-in-der-schweiz","category-newsletter-de","category-newsletter-media-de"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/173371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=173371"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/173371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media\/126482"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=173371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=173371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=173371"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=173371"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=173371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}