{"id":158000,"date":"2017-08-16T09:08:31","date_gmt":"2017-08-16T07:08:31","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=158000\/"},"modified":"2017-08-21T01:32:19","modified_gmt":"2017-08-20T23:32:19","slug":"sela-wir-werden-nicht-zulassen-dass-gewisse-kreise-unseren-nationalhelden-verunglimpfen","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/sela-wir-werden-nicht-zulassen-dass-gewisse-kreise-unseren-nationalhelden-verunglimpfen\/","title":{"rendered":"Sela: Wir werden nicht zulassen, dass gewisse Kreise unseren Nationalhelden verunglimpfen"},"content":{"rendered":"<div class=\"m_-4545940618601120164gmail-post-info\">Als politische Partei aber auch als Nation werden wir nicht zulassen, dass gewisse politische Kreise die historische Figur von Skenderbeg bestreiten und verunglimpfen.<\/div>\n<div class=\"m_-4545940618601120164gmail-post-info\"><\/div>\n<div class=\"m_-4545940618601120164gmail-post-info\">Der\u00a0albanischen Nationalheld Skenderbeg ist die Identit\u00e4tsfigur der albanischen Nation. Als politische Partei aber ach als Nation werden wir nicht zulassen, dass gewisse Kreise in der Politik seine Figur bestreiten und verunglimpfen, sagte Ziadin Sela bei einem Treffen mit seiner Basis in der Stadt Tetova.<\/div>\n<div class=\"m_-4545940618601120164gmail-post-info\"><\/div>\n<div class=\"m_-4545940618601120164gmail-post-info\">Er f\u00fchle sich gut in den Raum, in dem ein Abbild des albanischen Nationalhelden h\u00e4ngt, so Sela bei einer Veranstaltung mit seinen Anh\u00e4ngern. &#8220;Unser Nationalheld Skenderbeg ist die zentrale Figur unserer Nation. Egal welchen Namen wir tragen, er ist und bleibt unser Nationalheld. Ihn zu bestreiten und zu verunglimpfen, bedeutet einen Angriff auf uns als Nation&#8221;, sagte Sela.<\/div>\n<div class=\"m_-4545940618601120164gmail-post-info\"><\/div>\n<div class=\"m_-4545940618601120164gmail-post-info\">Die Albaner sehen sich hin und wieder mit solchen Angriffen aus bekannten Kreisen konfrontiert, die auch aus dem Ausland unterst\u00fctz werden. &#8220;Wir m\u00fcssen weiterhin aufmerksam sein und solche Entwicklungen stets im Auge behalten. Diese Kreise werden uns jedes mal angreifen, wenn wir als Nation geschw\u00e4cht\u00a0sind. Dies passiert in Universit\u00e4ten, in Schulen und Kinderg\u00e4rten.&#8221;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Als politische Partei aber auch als Nation werden wir nicht zulassen, dass gewisse politische Kreise die historische Figur von Skenderbeg bestreiten und verunglimpfen. Der\u00a0albanischen Nationalheld Skenderbeg ist die Identit\u00e4tsfigur der albanischen Nation. Als politische Partei aber ach als Nation werden wir nicht zulassen, dass gewisse Kreise in der Politik seine Figur bestreiten und verunglimpfen, sagte [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-158000","post","type-post","status-publish","format-standard","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/158000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=158000"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/158000\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=158000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=158000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=158000"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=158000"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=158000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}