{"id":154046,"date":"2017-06-29T15:55:34","date_gmt":"2017-06-29T13:55:34","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=154046\/"},"modified":"2017-06-29T15:55:50","modified_gmt":"2017-06-29T13:55:50","slug":"sondergericht-erste-anklagen-koennen-in-sieben-tagen-erhoben-werden","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/sondergericht-erste-anklagen-koennen-in-sieben-tagen-erhoben-werden\/","title":{"rendered":"Sondergericht: Erste Anklagen k\u00f6nnen in sieben Tagen erhoben werden"},"content":{"rendered":"<p>Das kosovarische Verfassungsgericht hat die neuen Regeln des Gesch\u00e4ftsordnung des Sondergerichts gutgeheissen. Dies nachdem Teile davon nicht im Einklang mit der kosovarischen Verfassung waren, schreibt die Zeitung Expres.<\/p>\n<p>Sieben Tage nach dieser Entscheidung kann das Sondergericht erste Anklagen erheben.<\/p>\n<p>Am 26. April 2017 stellte das Verfassungsgericht fest, dass neun Regeln der Gesch\u00e4ftsordnung des kosovarischen Sondergerichts nicht im Einklang mit dem 2. Kapitel der kosovarischen Verfassung waren. Die \u00fcberarbeiteten Regeln wurden nun genehmigt, sodass erste Anklagen k\u00f6nnen sehr bald erhoben werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Sondergericht f\u00fcr die Aufarbeitung von Kriegsverbrechen kann erste Anklagen in sieben Tagen erheben<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-154046","post","type-post","status-publish","format-standard","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/154046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=154046"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/154046\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=154046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=154046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=154046"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=154046"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=154046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}