{"id":146338,"date":"2017-04-12T18:35:12","date_gmt":"2017-04-12T16:35:12","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=146338\/"},"modified":"2017-04-12T18:01:00","modified_gmt":"2017-04-12T16:01:00","slug":"eu-regierung-in-skopje-soll-baldmoeglichst-gebildet-werden","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/eu-regierung-in-skopje-soll-baldmoeglichst-gebildet-werden\/","title":{"rendered":"EU: Regierung in Skopje soll baldm\u00f6glichst gebildet werden"},"content":{"rendered":"<p style=\"background: white;\">Die Wahl des Parlamentspr\u00e4sidenten und die Bildung der neuen Regierung in Skopje soll so schnell wie m\u00f6glich erfolgen, schreibt die Sprecherin der EU-Kommission, Maja Kocijan\u00e7iq an die Abgeordneten und an Staatspr\u00e4sident Ivanov.<\/p>\n<p style=\"background: white;\"><span style=\"font-family: 'Arial',sans-serif; color: #222222;\">Die EU erwartet, dass die neue reformorientierte Regierung in Skopje so schnell wie m\u00f6glich gebildet wird, so die Sprecherin der EU-Kommission.<\/span><\/p>\n<p style=\"background: white;\"><span style=\"font-family: 'Arial',sans-serif; color: #222222;\">&#8220;Die aktuelle Unsicherheit in Mazedonien muss so schnell beendet werden und die neue reformorientierte Regierung muss gebildet werden. Erweiterungskommissar Johannes Hahn hat die entsprechende Botschaft an Staatspr\u00e4sident Ivanov mitgeteilt und von ihm gefordert, seine Entscheidung zu \u00fcberdenken und das Mandat zu Regierungsbildung an Zoran Zaev zu erteilen. Wir erwarten nun, dass die demokratischen Prozesse vorangetrieben werden&#8221;, zitiert KP die EU-Sprecherin.<\/span><\/p>\n<p style=\"background: white;\"><span style=\"font-family: 'Arial',sans-serif; color: #222222;\">Im mazedonischen Parlament findet nun seit Tagen die konstituierende Sitzung des neuen Parlamentes statt. Es wird unendlich lang diskutiert unter anderem betreffend der Wahl des neuen Parlamentsvorsitzenden. Mit diesem Tempo und mit den wachsenden Protesten der Unterst\u00fctzer der VMRO-DMPNE scheint noch keine L\u00f6sung der mazedonischen Krise in Sicht.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Die aktuelle Unsicherheit in Mazedonien muss so schnell beendet werden und die neue reformorientierte Regierung muss gebildet werden&#8221;<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-146338","post","type-post","status-publish","format-standard","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/146338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=146338"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/146338\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=146338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=146338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=146338"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=146338"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=146338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}