{"id":143124,"date":"2017-03-14T10:44:36","date_gmt":"2017-03-14T09:44:36","guid":{"rendered":"http:\/\/www.albinfo.ch\/?p=143124\/"},"modified":"2017-03-14T10:44:36","modified_gmt":"2017-03-14T09:44:36","slug":"exporte-in-die-schweiz-und-nach-norwegen-nun-mit-erleichterten-verfahren-moeglich","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/exporte-in-die-schweiz-und-nach-norwegen-nun-mit-erleichterten-verfahren-moeglich\/","title":{"rendered":"Exporte in die Schweiz und nach Norwegen nun mit erleichterten Verfahren m\u00f6glich"},"content":{"rendered":"<div dir=\"ltr\">\n<p>Das Systems REX im Rahmen von Generel System of Preferences (GSP), das Kosova als Entwicklungsland zur Verf\u00fcgung gestellt wird, erleichtert die kosovarischen Exporte nach Norwegen und in die Schweiz.<\/p>\n<p>F\u00fcr Unternehmen, die ihre Waren in die Schweiz und nach Norwegen exportieren, erm\u00f6glicht das REX-System, sich von der kosovarischen Zollbeh\u00f6rden registrieren lassen und dann haben sie die M\u00f6glichkeit, ihre Produkte in diesen zwei L\u00e4ndern zu exportieren und dabei selbst das Herkunftszertifikat auszustellen. Dies ist mit FORM A m\u00f6glich. Das System ist seit dem 1. Januar 2017 im Einsatz, schrieb der kosovarischen Finanzminister in seinem Facebook-Account.<\/p>\n<p>\u201eWir informieren alle Unternehmer, die ihre Waren nach Norwegen und in die Schweiz exportieren und vom GSP-System profitieren wollen, das entsprechende Formular auszuf\u00fcllen, damit wir sie ins System aufnehmen k\u00f6nnen\u201c, so Hoti.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dank der Implementierung des REX-Systems im Rahmen von GSP ist der Export von kosovarischen Waren in die Schweiz und nach Norwegen nun erleichtert.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-143124","post","type-post","status-publish","format-standard","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/143124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=143124"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/143124\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=143124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=143124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=143124"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=143124"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=143124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}