{"id":129907,"date":"2016-11-02T09:26:05","date_gmt":"2016-11-02T08:26:05","guid":{"rendered":"http:\/\/www.albinfo.ch\/de\/?p=129907"},"modified":"2016-11-02T09:26:05","modified_gmt":"2016-11-02T08:26:05","slug":"bewohner-fliehen-weiterhin-aus-prishtina","status":"publish","type":"post","link":"https:\/\/www.albinfo.at\/de\/bewohner-fliehen-weiterhin-aus-prishtina\/","title":{"rendered":"Bewohner fliehen weiterhin aus Prishtina"},"content":{"rendered":"<div dir=\"ltr\">\n<p>&nbsp;<\/p>\n<p>Auch wenn in der Haupstadt Prishtina in den letzten Jahren wichtige Fortschritte erzielt worden sind, haben die Stadtbewohner mit vielen Problemen zu k\u00e4mpfen.<\/p>\n<p>Im letzten Jahr haben 1\u2018253 Menschen die Stadt verlassen und sind ausgewandert. Im Jahr 2014 waren es 1\u2018343, im Jahr 2015 waren es 2\u2018408, schreibt \u201aKlan Kosova\u2018. Im Jahr 2012 wohnten in Prishtina 205\u2018135 Menschen, im Jahr 2013 waren es 207\u2018477, im Jahr 2015 204\u2018721.<\/p>\n<p>Viele B\u00fcrger der Stadt verlassen gleich das Land, wie Tausende andere aus ganz Kosova. Der Drang zu fliehen und auszuwandern ist weiterhin sehr hoch. Viele junge Menschen wollen ins Ausland ziehen.<\/p>\n<p><b> <\/b><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aus der kosovarischen Haupstadt Prishtina fliehen die Menschen weiterhin. 1\u2018253 B\u00fcrger haben die Stadt Richtung Ausland verlassen.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1130,1129],"tags":[],"vendi":[],"content_country":[],"class_list":["post-129907","post","type-post","status-publish","format-standard","hentry","category-aktuell","category-ch-balkan"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/129907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/comments?post=129907"}],"version-history":[{"count":0,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/posts\/129907\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/media?parent=129907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/categories?post=129907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/tags?post=129907"},{"taxonomy":"vendi","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/vendi?post=129907"},{"taxonomy":"content_country","embeddable":true,"href":"https:\/\/www.albinfo.at\/de\/wp-json\/wp\/v2\/content_country?post=129907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}